{"id":5362,"date":"2016-11-21T22:23:46","date_gmt":"2016-11-21T21:23:46","guid":{"rendered":"http:\/\/www.josemariatornay.com\/index.php\/mis-libros\/en-pie-de-guerra\/"},"modified":"2018-10-07T15:19:26","modified_gmt":"2018-10-07T14:19:26","slug":"en-pie-de-guerra","status":"publish","type":"page","link":"http:\/\/www.josemariatornay.com\/index.php\/en-pie-de-guerra\/","title":{"rendered":"En pie de guerra"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5362\" class=\"elementor elementor-5362 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6634750 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6634750\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e760bf\" data-id=\"9e760bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4279ba elementor-widget elementor-widget-heading\" data-id=\"f4279ba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-large\">EN PIE DE GUERRA<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54a9846 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54a9846\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4abe0d0\" data-id=\"4abe0d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34b6cc4 elementor-widget elementor-widget-heading\" data-id=\"34b6cc4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2018\/10\/En-pie-de-guerra.pdf\">Bajar en pdf<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6eade5b\" data-id=\"6eade5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cc55da elementor-widget elementor-widget-heading\" data-id=\"9cc55da\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.lulu.com\/shop\/jos%C3%A9-mar%C3%ADa-tornay-ruiz\/en-pie-de-guerra\/ebook\/product-18453006.html\">Comprar en papel<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ff0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ff0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3af0\" data-id=\"3af0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7675 elementor-widget elementor-widget-text-editor\" data-id=\"7675\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 25%\" >\n        <p style=\"text-align: center;\"><img decoding=\"async\" width=\"105\" height=\"150\" alt=\"\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/En-pie-de-guerra-2-1.jpg\"><br><\/p>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 50%\" >\n        <br>En pie de guerra recoge 68 poemas de diversa tem\u00e1tica, pero unidos por el hilo invisible de la comnbatividad, frente a las inercias, las mediocridades, los fantasmas y todo aquello que convierte la vida en un asunto mezquino. En la INTRODUCCI\u00d3N de abajo explico con m\u00e1s profundidad el sentido general de los textos. El contenido se articula alrededor de un poema central, mi favorito de siempre, y que se titula, parafraseando un verso de Le\u00f3n Felipe, Hazme un sitio en tu montura. De nuevo el Quijote como met\u00e1fora de la rebeld\u00eda y de la lucha contra el conformismo.<br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 25%\" >\n        <p style=\"text-align: center;\"><img decoding=\"async\" width=\"98\" height=\"149\" alt=\"\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/frutosdelotono-2.jpg\"><br><\/p>\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 100%\" >\n        <span style=\"font-size: 14px; font-weight: bold;\">PR\u00d3LOGO<\/span><br>Hay mucha gente que ya no cree en las personas. Siempre la ha habido, pero hoy es patente que una buena parte del personal est\u00e1 instalada en la duda permanente, en la sospecha, en el recelo enfermizo, en la desconfianza. A casi nadie se le supone buena fe y honradez. Hay una tendencia generalizada a estar en guardia. Alguna raz\u00f3n tiene que haber; tal vez la sensaci\u00f3n que impone la nueva religi\u00f3n, el consumismo, de que nos enga\u00f1an en todas partes y que nadie se acerca a nosotros que no sea para sacarnos el dinero. Pocos admiten que t\u00fa act\u00faes movido por causas nobles y desinteresadas. El mundo ha sido infectado por un virus terrible que est\u00e1 acabando con el \u201cbuen rollo\u201d.<br>Ante tal avalancha de bajeza y podredumbre, no cabe otra herramienta que renovar la confianza en la sustancia \u00faltima del hombre y de la mujer y apelar, si no es posible a la inteligencia, s\u00ed a los instintos radicales de supervivencia, al orgullo de sentirse \u00fanico entre iguales, a la alegr\u00eda de ser parte imprescindible de un todo que s\u00f3lo se alimenta del jugo y del juego imprescindible de sus partes.<br>De tal confianza nacen estos versos, que arrancan literalmente en el oto\u00f1o estacional y que fermentan en la madurez de su autor. Tiempo de certezas inseguras y de dudas reafirmadas. De confianza en lo ef\u00edmero y resbaladizo, porque es lo que hay y lo que cabe esperar de una vida que se construye a cada paso y que se forja con cada aliento y con cada gesto. Vivir es construir la propia vida y convertirse en agente de la construcci\u00f3n de otras vidas que conforman nuestro horizonte vital e inmediato, nuestro paisaje, que construimos y nos construye.<br>De ese vivir laborioso y extenuante surgen estos jirones del alma, que se embriagan en lo que nos sobrepasa y que se alimentan de lo que nos conmueve.<br>Lo que nos cerca y lo que nos mueve desde dentro van jalonando con sus hitos el camino que vamos construyendo con nuestros pasos.<br>Este libro quiere ser un alegato contra la vulgaridad, contra la intolerancia, contra la estupidez, contra la ingratitud y contra la mala leche. Una apasionada defensa de la palabra como motor de cualquier posibilidad de cambio y de crecimiento\u2026<br>La palabra, esa eterna olvidada en nuestras cuitas, est\u00e1 pasando a mejor vida. Por estar postergada, enseguida pasamos a los hechos, a las manos de la sinraz\u00f3n y de la suspicacia.<br>Cargados de afrentas y reproches, de brutales y ciegas ingratitudes, estamos perdiendo la limpieza de la mirada y el equilibrio imprescindible para mantenernos erguidos ante tales fuerzas poderosas.Estos poemas quieren ser un homenaje a la palabra y a los horizontes que se abren con su cultivo. La palabra nos lleva al respeto, a la tolerancia y al compromiso. Quien abandona la palabra, abandona su condici\u00f3n de ser humano y cae de bruces en los brazos del ego\u00edsmo y de la sinraz\u00f3n.<br>Las tres partes en que se dividen estos versos, responden a la voluntad de la mirada. En la primera parte se lanza hacia fuera, hacia el paisaje humano y f\u00edsico que rodea al autor. En la segunda parte, la mirada se vuelve hacia adentro, para, si es posible, ofrecer un peque\u00f1o reportaje interior de sus cuitas y desvelos. En la tercera, hay un anhelo de recuperar como horizonte la utop\u00eda, esa vieja optimista y esperanzada que nos convierte en h\u00e9roes cabalgando a lomos de nuestra propia existencia.<br><br>De esta forma, desde esta trinchera, que siendo pac\u00edfica, no quiere ser conformista, haremos la guerra a la mezquindad, a lo convencional, a los dogmas y convicciones inamovibles, para, a la vez, reivindicar con urgencia y sin dilaci\u00f3n, la palabra, la duda estimulante, la utop\u00eda y la solidaridad.<br>Jos\u00e9 M\u00aa Tornay\n        <br><br>\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">ADI\u00d3S PESETA<\/span><br>\u00bfQu\u00e9 tendr\u00e9 yo que hacer para olvidarte,<br>amada compa\u00f1era de mi vida?<br>\u00a1Tantos sudores para conquistarte,<br>para acabar llorando tu partida!<br>Tu muerte, amor, no ha sido cualquier muerte;<br>jam\u00e1s otra ocurri\u00f3 m\u00e1s anunciada.<br>\u00a1T\u00fa que eres paradigma de la suerte,<br>verte de esta manera postergada!<br>\u00bfD\u00f3nde pondr\u00e9 sin ti tanto cari\u00f1o<br>y qu\u00e9 va a ser de la tercera edad?<br>\u00bfC\u00f3mo se apa\u00f1ar\u00e1n sin ti los ni\u00f1os<br>que cantan el sorteo de Navidad?<br>Ganas me dan de apretar el gatillo;<br>\u00bfqu\u00e9 voy a hacer de ahora en adelante,<br>cuando meta la mano en el bolsillo<br>y encuentre al sustituto repugnante?<br>A ti te debo todo lo que soy;<br>hasta llegu\u00e9 a perderme por ganarte;<br>no quiero que te vayas sin contarte<br>lo inmensamente triste que yo estoy.<br>Pero conozco bien el alma artera<br>que gobierna y dirige nuestra mente:<br>cuando otro caliente mi cartera,<br>pasar\u00e1s al olvido eternamente.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">ATARDECER<\/span><br>Atardecer, El Campillo:<br>se estremecen dos miradas,<br>suenan lejos campanadas,<br>las beatas van a misa;<br>se ve el Tajo; en la cornisa<br>revolotean los grajos.<br>Hace fr\u00edo y all\u00ed abajo<br>los campos est\u00e1n desiertos;<br>vuelve a tocar la campana:<br>ahora est\u00e1 tocando a muerto.<br><br>En el fondo se ve el r\u00edo<br>con sus aguas estancadas<br>y su caudal que son l\u00e1grimas<br>por las lluvias olvidadas;<br>y el sol que desaparece<br>y la tarde se oscurece;<br>quedan flotando arreboles,<br>preludios de nuevos soles<br>que volver\u00e1n a salir:<br>suenan de nuevo campanas,<br>seguramente ma\u00f1ana<br>volveremos a vivir.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">CUANDO EMPIEZAN LOS BUITRES<\/span><br><br>Cuando empiezan los buitres<br>a nublar el horizonte,<br>cuando se vuelve amarga<br>la miel que endulzaba los labios,<br>ya no bastan las l\u00e1grimas<br>ni el valor<br>ni la fe;<br>hay que esperar que concuerden los signos,<br>que cuadren los sintagmas,<br>que el esencial no ser<br>crepite en el vac\u00edo<br>como una noche vencida por el alba.<br>Hay que esperar,<br>sentarse en las pilastras de la vida y esperar,<br>esperar como un ni\u00f1o,<br>como un adolescente atolondrado;<br>esperar, esperar,<br>aunque nos hayan robado la esperanza.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">\u00bfAD\u00d3NDE IR\u00c1N?<\/span><br>\u00bfAd\u00f3nde ir\u00e9 a parar cuando me vaya?<br>\u00bfAd\u00f3nde ir\u00e1n mis huesos polvorientos?<br>\u00bfD\u00f3nde reposar\u00e1n mis pensamientos?<br>\u00bfQu\u00e9 nuevas olas ba\u00f1ar\u00e1n mi playa?<br>\u00bfD\u00f3nde terminar\u00e1n mis desvar\u00edos?<br>\u00bfD\u00f3nde mis esperanzas y mis sue\u00f1os?<br>\u00bfAd\u00f3nde ir\u00e1n estos paisajes m\u00edos?<br>\u00bfAd\u00f3nde mis afanes, mis empe\u00f1os?<br>Tal vez se vayan a ninguna parte,<br>quiz\u00e1 se vengan por siempre conmigo;<br>tal vez se queden para conquistarte<br>o vayan a so\u00f1ar en mis amigos.<br>O tal vez vuelvan al punto primero<br>cuando partimos en aquel expr\u00e9s:<br>antes del d\u00eda doce de febrero<br>de mil novecientos cincuenta y tres.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">EL OTRO<\/span><br>El otro acecha oculto en la ensenada,<br>vive de soledades compungidas,<br>destruye las verdades, siempre atento,<br>no deja de otear el infinito.<br>Obsequia con su bilis repugnante,<br>n\u00e9ctar podrido,<br>negra concupiscencia,<br>almac\u00e9n de fracasos, frustraciones,<br>terrores y miedos destructivos.<br>Detr\u00e1s de los espejos se acomoda,<br>saca la lengua cuando t\u00fa te miras,<br>no perdona los eternos desencuentros,<br>vencido siempre,<br>su fuerte es la derrota.<br>Lastre que carga<br>y deforma el esqueleto,<br>que a\u00f1ora soledad en su viaje,<br>viejo de alma carcomida y triste,<br>funesto viajero despiadado.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        CUMPLEA\u00d1OS<br>Esto de cumplir a\u00f1os es un rollo<br>que nos suele ocurrir todos los a\u00f1os;<br>miras dentro y te sientes un pimpollo,<br>miras fuera, al espejo, y te haces da\u00f1o.<br>El tic-tac del reloj de la existencia<br>es un dardo que apunta hacia el ocaso,<br>es una bomba asida a la conciencia,<br>es una trampa tendida a cada paso.<br>Echar a\u00f1os atr\u00e1s, no es s\u00f3lo agravio,<br>va teniendo tambi\u00e9n sus puntos buenos:<br>somos m\u00e1s viejos, mas tambi\u00e9n m\u00e1s sabios;<br>menos nos queda, mas tememos menos.<br>No dejar\u00e9 que el tiempo me esclavice,<br>me apuntar\u00e9 a la fiesta de la vida,<br>dejar\u00e9 atr\u00e1s, de una vez, las cicatrices,<br>no dar\u00e9 una pelota por perdida.<br><br>Proclamar\u00e9 con sangre en cada calle<br>que aunque nada me invita al optimismo,<br>voy a coger la vida por el talle<br>para bailar con ella hasta el abismo.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">EL SILENCIO<\/span><br>Yo s\u00e9 muy bien que el silencio<br>es la mejor compa\u00f1\u00eda<br>y que el que vive hacia dentro,<br>vive m\u00e1s densa la vida.<br>Tambi\u00e9n s\u00e9 muy bien el da\u00f1o<br>que ocasiona a sus vecinas<br>&#8211; el resto de las manzanas &#8211;<br>una manzana podrida.<br>Cuentan las sabias cabezas<br>que se devanan pensando<br>que vale m\u00e1s estar s\u00f3lo<br>que estar mal acompa\u00f1ado.<br>Dicen los santos varones,<br>amantes del celibato,<br>que para acercarse a Dios<br>hay que estar ensimismados.<br><br>Y digo yo que de acuerdo,<br>que eso puede ser verdad<br>pero nada es m\u00e1s amargo<br>que un buen trago en soledad.<br>Las horas que compartimos<br>nunca son horas perdidas:<br>yo antes que solo prefiero<br>una mala compa\u00f1\u00eda.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        EN LA RIBERA<br>En la ribera,<br>sentado en la ribera,<br>viendo pasar el r\u00edo:<br>el agua que nos lleva;<br>como un espectador<br>de la propia existencia.<br>A la sombra de un \u00e1rbol<br>sin ra\u00edces ni tierra,<br>viendo crecer el muro<br>sin poner una piedra,<br>repitiendo murmullos,<br>dormido en la indolencia,<br>oculto de los otros<br>en su isla desierta,<br>con el cuerpo cansado,<br>con el alma tan vieja<br>que ni en la noche teme<br>ni con el alba tiembla.<br>A la sombra de nada,<br>sentado en la ribera,<br>viendo en la superficie<br>pasar las hojas muertas<br>como el que ve su sombra<br>cruzando por la acera.<br>Sin mojarse los pies,<br>sin dejar una huella,<br>a salvo de peligros<br>sobre la blanda arena,<br>viendo pasar el r\u00edo:<br>el agua que nos lleva.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        Est\u00e1n de moda los ecos,<br>est\u00e1n de baja las voces,<br>andan los tenores huecos<br>dispar\u00e1ndonos sus coces.<br>Penan sin color las flores<br>mustias por tanto ladrido,<br>anda sin pulso el latido<br>y sin besos los amores.<br>Vagan sin rumbo los hilos<br>misteriosos de la vida,<br>y en la penosa partida<br>se vuelven romos sus filos.<br>Se lanza al vuelo la oscura<br>sombra que duerme en la frente<br>y a nadar contra corriente<br>nos empuja su locura..<br>Y las alarmas que saltan<br>y un ej\u00e9rcito de grillos<br>se lanza al monte y te canta<br>un mon\u00f3tono estribillo.<br>Bajan los arroyos secos,<br>reinan los vientos feroces,<br>est\u00e1n ganando los ecos<br>a las est\u00e9riles voces*<br><br>* palabras. As\u00ed las llamaba Machado.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">CELOS<\/span><br>Pistola de mil ca\u00f1ones,<br>grandiosa y punzante espina<br>ojo alerta en cada esquina<br>duda que pre\u00f1a ficciones.<br>Dolorosa golosina,<br>torvas sombras en la noche<br>cargadas de vil reproche,<br>veneno del coraz\u00f3n,<br>v\u00edctima de esa pasi\u00f3n<br>que lo ahoga en su derroche.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">\n         AROMA<\/span><br>\n         \u00a1C\u00f3mo te invade,<br>c\u00f3mo te llena,<br>c\u00f3mo te embriaga,<br>c\u00f3mo te eleva!<br><br>\u00a1C\u00f3mo va renovando<br>la sangre vieja<br>y nos va contagiando<br>las ansias nuevas.<br><br>Te da la vida,<br>te la envenena.\n        <br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">\n         CAE LA LLUVIA<\/span><br>Cae la lluvia&#8230;<br>En los cristales<br>las gotas que se estremecen<br>y el alma que se adormece<br>al olvidar sus pesares.<br><br>Cae la lluvia&#8230;<br>Ruge el viento;<br>se est\u00e1 a gusto aqu\u00ed en el nido:<br>de ella se escucha el latido,<br>de aqu\u00e9l, tan s\u00f3lo el lamento.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">COMO EL TRONCO DE LA ENCINA<\/span><br>Como el tronco de la encina<br>tengo yo la piel del alma,<br>dura y seca de esperar,<br>de esperar sin esperanza.<br>Le\u00f1oso tronco que hunde<br>sus ra\u00edces destempladas<br>en la polvorienta sangre,<br>vieja sangre atormentada.<br>Cada paso en cada calle<br>encierra una nueva trampa,<br>nuevas arrugas del tronco,<br>rugoso tronco del alma.<br>Yo quiero pasar mi mano<br>sobre las \u00e1speras ramas,<br>llevar algo de calor<br>donde huelgan las palabras,<br>dejar mi aliento caliente<br>sobre la g\u00e9lida escarcha<br>que cubre las duras grietas<br>hechas de mieles frustradas.<br>Y en las hojas verdecidas<br>a fuerza de secas l\u00e1grimas<br>tengo una costra de sue\u00f1os,<br>f\u00f3siles de negra savia.<br>Como el rostro de la tierra,<br>del labrador que la labra,<br>como el tronco de la encina<br>tengo yo la piel del alma.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">CUANDO ME VAYA DE AQU\u00cd<\/span><br>Cuando me vaya de aqu\u00ed<br>deja la ventana abierta<br>que subido en una ola<br>vendr\u00e9 a ba\u00f1ar tus arenas<br>y en cada soplo de viento<br>te mandar\u00e9 savia fresca.<br>Deja que el nogal me a\u00f1ore<br>y que me olvide la yedra,<br>que crezcan negros espinos<br>en el camino de vuelta,<br>que yo vendr\u00e9 por las nubes<br>apartando las estrellas,<br>sembrando nuevos caminos<br>en las distancias et\u00e9reas.<br><br>Qu\u00e9date con las miradas<br>que colgu\u00e9 en tu primavera<br>y con los besos azules<br>y con las blancas adelfas;<br>con los versos anhelantes<br>y las dulces azucenas.<br><br>Cuando me vaya de aqu\u00ed<br>deja la puerta entreabierta<br>que yo cuidar\u00e9 de ti<br>como cuidan las estrellas<br>de apagar la oscuridad<br>con la luz que las desvela.<br>Deja la cama vac\u00eda<br>que yo rondar\u00e9 por ella<br>en la nube del silencio<br>y en la ansiedad de la espera.<br>Cuando me vaya vendr\u00e9<br>a rondarte en cada espera.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">D\u00c9CIMA NOST\u00c1LGICA<\/span><br>\u00bfD\u00f3nde estar\u00e1 aquel roc\u00edo<br>que regaba las ma\u00f1anas<br>en esa etapa temprana<br>que fragu\u00f3 el coraz\u00f3n m\u00edo?<br>\u00bfD\u00f3nde los inviernos fr\u00edos<br>al calor de la candela?<br>\u00bfY el beso de la mistela<br>y los trigales dorados?<br>\u00bfD\u00f3nde los sue\u00f1os forjados<br>a la luz de aquella vela?<br><br><span style=\"font-weight: bold;\">DENTRO<\/span><br>Yo quiero ser vereda que recorre<br>las curvas peligrosas de tu cuerpo,<br>sentir el fresco aliento de tus valles<br>subir por las monta\u00f1as de tus huesos;<br>bajar a tus abismos m\u00e1s profundos,<br>deslizarme sinuoso hasta tu centro.<br><br>Quiero quedarme dentro, all\u00ed prendido,<br>a salvo de enemigos y de miedos:<br>humilde como un paje ante su reina,<br>altivo como un pr\u00edncipe en su reino.<br>Yo quiero sumergirme en tu mirada,<br>oscura claridad de ojos eternos,<br>resplandor invisible que ilumina<br>los pasajes de tu alma m\u00e1s secretos;<br>perderme en los infiernos de tus sombras,<br>salvarme conden\u00e1ndome en tu cielo.<br>\u00a1Ay, si para ti yo, tan solo fuera<br>una fugaz imagen de tus sue\u00f1os!<br>\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">\u00bfC\u00d3MO PUEDE LA LUZ?<\/span><br>&nbsp;I<br>\u00bfC\u00f3mo puede la luz<br>posarse indiferente en tus praderas,<br>perderse en tus montes,<br>besar tus labios y tu frente,<br>recorrerte callada e impasible,<br>cobijarse en tus huecos,<br>derramarse jugosa por tu espalda,<br>so\u00f1arse sombra en tus adentros,<br>proseguir su camino<br>y ser presencia activa en otros \u00e1mbitos?<br>\u00bfC\u00f3mo puede la luz seguir viviendo?<br>\u00bfC\u00f3mo pasa de largo?<br><br>II<br>\u00bfC\u00f3mo pueden los \u00e1tomos<br>del aire que te envuelve y te acaricia<br>perderse en otros labios,<br>refrescar otra piel,<br>doblar raudo la espalda de la esquina<br>donde te quedas t\u00fa?<br>\u00bfC\u00f3mo pueden pasar por ti sin alterarse,<br>volverse hurac\u00e1n o hacerse brisa?<br><br>\u00bfQu\u00e9 poderosa amnesia<br>les permite volar por otros mares<br>soplar en otros mundos<br>que no has llenado t\u00fa con tu presencia.<br>Mecerse en otros brazos,<br>alborotar juguet\u00f3n otros cabellos,<br>silbar en otras sienes,<br>acompa\u00f1ar rel\u00e1mpagos y truenos,<br>vagar por los caminos<br>como un gui\u00f1o sutil y aventurero?<br><br>\u00bfC\u00f3mo pueden subir a otras monta\u00f1as<br>lejanas y perdidas<br>tras escalar tus montes m\u00e1s sabrosos,<br>tus c\u00e1lidas colinas?<br>\u00bfc\u00f3mo bajan del cielo donde habitas<br>para hollar otros valles,<br>levantar polvaredas<br>esparcir las simientes milagrosas<br>y no mueren de pena en la ca\u00edda?<br><br>\u00bfQu\u00e9 extra\u00f1a condici\u00f3n,<br>qu\u00e9 fuerza c\u00f3smica<br>los amarra a otro rumbo,<br>los encadena al l\u00f3gico destino,<br>despreciando el hechizo de tu \u00f3rbita?<br><br>\u00bfQu\u00e9 g\u00e9lida pasi\u00f3n<br>despu\u00e9s de navegarte<br>huye de ti como si cualquier cosa?<br><br>\u00bfQu\u00e9 terrible desierto<br>puebla el alma de esa terrible sombra?<br><br>\u00bfC\u00f3mo pueden los \u00e1tomos del aire<br>seguir siendo hurac\u00e1n<br>y no volverse locos,<br>locos eternamente por besarte?<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">DESOLACI\u00d3N<\/span><br>Esperaban a los p\u00e1jaros<br>y encontraron motosierras:<br>ya no so\u00f1ar\u00e1n m\u00e1s frutos,<br>ya s\u00f3lo pueden ser le\u00f1a.<br>Ya no guardar\u00e1n m\u00e1s nidos,<br>entre sus ramas de piedra,<br>tan s\u00f3lo un negro recuerdo<br>de cenizas polvorientas.<br>Donde cantaban los grillos<br>hay una orquesta de claxon:<br>debajo de las aceras<br>suena un silencioso llanto.<br>Espesos bloques condenan<br>los mutilados espacios:<br>arriba, luces y antenas,<br>derrota y muerte debajo.<br>Hoy las \u00fanicas ra\u00edces<br>son los acerados cables,<br>ya no corren por sus venas,<br>dulce savia, verde sangre.<br>En cada palmo de tierra<br>hay un suspiro sin aire,<br>amarga desolaci\u00f3n,<br>pertinaz, inevitable.<br><br>Hay, bordeando las calles<br>un ej\u00e9rcito de casas,<br>rayas blancas de cemento<br>uniformes, soleadas,<br>donde crecen hombres nuevos,<br>renovadas esperanzas,<br>que segar\u00e1 en su momento<br>la inevitable guada\u00f1a.<br><br>Donde campaba el olivo<br>ahora reinar\u00e1 el asfalto:<br>hay un inmenso dolor<br>en las entra\u00f1as del campo<br><br><span style=\"font-weight: bold;\">ESTOY EN LA FRONTERA<\/span><br>Estoy en la frontera,<br>no sirvo para huir;<br>si me quedo me mata<br>un cielo bronco y gris.<br>Estoy en la frontera,<br>no quiero perseguir<br>las sombras fugitivas<br>que se escapan de m\u00ed.<br>Est\u00e1 muriendo un monstruo,<br>est\u00e1 naciendo un \u00e1ngel<br>si vuelan los fantasmas<br>si plumas se hace el lastre.<br>Si todo se hace verde<br>como en abril el valle,<br>el monstruo que agoniza<br>habr\u00e1 parido un \u00e1ngel.<br>Un aliento distinto<br>exhalar\u00e1n las cosas<br>y los ojos gastados<br>perder\u00e1n la memoria.<br><br>Y cuando una chistera<br>vomite una paloma<br>yo soplar\u00e9 las manos<br>del mago que la nombra.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">ESA DIVINA LUZ<\/span><br>Esa luz divina<br>que nos ciega la frente,<br>que brota de abismos y de cielos,<br>que est\u00e1 en cada rinc\u00f3n,<br>que inunda los espejos<br>de una fuente interior<br>deshabitada,<br>convierte en p\u00e1ramo el jard\u00edn<br>y riega los desiertos.<br><br>Esa mano de Dios<br>asiendo con sus dedos invisibles<br>la terrible verdad,<br>que esparce pertinaz sobre los hombres,<br>se\u00f1ala por siempre los senderos,<br>mide sin cesar oscuridades;<br>capaz de amor inmenso,<br>inmenso amor,<br>deja sus predios de la mano de Dios<br>y atiende lo imposible.<br><br>Ese ojo encerrado en un tri\u00e1ngulo,<br>que presiente todas las presencias,<br>que no conoce l\u00edmites<br>ni siquiera en su divino ser,<br>incansable, infinito,<br>que todo lo vislumbra,<br>que ve su propio ojo,<br>oscurece sus c\u00e9firos dominios<br>para alumbrar la nada.<br><br>Ese terrible c\u00edrculo perfecto<br>que ocupa todo,<br>que todo lo sabe y lo imagina,<br>total totalidad,<br>suma perfecta<br>de imperfectos sumandos,<br>brutal capacidad,<br>suprema dimensi\u00f3n,<br>cobija vacuidades<br>y desaira rec\u00f3nditos temblores.<br><br>Ese o\u00eddo de Dios<br>que escucha lo inaudible,<br>que interpreta sin luz los corazones,<br>que dispone sublimes pentagramas,<br>consonantes acordes,<br>que goza con grandiosas melod\u00edas,<br>que inventa ritmos puros<br>y mora en la armon\u00eda,<br>est\u00e1 abierto a truenos y explosiones<br>y no puede escuchar la voz del hombre.\n        <br><br><span style=\"font-weight: bold;\">IMPRESI\u00d3N<\/span><br>Dos mulas y una carreta<br>por el carril aparecen,<br>en mi alma se estremecen<br>los acordes del pasado;<br>llegan aromas de siega<br>huele a rastrojos quemados.<br>\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">EN SUS LAURELES<\/span><br>Ya no tiene quien siembre su barbecho,<br>ya no siente sus dedos en la espalda,<br>ni ya le aturde el vuelo de su falda<br>ni est\u00e1 su nombre ardi\u00e9ndole en el pecho.<br><br>Pasi\u00f3n var\u00f3 en la orilla, naufragada;<br>el fuego eterno se quem\u00f3 en la nieve;<br>lo que fue el todo se torn\u00f3 en un leve<br>y p\u00e1lido reflejo de la nada.<br><br>Nadie atiz\u00f3 la llama consumida,<br>pensaban que era un cielo permanente<br>aquel tiempo de rosas y claveles<br><br>que una vez por azar les dio la vida.<br>Y el amor se hizo sue\u00f1o eternamente,<br>se durmi\u00f3 para siempre en sus laureles.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">ES CURIOSO SE\u00d1OR<\/span><br>Es curioso, Se\u00f1or, el desatino<br>que induce tu poder imponderable:<br>conviertes en piadoso al despreciable<br>y en un sabio al mostrenco m\u00e1s cretino.<br><br>En nombre del amor m\u00e1s generoso<br>blanden espadas Tus creyentes fieros,<br>transformando las flores del sendero<br>en pistolas del brazo poderoso.<br><br>Es muy duro que apruebes que en Tu nombre<br>anden a tortas los incautos hombres.<br>Y es terrible, Se\u00f1or, el triste hecho,<br><br>inhumano y brutal como una roca,<br>que los que no te sienten en el pecho<br>son los que m\u00e1s te llevan en la boca.\n        <br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">FRUSTRACI\u00d3N<\/span><br>\u00a1Qu\u00e9 ingrata lucha, negra frustraci\u00f3n!<br>querer sembrar en \u00e1rido desierto,<br>pretender cultivar un pobre huerto<br>condenado a ser carne de ca\u00f1\u00f3n.<br><br>Me duelen como un tr\u00e1gico tormento<br>estas vidas sin rumbo y sin ma\u00f1ana,<br>pobres almas de fr\u00e1gil porcelana,<br>tristes hojas llevadas por el viento.<br><br>Cada paso es un paso hacia el abismo,<br>cada caso es un calco de lo mismo:<br>con fruici\u00f3n, sin descanso y ciegamente<br><br>se sumergen con gusto en la manada<br>y t\u00fa los ves hundirse mansamente<br>sin que tu ciencia sirva para nada.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">\n         FRUTOS DEL OTO\u00d1O<\/span><br>Este modesto manojo de sue\u00f1os,<br>esta ristra de toscas emociones<br>responden al anhelo de mi empe\u00f1o<br>por convertir mis dudas en canciones.<br><br>No quieren ser bandera ni doctrina<br>ni son remedio contra el desaliento;<br>s\u00ed quieren ser fugaces golondrinas<br>que dibujan sus huellas en el viento.<br><br>Apenas van brotando de la boca<br>lanzan el vuelo a buscar su ventura<br>como torpes y fr\u00e1giles reto\u00f1os.<br><br>Perd\u00f3name si alguna es hiel o roca,<br>disculpa las cargadas de amargura,<br>pues no son m\u00e1s que frutos del oto\u00f1o.\n        <br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">\u00bfHAY ALGO DETR\u00c1S DE LAS PALABRAS?<\/span><br>\u00bfHay verdades detr\u00e1s de las palabras?<br>\u00bfHay algo detr\u00e1s de las palabras?<br>\u00bfNo son m\u00e1s que sonidos que acarician,<br>hieren, lastiman, ofenden, desesperan?<br>Tal vez no son m\u00e1s que s\u00edmbolos marchitos,<br>tal vez no m\u00e1s que sombras de la nada.<br>Quiz\u00e1 s\u00f3lo son ondas que envenenan,<br>divierten, perdonan y estimulan,<br>pero nada detr\u00e1s, nada que lleve<br>un \u00e1tomo de luz de tu mirada.<br>\u00bfHay mentiras detr\u00e1s de las palabras?<br>\u00bfHay algo detr\u00e1s de las palabras?<br>S\u00f3lo nombres, adverbios y adjetivos,<br>art\u00edculos, verbos, concordancias?<br>\u00bfDetr\u00e1s no habr\u00e1 ese coraz\u00f3n que llora,<br>esa rabia que hace crecer la vida?\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">LEVANTE<\/span><br>Desapacibles d\u00edas de levante<br>que alteran la cabeza m\u00e1s serena,<br>cual resaca tras noche de verbena<br>con vino generoso y dulce cante.<br><br>Soplo de Eolo que, cuando se enoja,<br>lanza al espacio y ruge cuando pasa,<br>rob\u00e1ndole a los \u00e1rboles sus hojas<br>y dejando a las gentes en sus casas.<br><br>En Ronda, en tus visitas cotidianas<br>tus dedos invisibles se divierten<br>estremeciendo puertas y ventanas:<br>met\u00e1fora invisible de la muerte.<br><br>S\u00f3lo una vez te siento pertinente,<br>te lo dir\u00e9 con lujo de detalles:<br>cuando estoy entre s\u00e1banas calientes<br>oyendo c\u00f3mo bramas por las calles.\n        <br><br>\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">LA COSA TIENE TOMATE<\/span><br>Esa mujer que se entrega<br>a cultivar \u201cel tomate\u201d,<br>lo cultiva mas lo niega<br>\u00bfYo eso?\u2026\u00a1Qu\u00e9 disparate!<br><br>Y ese hombre que embobado<br>tan sumiso la acompa\u00f1a<br>representa a media Espa\u00f1a;<br>la otra, la tiene a su lado.<br><br>En esta sociedad nuestra<br>todo es medido o comprado;<br>en disimulo es maestra;<br>nadie asume sus pecados.<br><br>Y es que atenta a la decencia<br>comprobar tanto dislate:<br>ver los datos de la audiencia<br>y que nadie se delate.<br><br>Duele que tantos ga\u00f1anes<br>s\u00f3lo pongan su pasi\u00f3n<br>en \u201cpasi\u00f3n de gavilanes\u201d<br>y en cuitas del coraz\u00f3n.<br><br>Mal asunto es que la gente<br>ande poniendo su empe\u00f1o<br>en perder horas de sue\u00f1o<br>y en jibarizar su mente.<br><br>Produce rabia y da pena<br>que con cruel delectaci\u00f3n<br>fabrique su diversi\u00f3n<br>con las miserias ajenas.<br><br>Un pueblo que de tal suerte<br>sus ocios as\u00ed cultiva<br>es un barco a la deriva<br>un tren con rumbo a la muerte.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">LA RADIO<\/span><br>Cuando te pesan los huesos<br>como pesan los fracasos,<br>cuando el silencio se impone<br>como se impone un mal trago;<br>cuando todo est\u00e1 perdido,<br>cuando nos puede el letargo,<br>cuando eres plomo por dentro,<br>siempre nos queda la radio.<br>Cuando se acerca la noche<br>y la luz se va apagando;<br>cuando calla la esperanza,<br>cuando habla el desenga\u00f1o<br>y s\u00f3lo soplos del viento<br>pueden coger nuestros brazos;<br>cuando todo est\u00e1 vac\u00edo<br>siempre nos queda la radio.<br>Cuando no queda una boca<br>donde poner nuestros labios,<br>cuando no tenemos voz<br>para lanzar nuestro canto;<br>cuando nos falta ese hombro<br>donde apoyar nuestra mano;<br>cuando perdemos las alas<br>siempre nos queda la radio.<br><br>Cuando la vida le pone<br>zancadillas a los pasos;<br>cuando correr es lo mismo,<br>lo mismo que estar sentados;<br>cuando da igual lo que hacemos,<br>cuando da igual lo que hagamos;<br>cuando lo mejor es nada<br>siempre nos queda la radio.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">EN EL CENTRO DE MI CENTRO<\/span><br>En el centro de mi centro<br>he plantado una esperanza;<br>la alimento con mis sue\u00f1os<br>y la riego con mis l\u00e1grimas.<br>Espero que apunte al cielo,<br>aunque s\u00e9 que es fruta vana,<br>que nunca echar\u00e1 ra\u00edces,<br>que no parir\u00e1 un ma\u00f1ana.<br>Pero yo voy cultivando<br>con esmero, con constancia,<br>su fr\u00e1gil arquitectura,<br>su pobre verdad amarga.<br>Arranco las malas hierbas<br>que la oprimen con sus garras.<br>Le doy calor en invierno<br>y la cobijo en mi casa<br>Pero s\u00e9 que no es posible<br>que su sombra sea grata.<br>Que nI se abrir\u00e1n sus hojas<br>ni se extender\u00e1n sus ramas.<br>Que no cantar\u00e1n los p\u00e1jaros<br>en sus precarias entra\u00f1as.<br>Que no besar\u00e1 la luna<br>sus l\u00edvidas flores blancas.<br>Que se perder\u00e1 en la noche<br>como se pierde la nada,<br>pero yo sigo aqu\u00ed dentro<br>cultivando una esperanza.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">LOS CAPRICHOS DE LA MODA<\/span><br>Yo sospecho que mi musa<br>tiene m\u00e1s fe que talento<br>y la pobre es una ilusa,<br>una lamentable intrusa<br>que se cree sus propios cuentos.<br>S\u00e9 que mi pluma y mi historia<br>&#8211; que a conocer os convido &#8211;<br>m\u00e1s que apuntar a la gloria<br>y a quedar en la memoria,<br>ir\u00e1n raudas al olvido.<br>Y s\u00e9 que no soplan vientos<br>para sensibles poetas,<br>ni cotiza el sentimiento,<br>ni emocionan las cuartetas.<br>M\u00e1s s\u00e9 tambi\u00e9n que la moda<br>puede encumbrar a cualquiera<br>y as\u00ed puede ser que un d\u00eda,<br>como flor de primavera,<br>escriba mi biograf\u00eda<br>&#8211; \u00a1qu\u00e9 honor m\u00e1s grande ser\u00eda! &#8211;<br>Don Rafael Aguilera.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">LA M\u00c9TRICA<\/span><br>Yo s\u00e9 bien que hoy el verso no se estima<br>si no se humilla ante la nueva est\u00e9tica<br>que desprecia las reglas de la m\u00e9trica<br>y los dulces compases de la rima.<br><br>En nombre de una extra\u00f1a libertad<br>se alejan sin decoro de la norma,<br>lo que no suele ser m\u00e1s que otra forma<br>de rendirse a la propia vacuidad.<br><br>A la grupa de reglas del pasado<br>sin abjurar del cl\u00e1sico equipaje,<br>dejaron los Quevedo y los Machado<br>muy alto y muy concreto su mensaje.<br><br>Hoy cualquier tonto puede ser poeta<br>cualquier insustancial pasar por vate,<br>basta con ser un loco de remate<br>y escribir como mande la bragueta.<br><br>Hoy cualquiera se pierde en su maleza<br>en busca de un perdido escalofr\u00edo,<br>mas poco puede alejarse del vac\u00edo<br>quien no tiene otra cosa en la cabeza.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">LA TARDE<\/span><br>La tarde viene seria y en su vientre<br>guarda el peso de tardes infinitas,<br>gotas de plomo manan de su frente,<br>balas que hieren su beldad marchita<br>Bolas de fuego adornan su cabeza,<br>con besos rotos viste su plumaje<br>tal vez detuvo en seco su viaje<br>el dios de la aton\u00eda y la pereza.<br>Lo mismo que una dicha que se a\u00f1ora,<br>recuerda sus pasados esplendores,<br>aquellos donde vivos sus colores<br>reinaban con soberbia en cada hora.<br>Ya no la besan los temibles vientos<br>ni acarician su pelo los amantes<br>minutos del reloj en movimiento<br>ni la mece la brisa como antes.<br>Con flojedad se arrastra mansamente<br>en busca de la noche que la espera<br>enganchada a su sino, compa\u00f1era,<br>presas las dos de una feroz corriente.<br>Tallada va en el pecho su verdad<br>como una maldici\u00f3n empecinada<br>y en su cara se palpa alucinada<br>su indestructible sed de eternidad.<br><br>\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">MIRADAS<\/span><br>Miradas hondas, sutiles<br>tiernas y dulces miradas<br>penetrantes y profundas,<br>elocuentes como l\u00e1grimas;<br>lanzadas con la intenci\u00f3n<br>del que est\u00e1 lanzando el alma,<br>recibidas con el gozo<br>de quien colma su esperanza.<br>siempre a mitad de camino<br>entre el temor y las ganas,<br>un s\u00ed es no es que estremece<br>y levanta las espadas;<br>un derroche de intenciones<br>comprendidas y admiradas.<br>Con estr\u00e9pito de truenos<br>\u00e9l las suyas disparaba,<br>como una bala perdida<br>en la frontera del alba.<br>Quien sabe mirar as\u00ed<br>lleva un misil en la cara.<br>Ella atacando de frente,<br>devolviendo la estocada,<br>todo un tratado de versos<br>que rompe cualquier muralla.<br>Hasta que lleg\u00f3 el momento<br>de recortar las distancias<br>y de convertir en actos<br>las potencias disparadas.<br>Cuando empezaron a hablar<br>se fue apagando la magia<br>y entre ellos y el amor,<br>entre el amor y la nada<br>s\u00f3lo quedaron vulgares,<br>toscas y torpes palabras.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">LIBRE<\/span><br>Agua dulce que resbala<br>por el rostro de la sierra,<br>vencida a su propio peso,<br>buscando verdes riberas.<br>Agua dulce que se embala<br>en vibrantes torrenteras ;<br>agua de pr\u00f3digas lluvias<br>y de interminables nieblas,<br>l\u00e1grimas de este paisaje<br>de arbustos, riscos y piedras.<br>Agua que baja del cielo<br>y vuelve a la dulce tierra.<br>Agua que no quiere diques<br>ni canales ni compuertas,<br>ni pantanos ni lagunas<br>ni manantiales ni acequias;<br>agua que desciende libre<br>y que libre se despe\u00f1a,<br>s\u00f3lo obediente al instinto<br>natural del agua fresca.<br>Agua que se sue\u00f1a libre<br>y que libre se condena,<br>que teje su breve vida<br>con mol\u00e9culas eternas.<br>Agua dulce que resbala<br>por los poros de las piedras,<br>agua que baja del cielo<br>y vuelve a la dulce tierra.\n        <br><br>SI VENIMOS AQU\u00cd<br>Si venimos aqu\u00ed porque nos traen,<br>si nos vamos de aqu\u00ed porque nos llevan,<br>si estamos aqu\u00ed porque nos dejan,<br>como nos dejan;<br>\u00bfpor qu\u00e9 nos piden tanto a cambio?<br>\u00bfPor qu\u00e9 tanto dolor?<br>\u00bfPor qu\u00e9 tanto dolor?<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">LAS GOTITAS DE LLUVIA<\/span><br>Las gotitas de lluvia<br>tras la ventana<br>van tejiendo caminos<br>de porcelana.<br>Traviesas van pasando<br>sus leves horas,<br>felices como alegres<br>patinadoras.<br>Las gotitas de lluvia<br>son inocentes<br>met\u00e1foras aladas<br>y transparentes.<br>Desnudas en su esfera,<br>viven temblando,<br>furtivas como un beso<br>de contrabando.<br>Las gotitas de lluvia<br>bailan su danza:<br>escu\u00e1lido trasunto<br>de la esperanza.<br>Lo mismo que los hombres,<br>pintan su huella<br>como una reluciente<br>fugaz estrella.<br>Las gotitas de lluvia<br>mueren saltando<br>hundidas en un mundo<br>h\u00famedo y blando.<br><br>Vencidas por su peso,<br>van mansamente<br>a perderse en la nada<br>de la corriente.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">ME GUSTAN<\/span><br>Me gustan las ma\u00f1anas<br>brillantes, relucientes,<br>pre\u00f1adas de aguardiente<br>y aromas de caf\u00e9.<br><br>Me gusta beber vino<br>rodeado de amigos;<br>y si son enemigos<br>me lo bebo tambi\u00e9n.<br>Y escuchar esas voces<br>que apagando el ruido,<br>acarician mi o\u00eddo:<br>\u00bfqu\u00e9 llenen otra vez!<br><br>Y las calles lavadas<br>que, privadas de gente,<br>esperan impacientes,<br>te invitan a correr.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">REAL MADRID<\/span><br>(En su centenario: 2002, a\u00f1o de la 9\u00aa copa de Europa)<br>Glorioso campe\u00f3n, Europa entera<br>rendida est\u00e1 a tus pies, embelesada,<br>gozando de la magia desbordada<br>si tocas con primor la blanca esfera.<br><br>L\u00fadica religi\u00f3n que da sentido<br>a una vida agobiante y pervertida,<br>que regala la gloria en esta vida<br>cada vez que ganamos un partido.<br><br>De gestas sin igual y haza\u00f1as tantas,<br>tu historia centenaria reina al son<br>de cada gol que rompe las gargantas,<br><br>que han llenado de copas tu vitrina,<br>poniendo en el cielo a la afici\u00f3n<br>con la carne del alma de gallina.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">SALVE EURO<\/span><br>\u00a1Oh, C\u00e9sar de la nueva econom\u00eda!<br>A tus pies ves rendida a Europa entera;<br>nuevo due\u00f1o y se\u00f1or de las carteras.<br>inst\u00e1late a tus anchas en la m\u00eda.<br><br>Uno, dos, cinco, diez, veinte, cincuenta,<br>por ciento sesenta y seis, coma&#8230; \u00a1joder!<br>\u00a1Qu\u00e9 autoridad sin par para poner<br>a todo el personal a hacer las cuentas!<br><br>Adi\u00f3s a la peseta provinciana;<br>\u00a1salve euro! moneda del ma\u00f1ana.<br>Ojal\u00e1 que nos traigas buena estrella.<br><br>Un prudente consejo quiero darte:<br>a ver si pides para conquistarte<br>menos sudor que el que exig\u00eda ella.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">\n         PEDRO P\u00c9REZ CLOTET<\/span><br>Aqu\u00ed estoy, en Villaluenga,<br>donde reposa el maestro,<br>alimentando a esta tierra<br>que le dio tanto alimento.<br>Domesticando palabras,<br>aprehendiendo lo eterno,<br>todo lo que aqu\u00ed vivi\u00f3<br>sigue viviendo en sus versos.<br>\u00c9l buscaba las esencias,<br>dejaba de lado el viento:<br>poes\u00eda sustantiva<br>sin ambages ni embelecos,<br>l\u00edneas trazadas con sangre,<br>caliente sangre del cuerpo.<br>En estos luengos lugares,<br>donde estremece el silencio,<br>m\u00e1s apartado del mundo,<br>m\u00e1s cerca del universo,<br>sinti\u00f3 el poeta estos riscos,<br>estos valles y estos cerros,<br>esta luz y estos paisajes,<br>acompasando su tiempo:<br>ritmo lento del que vive<br>la vida siempre hacia adentro.<br>Sin prisa, lento, despacio,<br>templando como un torero,<br>citando al toro de frente,<br>solo en el centro del ruedo,<br>disfrutando cada trago<br>como si fuera el postrero.<br>Cargado de este bagaje<br>sobrevol\u00f3 los eternos,<br>turbios espacios del alma,<br>recorriendo sus senderos,<br>dando firmeza a sus pasos,<br>iluminando los nuestros.<br>Negociando con el alba,<br>elev\u00e1ndose del suelo<br>para ver que no hay caminos,<br>que la vida es como un sue\u00f1o:<br>oscura noche del hombre,<br>primer amor, desconsuelo.<br>Ante nada indiferente,<br>nada de aqu\u00ed le fue ajeno<br>hasta que un d\u00eda su sombra<br>sucumbi\u00f3 ante tanto peso<br>y su fr\u00e1gil coraz\u00f3n,<br>temprano ,libre, sereno,<br>como una nube dorada,<br>emprendi\u00f3 el \u00faltimo vuelo.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">LA M\u00daSICA<\/span><br>Has llegado a mi vida<br>para ahuyentar la noche:<br>has llenado mi c\u00e1ntaro<br>de pasi\u00f3n hasta el borde.<br>Has deshecho la niebla<br>que ocupaba mi alma,<br>has barrido con ella<br>temores y fantasmas.<br>Has elevado al cielo<br>mi coraz\u00f3n alado,<br>contigo sigue errante,<br>libre como los p\u00e1jaros.<br>Cuando canto contigo<br>mi pulso se hace eterno,<br>cuando lloro en tus brazos<br>me prestas tu pa\u00f1uelo<br>Te has quedado conmigo,<br>ya somos uno solo;<br>me confundo en tu pecho,<br>me consuelo en tu hombro.<br>Charlamos en silencio<br>cual dos enamorados<br>que buscan en tu ritmo<br>acompasar sus pasos,<br>perderse en un te quiero,<br>fundirse en un abrazo.<br>Por el camino voy,<br>mirando siempre al frente:<br>si t\u00fa vienes conmigo<br>no me importa la muerte.<br><br>\t<span style=\"font-weight: bold;\">ZIDANE<\/span><br>\u00a1Qu\u00e9 gracia y qu\u00e9 armon\u00eda en tu figura!<br>cuando acaricias con mimo la pelota,<br>seducida sin remedio por tu bota<br>embebida al comp\u00e1s de tu estatura.<br><br>Desde el c\u00e9sped fascina en la distancia<br>tu tonsura de fraile arrepentido,<br>referencia obligada del partido,<br>centro de gravedad de tu elegancia.<br><br>\u00a1Oh, gran Zizou, poeta futbolista,<br>un aura te acompa\u00f1a cuando avanzas,<br>tus gestos son las huellas de un artista,<br><br>tus pases son met\u00e1foras andantes;<br>lo tuyo es un ballet, es una danza,<br>una danza genial y alucinante.<br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">PASI\u00d3N CARNAVALESCA<\/span><br>Desde que el a\u00f1o que llega<br>dice adi\u00f3s al que se va<br>mi amigo Pepe se cuelga<br>su alma de carnaval<br>y hasta que aqu\u00e9l se despide<br>no se la vuelve a quitar.<br>Su coraz\u00f3n de gigante<br>se vuelve un grandioso hogar<br>donde arden las esencias<br>de esta fiesta popular.<br><br>Y sue\u00f1a con chirigotas,<br>con coros y con comparsas,<br>con cuartetos, dioses momos,<br>con la gente disfrazada,<br>con el teatro Espinel<br>y con el templo del Falla.<br><br>Mi amigo Pepe decora<br>de carnavales su alma<br>desde que el a\u00f1o que llega<br>dice adi\u00f3s al que se acaba .<br><img decoding=\"async\" width=\"110\" height=\"119\" alt=\"\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/largo.jpg\"><br><br><span style=\"font-weight: bold;\">TERREMOTO<\/span><br>Hay un estr\u00e9pito tronando en cada mundo,<br>ruido infernal en fantasmal silencio,<br>un torbellino huyendo de la noche,<br>un agobio infernal,<br>un terremoto en busca de los hombres,<br>p\u00e1lidas sombras de su esencia marchita.<br><br>Pura realidad<br>ahogando cada sue\u00f1o,<br>jugosa explosi\u00f3n que ahoga los o\u00eddos,<br>que aturde el pensamiento.<br><br>\u00a1Con qu\u00e9 ansiedad espero<br>la brutal llamarada<br>de tu caudal sonoro!<br>\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">PARAD\u00d3JICA LUZ<\/span><br>Los rayos iluminan la monta\u00f1a<br>mientras el agua cae tras la ventana,<br>parad\u00f3jicamente la ma\u00f1ana,<br>lejos pinta de azul y cerca empa\u00f1a.<br><br>Esta dudosa luz de primavera,<br>que en l\u00e1mpara convierte el horizonte,<br>decora un escenario all\u00e1 en el monte<br>traspasando una inmensa regadera.<br><br>Igual el hombre, a veces se confunde<br>a lomos del fracaso y la esperanza<br>sin tener una certeza que lo inunde<br><br>y descalzo, corriendo por rastrojos,<br>aprecia lo que luce en lontananza<br>y no ve lo que tiene ante los ojos.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">YA EST\u00c1N LAS ACEITUNAS VERDEANDO<\/span><br>Ya est\u00e1n las aceitunas verdeando,<br>ya el oto\u00f1o se ha hecho primavera<br>y los fr\u00edvolos chopos en hilera<br>se han ido lentamente desnudando.<br><br>Un tibio sol asoma su sonrisa<br>tras una nube negra y desgajada;<br>hay un negro presagio de la nada<br>en el hielo punzante de la brisa.<br><br>El resplandor brillante de la tarde<br>se esparce por el m\u00e1gico sendero<br>y una penumbra p\u00e1lida y cobarde<br>acecha para hacerlo prisionero.<br><br>Los p\u00e1jaros preparan su equipaje,<br>malos tiempos atisban tras la esquina<br>y las negras y tenues golondrinas<br>trazaron hace tiempo su viaje.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">YO TE SIENTO SE\u00d1OR<\/span><br>Yo te siento, Se\u00f1or, en la ternura<br>de una risa infantil, de una mirada<br>y te noto en la carne enamorada<br>de tus pobres y ardientes criaturas.<br><br>Te puedo ver gozando la locura<br>de los que dan su vida alucinada<br>por transportar en s\u00ed la llamarada<br>de Tu esencia preciosa, clara y pura.<br><br>Mas, \u00bfy el odio, el dolor y la pobreza,<br>la soledad, el miedo, la agon\u00eda<br>la angustia, el desamparo y la tristeza,<br><br>de sentirse transidos de impotencia,<br>no son faltas en tu caligraf\u00eda?<br>\u00bfno son un claro ejemplo de tu ausencia?\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">PRISIONERO<\/span><br>De bruces en la tierra,<br>prisionero del tedio y del olvido,<br>ajeno a los radiantes<br>d\u00edas de la infancia caducada.<br>Sin norte en las tinieblas<br>de un camino de piedras y de rosas<br>marchitas y esparcidas<br>por los blandos espacios<br>de un tiempo despiadado<br>que se encierra en un bucle,<br>que no despierta el agua<br>ni la luz ni el paisaje.<br>De sordos latidos se alimenta<br>y pone a andar su m\u00e1quina maltrecha,<br>carcomida y caduca;<br>vencida, castigada<br>por un fondo de piedras en el alma.<br>As\u00ed la savia fluye,<br>esparce su vital adolescencia,<br>se arrastra, se inocula<br>por los poros m\u00e1s leves de las nubes<br>rosas de tantos y tan tiernos<br>primorosos y valientes<br>atardeceres malgastados.\n        <br><br><span style=\"font-weight: bold;\">SUE\u00d1OS DE BLANCO SAT\u00c9N<\/span><br>Sobre agujas un ser se balancea,<br>haces de luz la oscuridad apagan,<br>un gozoso murmullo de glamour<br>invade cada mente y cada cuerpo.<br>Urnas brillantes muestran sugerentes<br>promesas de atracci\u00f3n irresistible;<br>el probador indiferente deja<br>esquemas de ansiedad en las miradas.<br>Ir y venir que bulle sigiloso<br>como un ej\u00e9rcito desordenado,<br>mas todo est\u00e1 medido, milim\u00e9trico<br>en el febril dictado de la moda,<br>espejo de cart\u00f3n que nos recuerda<br>la insoportable levedad del ser.<br>La gloria y el infierno aqu\u00ed comparten<br>espacio y tiempo, trastienda y escenario,<br>en tenaz equilibrio van marchando,<br>blanca ilusi\u00f3n y negro desconsuelo.<br><br>Si las miradas son el objetivo,<br>enemigo se vuelve el propio ojo,<br>el cuerpo que te lleva es una c\u00e1rcel<br>sin balcones ni puerta de salida;<br>siempre en conflicto esp\u00edritu y materia:<br>resolviendo ecuaciones imposibles,<br>cruce de realidades y deseos.<br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">PARECE QUE FUE AYER<\/span><br>Parece que fue ayer<br>cuando la alegr\u00eda<br>andaba por nuestra vida<br>como en su propia casa.<br>Cuando todo estaba<br>perfectamente explicado<br>porque todo era un misterio.<br>Cuando la vida tan solo<br>consist\u00eda en vivir.<br>cuando todos los problemas<br>se reduc\u00edan a uno:<br>estar a salvo de ellos.<br>Cuando el amor era<br>enemigo mortal de la angustia.<br>Cuando est\u00e1bamos amparados<br>frente al desamparo.<br>Cuando no nos importaba<br>en absoluto, lo que era el sol:<br>bastaban sus caricias en invierno,<br>protegernos de \u00e9l en el verano.<br><br>Cuando correr no era un ejercicio<br>sino una explosi\u00f3n de la energ\u00eda.<br>Cuando pens\u00e1bamos,<br>sin prejuicios, librepensadores.<br>Cuando los dogmas a\u00fan<br>no hab\u00edan castrado<br>nuestra independencia.<br>Cuando todav\u00eda<br>no nos hab\u00edan capado.<br>cuando a\u00fan no hab\u00edan<br>acabado con nosotros.<br>cuando est\u00e1bamos vacunados<br>contra las pamplinas.<br>La felicidad consiste<br>en que no te cojan;<br>en driblar las tonter\u00edas;<br>en eludir las grandes<br>buenas palabras.<br>En estar entre ellos<br>sin sentirlos.<br>En ser t\u00fa solo.<br>Por eso es imposible.<br>La felicidad existe<br>pero a\u00fan no es posible.<br>Todav\u00eda somos marionetas;<br>no es posible romper todos los hilos.<br>\u00a1Hay tantos!<br>Y bastar\u00eda uno para asfixiarnos.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">SEMANA SANTA<\/span><br>En fila los nazarenos,<br>redoblando los tambores,<br>en tensi\u00f3n los horquilleros,<br>los tronos llenos de flores.<br><br>Conviven en las aceras<br>el incienso y la arrop\u00eda ,<br>las prisas y las esperas,<br>el dolor y la alegr\u00eda.<br><br>El silencio y el bullicio,<br>los milagros, la raz\u00f3n,<br>las virtudes y los vicios,<br>la fe y la superstici\u00f3n.<br><br>La fe contraria a pensar<br>la del pueblo milenario,<br>la religi\u00f3n popular<br>de mantillas y rosario.<br><br>Est\u00e1 el pueblo convencido,<br>el que aplaude al dios clavado,<br>ese que nunca ha entendido<br>la saeta de Machado.<br><br>Est\u00e1 el pueblo indiferente<br>que guarda la tradici\u00f3n,<br>el que sigue la corriente<br>si lo manda la ocasi\u00f3n.<br><br>Y est\u00e1 el que busca la fiesta<br>y el placer de los sentidos,<br>el que rechaza la cuesta<br>si subir no es divertido.<br><br>Tambi\u00e9n los inteligentes<br>que comparten devoci\u00f3n:<br>farolillos en la frente,<br>cirios en el coraz\u00f3n.<br><br>La piedad, la algarab\u00eda,<br>el fervor y el desenfreno,<br>el placer y la agon\u00eda,<br>el hombre malo y el bueno.<br><br>Tatuajes junto a estigmas,<br>estrellas, gente sin nombre,<br>claridades junto a enigmas,<br>vaga condici\u00f3n del hombre.<br><br>Son brochazos de impresi\u00f3n,<br>estampas de una semana,<br>tiempo de gozo y pasi\u00f3n:<br>Semana Santa y profana.\n        <br><br>\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">SI TE VIENE BIEN<\/span><br>Si te viene bien<br>hacemos un trato:<br>t\u00fa pones la cara,<br>yo pongo los labios;<br>t\u00fa pones el cuerpo<br>yo pongo el abrazo;<br>t\u00fa la piel desnuda,<br>yo, la fresca mano.<br>T\u00fa pones la voz<br>y yo los aplausos.<br><br>Si a ti te parece<br>firmamos un pacto,<br>nos damos un cr\u00e9dito<br>sin letras ni plazos;<br>t\u00fa pones el sitio,<br>yo pongo el horario.<br>T\u00fa llenas de vino<br>mi sediento vaso<br>y yo de agua fresca<br>tu anhelante c\u00e1ntaro.<br><br>Si nos viene bien<br>hacemos un trato:<br>t\u00fa le pones alas<br>a mis graves p\u00e1rpados<br>y yo te regalo<br>mis cofres sagrados.<br>T\u00fa me amarras fuerte<br>con tus dulces lazos<br>y yo siembro ardiente<br>tu vientre dorado.<br><br>Si a ti te parece<br>firmamos un pacto:<br>yo pongo los besos,<br>t\u00fa pones los labios,<br>todo lo dem\u00e1s<br>llegar\u00e1 a su paso.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">BENDITA SOLEDAD<\/span><br>Bendita soledad<br>que te devuelve a ti mismo,<br>que te aparta de los otros<br>cuando te quitan el sitio.<br>Maldita soledad<br>que no consuela ni la compa\u00f1\u00eda,<br>que se abraza febril a los recuerdos,<br>que no encuentra la puerta de salida.<br><br>Bendita soledad<br>que nos deja rumiando lo vivido,<br>que ordena nuestra historia,<br>que pone pausa y luz en el camino.<br>Maldita soledad<br>que nos esconde el futuro,<br>que levanta una frontera<br>entre nosotros y el mundo.<br><br>Bendita soledad<br>que te secuestra en tu casa<br>a salvo de ruidos y vulgares<br>debilidades humanas.<br>Maldita soledad<br>que no deja disfrutar<br>de la magia que emana de los otros,<br>del c\u00e1lido calor de los dem\u00e1s.<br><br>Bendita soledad<br>que se instala a tus anchas,<br>que mira m\u00e1s all\u00e1,<br>m\u00e1s all\u00e1 del placer y la esperanza.<br><br>Maldita soledad<br>que mira entre la niebla,<br>que busca ansiosamente claridad<br>y s\u00f3lo niebla en el vac\u00edo encuentra.<br><br>Bendita soledad,<br>qu\u00e9date, sigue mi ritmo,<br>que siempre te tenga a mano<br>cuando quiera estar conmigo.<br>Maldita soledad,<br>vete por esos caminos<br>que ya es buena compa\u00f1\u00eda<br>la que me dan los amigos.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">TE BUSCO EN INTERNET<\/span><br>Dicen que en Internet se encuentra todo,<br>en sus venas de acero,<br>entre ceros y unos impasibles,<br>en medio de rocosos gigahercios.<br>Yo te he buscado a ti<br>y te sigo buscando en cada hueco<br>de su inmensa estructura,<br>en los espacios fr\u00edos de su esqueleto.<br>Te busco en cada archivo,<br>en cada directorio polvoriento,<br>en cada subcarpeta,<br>en cada chat ocioso, en cada puerto.<br>Entre fuertes tormentas me aventuro,<br>por procelosas aguas yo navego<br>como un cachorro herido,<br>como un le\u00f3n hambriento,<br>entre la furia y la melancol\u00eda,<br>entre la expectaci\u00f3n y el desaliento.<br>Atrapado en la red<br>busco saciar mi coraz\u00f3n sediento<br>y no encuentro ni un rastro de tu sombra,<br>ni un solo poro de tu dulce cuerpo,<br>ni un \u00e1pice de ti,<br>ni una m\u00ednima huella en el sendero,<br>ni un indicio de c\u00e1lidas palabras,<br>ni un atisbo de fr\u00e1giles alientos.<br>Te busco en Internet,<br>persigo un sue\u00f1o,<br>he ganado unas cuantas dioptr\u00edas<br>en este vano empe\u00f1o.<br>Te busco en Internet,<br>donde todo se encuentra,<br>y no te encuentro.<br><img loading=\"lazy\" decoding=\"async\" width=\"208\" height=\"150\" alt=\"\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/utopia.jpg\">\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">T\u00da SALUDAS A LA GENTE POR LA CALLE<\/span><br>T\u00fa saludas a la gente por la calle<br>vuelves pronto a tu casa,<br>eres un padre responsable<br>y un esposo sol\u00edcito y dispuesto.<br>Nunca faltas al trabajo<br>ni tienes malos gestos con la gente,<br>te comes lo que ganas;<br>vives como te lo permite<br>tu modesto sueldo.<br>Est\u00e1s alegre aunque te sientas triste,<br>intentas animar al que padece<br>y pones buenas caras<br>a todo el que se cruza en tu camino<br>Das lo que puedes,<br>no piensas m\u00e1s en ti que en los dem\u00e1s<br>y tienes una mano generosa<br>para quien la necesite.<br>No hablas jam\u00e1s de nadie por la espalda,<br>te dan fatigas los programas rosa<br>y padeces los nervios de tus jefes<br>y el rencor de la envidia que no cesa.<br>Te inventan intenciones y romances<br>que jam\u00e1s has so\u00f1ado,<br>pero por ellos te juzgan y te tratan,<br>sin ninguna clemencia,<br>sin ninguna verdad.<br>Eres un ciudadano responsable<br>que paga sus impuestos<br>y vota cuando toca.<br>Funcionas con unos principios inviolables<br>de esos de antes<br>que mamabas de tus padres<br>y de la gente honrada que ve\u00edas a tu alrededor.<br>Pues bien, no te sientas orgulloso:<br>no eres absolutamente nada,<br>ha pasado tu tiempo.<br>Ninguna televisi\u00f3n se va a interesar por ti,<br>nadie va a ir a entrevistarte,<br>ni vas a ser modelo de conducta<br>porque para nadie vas a ser una referencia.<br>Nadie te va a admirar tu honestidad,<br>ni tu competencia ni tu profesionalidad.<br>Hoy ya no eres nada,<br>sencillamente la nada;<br>la ausencia,<br>no existes.<br>Reconoce que te han faltado cojones<br>para ser alguien.<br>Con lo f\u00e1cil que era.\n        <br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">UN HOMBRE NUEVO<\/span><br>&nbsp;empiece cuanto antes la funci\u00f3n,<br>vamos a abrir la caja de los truenos,<br>hay que brincar, romper la melod\u00eda<br>que hace que nuestros versos no sean nuestros.<br><br>Saltemos al vac\u00edo sin la red,<br>dej\u00e9monos de hadas y de cuentos,<br>de una vez aclaremos los asuntos,<br>hay que orear los p\u00e1lidos cerebros.<br><br>Tenemos que inventar un nuevo ox\u00edgeno,<br>otras palabras, otros elementos,<br>una nueva sintaxis seductora<br>que ponga fin al reino de los muertos.<br><br><br>Hay que arrancar el plomo que nos lastra,<br>que nos tiene clavados en el suelo;<br>si queremos crear otro horizonte,<br>\u00bfpor qu\u00e9 ocultar que estamos muy enfermos?<br><br>Tan s\u00f3lo con palabras renovadas<br>podemos elevar el pensamiento.<br>Hay que tirar la carga por la borda<br>para poder hacer un hombre nuevo.<br><br>Hay que llenar de versos su equipaje<br>y de arpegios la punta de sus dedos.<br>Si rompemos aprisa los relojes<br>probablemente a\u00fan nos quede tiempo;<br>hay que apagar la mecha con su sangre<br>antes que estalle todo sin remedio.\n        <br><br><br><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"171\" alt=\"\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/unhombrenuevo.jpg\">\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">UTOP\u00cdA<\/span><br>Que lancen abrazos los ca\u00f1ones,<br>que las pistolas disparen besos,<br>que las marchas se vuelvan canciones,<br>que las ratas se queden sin queso.<br>Que los tristes se partan de risa,<br>que el esclavo deje su cadena,<br>que el rastrero mire donde pisa,<br>que los malos se mueran de pena.<br><br>Qe a los fr\u00edos los hiele su hielo,<br>que los c\u00e9libes hallen pareja,<br>que los falsos no vayan al cielo,<br>que la furia de Dios los proteja.<br>Que gane, por fin, la inteligencia<br>que el mundo se inunde de belleza<br>que los pedantes pierdan la audiencia,<br>que los castos pierdan la pureza.<br><br>Que los que gozan haciendo la guerra,<br>sean condenados a hacer el amor,<br>que los que est\u00e1n de prestado en la Tierra<br>pongan un punto de luz al dolor.<br>Que las fronteras se vuelvan caminos,<br>las aduanas, casetas de feria,<br>que llueva a gusto de los campesinos,<br>que conozca el avaro la miseria.<br>Que los tramposos caigan en sus trampas,<br>que los astutos muerdan el anzuelo,<br>que encontremos un bar mientras escampa,<br>que los que hieren no tengan consuelo.<br>Que los necios no tengan seguidores,<br>que Dios Padre prescinda de su clero,<br>que no dejen de andar los transistores,<br>que no falle ese gol mi delantero.<br><br>Que los famosos se queden sin foto,<br>que los pol\u00edticos pierdan su empleo,<br>que los canallas no ganen ni un voto,<br>que en las pel\u00edculas triunfen los feos.<br>Que gane el Betis y que pierda Lopera,<br>que viva el Atleti, que pierdan los G.I.L.<br>que los asesinos de la carretera<br>se sientan pilotos dentro de un misil.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">YO ME VOY CON VIENTO FRESCO<\/span><br>Yo me voy con viento fresco,<br>con fulgor de madrugada<br>a buscar lo que no fui<br>a encontrar otro ma\u00f1ana.<br>Corro detr\u00e1s de esos soles<br>que est\u00e1n m\u00e1s all\u00e1 del alba<br>en busca de esa verdad<br>que al alcanzarla se escapa.<br><br>Yo me ir\u00e9 detr\u00e1s del Sol<br>donde no alumbra su l\u00e1mpara,<br>donde los vientos azules<br>te besan dulces la cara,<br>donde el tiempo se detiene<br>y s\u00f3lo habitan palabras.<br><br>Palabras a todas horas,<br>voces habitando casas;<br>palabras junto a tu o\u00eddo,<br>palabras en la distancia.<br>Palabras rompiendo el eco<br>de las m\u00faltiples palabras.<br>El reino de la raz\u00f3n,<br>el mundo de la esperanza.<br><img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"224\" alt=\"\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/yomevoyconvientofresco.jpg\"><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">VERANO<\/span><br>Ya soplan fuego las noches<br>en sus suspiros dorados,<br>ya las s\u00e1banas ardientes<br>queman la piel y el verano<br>deja al aire los instintos<br>que el hielo dej\u00f3 olvidados.<br>Ya el perro busca la sombra<br>con aire desesperado<br>y el asfalto se derrite<br>bajo los pies derrotados;<br>se puede cortar el aire<br>con la palma de la mano.<br>La vida se echa a la calle,<br>con los ardorosos labios<br>cuajados de ardientes besos<br>que se posan en las manos,<br>en la piel, en otras bocas<br>llenas de besos alados.<br><br>El zumbido de las moscas<br>llena el agobiante espacio:<br>escu\u00e1lida sinfon\u00eda<br>de acordes desafinados,<br>pentagrama familiar<br>que nos evoca el pasado.<br>Ya las fuentes se han rendido<br>bajo el peso del verano.<br><img loading=\"lazy\" decoding=\"async\" width=\"187\" height=\"209\" alt=\"\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/ymiradestosversos.jpg\"><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        Y MIRAD ESTOS VERSOS<br>Mirad el fondo azul<br>del vuelo de los pardos gorriones<br>nunca podr\u00e1 ser cielo<br>si no lo sue\u00f1a el sue\u00f1o de los hombres (1).<br><br>Mirad esas monta\u00f1as,<br>poderosos y eternos estandartes;<br>no son tales si s\u00f3lo<br>cabalgaran sus cimas los gigantes.<br><br>Mirad aquel camino<br>de flores y de sombras escoltado;<br>nunca ser\u00e1 vereda<br>si el hombre (2) no lo pisa con sus pasos.<br><br>Mirad aquella sima:<br>flecha que apunta al centro de la Tierra;<br>nunca ser\u00e1 refugio<br>si un hombre (2) no traspasa sus fronteras.<br><br>Y mirad esas casas<br>que alumbran con su cal el horizonte;<br>nunca ser\u00e1n ciudad<br>si no las puebla el beso de los hombres (1).<br><br>Mirad bien esas aguas<br>que forman una esquina con el cielo;<br>no ser\u00e1n nunca mar<br>si no las surcan pl\u00e1cidos veleros.<br><br>Mirad bien esa luz<br>que inunda la verdad con su presencia;<br>nunca podr\u00e1 ser sol<br>si una mente no admira su grandeza<br><br>Y mirad estos versos,<br>manojos de po\u00e9ticos vocablos;<br>nunca ser\u00e1n poema<br>si no los canta un pecho enamorado.<br><br>(1) Y de las mujeres, claro.<br>(2) O\/y una mujer, claro<br>.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">VERSOS DE RONDA<\/span><br>Esta duda del cielo, intermitente,<br>este sol que saluda entre las nubes,<br>esta lluvia que baja y luego sube,<br>ese \u00e1rbol que te mira indiferente.<br>Ese rostro dorado de la roca,<br>esa ristra de casas en hilera,<br>ese arbusto trapecista, esa chumbera<br>que nunca endulzar\u00e1 ninguna boca.<br>Esa muralla rota que no guarda,<br>ese molino en ruinas que no muele,<br>esa garganta helada que no duele<br>esa picha del moro tan gallarda.<br>Esa mirada c\u00e1lida y hermosa<br>de ese tajo glorioso y ese puente,<br>ese r\u00edo con color y sin corriente;<br>esa atracci\u00f3n fatal y poderosa.<br>Esas grietas de piedra que son nido<br>de esos s\u00edmbolos negros y volantes;<br>la magia que hace nuevo cada instante,<br>el silencio del tiempo detenido.<br>Esa gasa que vela la monta\u00f1a<br>esa alfombra de verdes imposibles,<br>esa verdad rec\u00f3ndita, intangible,<br>esa forma de ser que la acompa\u00f1a.<br>Estos vientos sin lazos y sin due\u00f1os<br>esta tarde de encaje que agoniza<br>este plomizo abril que simboliza<br>las luces y las sombras de los sue\u00f1os.<br>Son los versos que acaban de nacer<br>hechos con luz de una pureza extrema<br>que componen los hilos del poema<br>que teje Ronda en cada atardecer.<br><br><img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"211\" alt=\"\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/hazmeunsitioentumontura.jpg\"><br><span style=\"font-weight: bold;\">HAZME UN SITIO EN TU MONTURA<br>I<\/span><br>A lomos de Rocinante,<br>atravesando La Mancha<br>prefiere la libertad<br>al abrigo de su estancia.<br>Elige limpiar la tierra<br>de villanos con su lanza,<br>pertrechado de un ensue\u00f1o<br>que cubre m\u00e1s que su adarga.<br>Va dentro de su armadura,<br>de su yelmo y su celada<br>como un extra\u00f1o inquilino<br>de su propia destemplanza;<br>como un ardiente adalid<br>de su ideal y su amada,<br>de su dulce Dulcinea,<br>Aldonza transfigurada.<br>Su caballo y su escudero<br>son su mejor alianza;<br>su arrojo y su bonhom\u00eda<br>forjan sus mejores armas.<br>Lleva en el pecho una estrella<br>una febril llamarada,<br>un destino inexorable<br>que lo empuja y que lo llama.<br>Delante va su quimera,<br>detr\u00e1s lleva a Sancho Panza<br>y en el mundo que abandona<br>deja su hacienda y su casa,<br>el calor de sus amigos,<br>a su sobrina y su ama,<br>a su galgo corredor,<br>sus libros, su cama blanda.<br>Su horizonte no es la l\u00ednea<br>que dibujan las monta\u00f1as<br>ni esas siluetas arb\u00f3reas<br>que vislumbra en lontananza,<br>sino dar fuerza a los d\u00e9biles<br>dar su sangre a los que sangran,<br>comprensi\u00f3n a los que sufren<br>y rigor a los canallas.<br>Se han perdido los papeles,<br>han ganado la batalla<br><br><br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">Y ESE PUENTE<\/span><br>Ronda encima de su Tajo,<br>mirando arriba y abajo<br>desde su gloriosa altura<br>con su piel rugosa y dura,<br>sus arterias luminosas,<br>con su carne revoltosa<br>y ese puente<br>siempre atestado de gente<br>con los pellejos al viento<br>que no para ni un momento<br>con sus c\u00e1maras en ristre<br>y ese espect\u00e1culo triste<br>de los coches en hilera<br>parados y en las aceras<br>otros impidiendo el paso.<br>Y la gente, por si acaso<br>por en medio de los coches.<br>Y esto de d\u00eda y de noche<br>como una gran maldici\u00f3n<br>nacida del coraz\u00f3n<br>de este pueblo centenario,<br>de piedras y campanarios<br>moldeando las conciencias.<br>De culto a las apariencias,<br>de apellidos pintureros<br>sin prestigio y sin dinero<br>pero con mucha cala\u00f1a,<br>herederos de esa Espa\u00f1a<br>pertinaz, eterna y vana<br>siempre obediente a campanas,<br>uniformes y sotanas,<br>recelosa del presente<br>y enemiga del futuro,<br>ese agujerito oscuro<br>que s\u00f3lo trae novedades,<br>donde mueren las verdades<br>que tanto cost\u00f3 forjar<br>y que ahora vemos pasar<br>como pasa la corrient.<br><br><img loading=\"lazy\" decoding=\"async\" width=\"286\" height=\"215\" alt=\"\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/yesepuente.jpg\"><br><br><br>Va cubriendo los caminos<br>con su gloria y con su fama,<br>a los charranes vencida<br>y a los gigantes ganada.<br>No te pares caballero,<br>no abandones tu campa\u00f1a,<br>procura que los tunantes<br>se conformen con las ganas,<br>que hace falta tu presencia,<br>precisamos tus haza\u00f1as.<br>II<br>Porque este p\u00e1ramo absurdo,<br>esta historia chabacana<br>necesita de tus sue\u00f1os,<br>de tu ut\u00f3pica mirada,<br>de tu genial chifladura,<br>de tu valor y tu lanza.<br>Ayer no es posible y hoy<br>es una sustancia vana,<br>una entelequia, una duda,<br>una imposible mara\u00f1a,<br>una monstruosa cordura,<br>una atroz y brutal farsa.<br>Ma\u00f1ana es igual que ayer;<br>ayer es hoy sin ma\u00f1ana.<br>Cada apuesta por la vida<br>es una nueva campa\u00f1a,<br>un pasaje sin regreso,<br>una aventura frustrada.<br>La soledad nos acecha,<br>el desamparo amenaza<br>y la congoja se adue\u00f1a<br>de nuestra pobres sustancias.<br>\u00bfC\u00f3mo no esperar tu envite<br>a tanta desesperanza?<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        Y as\u00ed volvemos al puente<br>con sus tres esbeltos ojos<br>y sus grajos y sus rojos<br>y limpios atardeceres,<br>sus hombres y sus mujeres,<br>sus ni\u00f1os y sus escuelas<br>y ese fr\u00edo que se cuela<br>y te congela hasta el alma<br>y ese \u201cNi\u00f1o de la Palma\u201d<br>y Antonio Ord\u00f3\u00f1ez, toreros,<br>hijos de Pedro Romero<br>y padres del ancestral<br>y puro arte celestial<br>de pintar con la franela<br>lienzos que han hecho de Ronda<br>una tauromaquia honda,<br>una plaza universal.<br>Y del puente a \u201cLa Ciudad\u201d<br>(ese barrio de verdad)<br>en donde duerme la historia,<br>donde sue\u00f1a la memoria<br>y uno se siente m\u00e1s viejo,<br>m\u00e1s cerca, pero m\u00e1s lejos<br>de aquello que ya no es<br>pero sigue siendo, pues<br>se esconde en esos rincones<br>en sus rejas y balcones,<br>sus iglesias y sus casas,<br>en el fr\u00edo que traspasa,<br>en su aire y su color<br>donde el inocente amor<br>sigue mirando al poniente<br>y otra vez vamos al puente,<br>met\u00e1fora de la vida,<br>lugar de entrada y salida,<br>de paso de caminantes,<br>de caballeros andantes<br>y damas enamoradas,<br>de pasiones encontradas,<br>conjunci\u00f3n copulativa:<br>c\u00f3pula de piedra viva<br>que concilia los contrarios<br>y que admite en s\u00ed los varios<br>y curiosos personajes<br>que conforman su paisaje;<br>con sus sue\u00f1os y quimeras<br>pululan por sus aceras<br>llenas de gentes sencillas<br>y de sus medias costillas,<br>esos que tiran del carro,<br>que no le temen al barro<br>y que pagan su sustento<br>a los que viven del cuento;<br>de especuladores varios,<br>de salidos del armario<br>y de mucho cara dura<br>y de comida basura;<br>de alima\u00f1as peligrosas<br>y amantes de salsa rosa;<br>de pol\u00edticos ineptos,<br>sin ideas y sin conceptos<br>con una sola obsesi\u00f3n:<br>pertrecharse en el sill\u00f3n;<br>de j\u00f3venes cavilando<br>y de maestros so\u00f1ando<br>que lleguen las vacaciones,<br>de verdades, de ficciones,<br>de padres acongojados,<br>ocupados, preocupados,<br>rebosantes de cari\u00f1o<br>de no d\u00e1rselo a los ni\u00f1os,<br>de tiendas donde no hay nada,<br>tenderos con empanada,<br>de peregrinos sin fe,<br>de curas sin testimonio,<br>\u00bfd\u00f3nde est\u00e1 usted, don Antonio?<br>\u00bfPor qu\u00e9 no vuelve otra vez?<br>De poetas como yo,<br>de locutores sin voz,<br>de abogados relamidos,<br>de m\u00e9dicospresumidos<br>y ediles incompetentes<br>y otra vez de nuevo el puente<br>como punto de inflexi\u00f3n<br>y acabo esta reflexi\u00f3n<br>no vaya a ser que la gente<br>diga que soy un mam\u00f3n,<br>un est\u00fapido inconsciente<br>aunque tenga la raz\u00f3n<br>que ya sabemos que as\u00ed<br>suele reaccionar la gente.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        los buscadores de votos,<br>los cazadores de almas<br>que ignoran que la verdad<br>es una cosa sagrada,<br>que no pertenece a nadie<br>y que a todos nos alcanza.<br><br>\u00bfC\u00f3mo no querer, se\u00f1or,<br>acabar con tanta trampa?<br>\u00bfC\u00f3mo no querer cambiar<br>lo que tanto nos espanta?<br>Donde los ni\u00f1os estorban,<br>donde los viejos se aparcan<br>hace falta que tu furia<br>ponga en orden tanto drama.<br>En un orbe que prefiere<br>la tosquedad a la gracia,<br>las tarjetas a los besos,<br>el pl\u00e1stico a las manzanas,<br>los cheque a las caricias,<br>los gritos a las palabras,<br>hace falta un Don Quijote<br>dispuesto a dar la batalla,<br>que entierre en la pobre tierra<br>tan s\u00f3rdidas acechanzas.<br><span style=\"font-weight: bold;\">III<\/span><br>Ll\u00e9vame, hidalgo, contigo,<br>ay\u00fadame en la mudanza<br>que mis huesos necesitan<br>y que este mundo reclama.<br>Hazme un sitio en tu montura,<br>dame tu brazo y tu espada<br>y pr\u00e9stame tu locura,<br>bendita locura humana.<br>Si t\u00fa me dejas tu pu\u00f1o<br>y yo te presto mis ganas,<br>no crecer\u00e1 en el planeta<br>ni un mal gramo de ciza\u00f1a.<br>Y si me prestas tu amor<br>y yo te dejo mi rabia,<br>ni un esp\u00edritu andar\u00e1<br>sin una aventura m\u00e1gica.<br>No me dejes tu amargura<br>ni tu da\u00f1o ni tu drama,<br>tus lacerantes heridas<br>tus ilusiones ajadas,<br>que yo ya tengo de esas<br>una n\u00f3mina bien larga.<br>P\u00e1same tu sed de lucha,<br>tu hambre de bien y tu garra,<br>tus deslumbrantes razones<br>y tu bizarr\u00eda brava.<br><br><br><img loading=\"lazy\" decoding=\"async\" width=\"194\" height=\"259\" alt=\"\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/quijote-3.jpg\"><br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        Que este enfermo necesita<br>que t\u00fa le laves la cara,<br>que le alientes en la lid<br>y que le cures las llagas.<br>Que le protejas el pecho,<br>que le guardes las espaldas,<br>que lo alivies del marasmo<br>que por doquier lo quebranta.<br>Pondremos a los valientes<br>por encima de las l\u00e1grimas;<br>daremos a los cobardes<br>un coraz\u00f3n y una causa.<br>Enterraremos en risas<br>a la tristeza prosaica.<br>Para los sabios, disc\u00edpulos,<br>para los buenos, constancia,<br>para los malos, desprecio<br>por donde quiera que vayan.<br>A los \u00eddolos, silencio,<br>a los aburridos, marcha.<br>Para los crueles, justicia,<br>a las v\u00edctimas, venganza;<br>para los pobres, fortuna<br>y ocasi\u00f3n para gastarla.<br><br><span style=\"font-weight: bold;\">IV<\/span><br>Que se preparen los necios,<br>que se acicalen las damas,<br>que tiemblen los despreciables<br>partidarios de la nada;<br>los que escupen su miseria<br>por el vientre de sus balas,<br>los que pre\u00f1an los ca\u00f1ones<br>con su mierda y con sus babas.<br>los que corrompen el sue\u00f1o<br>de las inocentes almas,<br>los que ensucian con su bilis<br>las veredas m\u00e1s holladas.<br>Que tiriten los mediocres,<br>las censuras, las mordazas,<br>el atropello, el abuso<br>la injusticia y las sotanas.<br>Los que duermen a la gente<br>con dulces cuentos de hadas.<br>Los que despiertan la noche<br>y matan la luz del alba.<br>Que escapen los miserables,<br>los mezquinos, hierbas malas<br>que llenan la pobre tierra<br>con sus pestosas entra\u00f1as.<br>Que corran los poderosos<br>y sus podridas comparsas,<br>porque no habr\u00e1 compasi\u00f3n<br>ante sus perfidias b\u00e1rbaras.<br><br>n<img loading=\"lazy\" decoding=\"async\" width=\"210\" height=\"240\" alt=\"\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/quijote2.jpg\">\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        Los tibios y los ingratos,<br>los vacuos y las morrallas,<br>que se pierdan como el viento,<br>que escapen con luna clara,<br>pues va a caerles la noche<br>con su negrura macabra.<br>Que se apresten a volar<br>los verdugos y sus hachas,<br>que busquen un agujero<br>las carro\u00f1as despiadadas,<br>que se metan bajo tierra<br>las terribles alima\u00f1as,<br>porque vamos sin piedad<br>con nuestras justas guada\u00f1as.<br>Que se esfumen las fronteras,<br>los muros, las alambradas,<br>que vamos a abrir senderos<br>pintados con luna blanca.<br>Que se prepare la muerte,<br>que afile sus negras garras<br>que vamos a entrar en fiera,<br>cruel y desigual batalla.<br><br><span style=\"font-weight: bold;\">V<\/span><br>Mas calle, se\u00f1or, no grite,<br>que no nos deslumbre el alba,<br>so\u00f1emos siempre, so\u00f1emos<br>como nuestra esencia manda.<br>Que no nos despierte Sancho,<br>quede su boca callada:<br>su verdad es la verdad,<br>mas no conviene mirarla;<br>d\u00e9mosles mentiras dulces<br>a las verdades amargas,<br>que hay mucho entuerto pendiente<br>que desfacer nos reclaman;<br>que hay que mirar adelante<br>aunque nos cubran la cara,<br>que hay que volar muy arriba<br>aunque no tengamos alas.<br>Sembrar nuestro pobre huerto,<br>aunque la tierra sea mala<br>y recoger la cosecha<br>aunque la fruta sea vana.<br>Regar los \u00e1ridos surcos,<br>aunque nos roben el agua.<br>Golpe a golpe, verso a verso<br>como Machado mandaba.<br>Sancho sabe bien que el hombre<br>tiene costumbres muy raras,<br>ilusiones desmedidas,<br>pretensiones muy extra\u00f1as:<br>legar a ninguna parte,<br>querer asir lo que pasa,<br>gemir delante de dioses<br>que no entienden sus plegarias;<br>morir por causas in\u00fatiles,<br>correr detr\u00e1s de fantasmas;<br>pretender que gana siempre<br>sabiendo que nunca gana;<br>luchar contra la raz\u00f3n<br>que invita a guardar la calma,<br>estropear los caminos<br>antes de iniciar la marcha.<br>Caminar sin un destino,<br>retar a la madrugada,<br>alzarse para caer<br>de nuevo en la misma trampa;<br>querer luchar contra el viento<br>invencible que lo arrastra.<br>Apuntar al infinito<br>mientras la tierra lo abraza,<br>trascender sin trascendencia,<br>esperar sin esperanza.\n    <\/div>\n    <\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>EN PIE DE GUERRA Bajar en pdf Comprar en papel En pie de guerra recoge 68 poemas de diversa tem\u00e1tica, pero unidos por el hilo invisible de la comnbatividad, frente a las inercias, las mediocridades, los fantasmas y todo aquello que convierte la vida en un asunto mezquino. En la INTRODUCCI\u00d3N de abajo explico con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_aioseop_title":"","_aioseop_description":"","ngg_post_thumbnail":0,"footnotes":""},"_links":{"self":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/pages\/5362"}],"collection":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/comments?post=5362"}],"version-history":[{"count":0,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/pages\/5362\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/media?parent=5362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}