{"id":5365,"date":"2016-11-21T22:23:49","date_gmt":"2016-11-21T21:23:49","guid":{"rendered":"http:\/\/www.josemariatornay.com\/index.php\/mis-libros\/al-filo-de-la-vida\/"},"modified":"2018-10-05T16:59:40","modified_gmt":"2018-10-05T15:59:40","slug":"al-filo-de-la-vida","status":"publish","type":"page","link":"http:\/\/www.josemariatornay.com\/index.php\/al-filo-de-la-vida\/","title":{"rendered":"Al filo de la vida"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5365\" class=\"elementor elementor-5365 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4d0311 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4d0311\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6dfc891\" data-id=\"6dfc891\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8bc1b12 elementor-widget elementor-widget-heading\" data-id=\"8bc1b12\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-large\">AL FILO DE LA VIDA<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2386373 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2386373\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d52891\" data-id=\"1d52891\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffd5467 elementor-widget elementor-widget-heading\" data-id=\"ffd5467\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2018\/10\/Al-filo-de-la-vida.pdf\">Bajar en pdf<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9b1ab5e\" data-id=\"9b1ab5e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-016e364 elementor-widget elementor-widget-heading\" data-id=\"016e364\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.lulu.com\/shop\/jos%C3%A9-mar%C3%ADa-tornay-ruiz\/al-filo-de-la-vida\/paperback\/product-23037161.html\">Comprar en papel<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5641 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5641\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f25\" data-id=\"6f25\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a16 elementor-widget elementor-widget-text-editor\" data-id=\"5a16\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 25%\" >\n        <p style=\"text-align: center;\"><img decoding=\"async\" width=\"149\" height=\"99\" alt=\"\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/portadaalfilodelavida.jpg\"><br><span style=\"font-weight: bold; font-size: 14px;\">Al filo de la vida<\/span><\/p>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 75%\" >\n        <p>A partir de hoy, 7 de marzo de 2013, colocar\u00e9 a diario un poema, hecho ex profeso para este espacio y compuesto al comp\u00e1s de cada d\u00eda, sobre la marcha, sin correcciones ni acicalamiento posterior, tal como vayan saliendo. Voy a intentar que, al menos durante un mes, aparezca uno nuevo en cada amanecer. Un reto diario. Un compromiso cotidiano. Ser\u00e1n poemas acomodados a este espacio. Por obligaci\u00f3n. Ni m\u00e1s largos ni m\u00e1s cortos. Apropiados a este rinc\u00f3n. En 12 versos.&nbsp;<br>El rinc\u00f3n hace referencia al &nbsp;espacio que le hab\u00eda asignado en la portada de la p\u00e1gina web. Est\u00e1n en el orden que va del v\u00e1s reciente al m\u00e1s antiguo, aunque uno y otra no hay m\u00e1s que tres meses.<\/p>\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout-br layout-item-0\">\n<\/div><div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">SE ACAB\u00d3 ESTA HISTORIA<\/span> (16(06\/2013)<br>Aqu\u00ed se acaba esta historia<br>de versos entretejidos<br>al socaire de la vida,<br>al hilo de lo vivido.<br><br>Han sido 100 golondrinas<br>condenadas a este vuelo<br>cibern\u00e9tico y febril,<br>ce\u00f1idas en doce versos.<br><br>Aqu\u00ed se acaban, mas sigue<br>girando inquieta la noria,<br>que no conoce descansos,<br>ni tiene orden ni l\u00f3gica.\n    <\/div><div class=\"art-layout-cell layout-item-1\" style=\"width: 34%\" >\n        <p style=\"margin-right: 10px;\">Pues s\u00ed, se acab\u00f3. Se acab\u00f3 lo que empez\u00f3 el d\u00eda 7 de marzo. Han sido 101 d\u00edas seguidos, en los que puntualmente han ido acudiendo a esta cita estos 101 lamentos compungidos ante un mundo cada vez m\u00e1s adulterado, m\u00e1s injusto, m\u00e1s lamentable y menos humano, menos habitable, menos delicado.Pero este proyecto de AL FILO DE LA VIDA se ha terminado. Lo hace cerrando un poemario que incluye 101 desahogos. Volver\u00e1n, tal vez, otro nombre, para seguir urgando en las heridas de un mundo que se desangra y de una vida que se ha vuelto an\u00e9mica y descolorida.<br><\/p><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">\n         SUBE, BAJA<\/span> (14\/06\/2013)<br>Sube Dios, baja el hombre,<br>suben los precios, bajan los salarios,<br>baja la ardiente piel<br>suben los pl\u00e1sticos,<br>sube la estolidez,<br>bajan los sabios.<br><br>Sube la soledad que no perdona,<br>bajan los buenos rollos necesarios<br>y sube lo vulgar<br>y cae los m\u00e1gico.<br>Que alguien pare este tren,<br>que yo me bajo.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout-br layout-item-0\">\n<\/div><div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">SOLO EXISTE EL PRESENTE<\/span> (15\/06\/2013)<br><br>S\u00f3lo existe el presente,<br>un instante que vuela<br>hacia ninguna parte,<br>un cicl\u00f3n que no espera,<br>que no tiene cuidado,<br>que arrasa lo que encuentra.<br><br>Momentos en la tarde<br>febril de la conciencia;<br>engranaje que escapa,<br>sin control, de la tierra,<br>desahuciada aventura<br>que no encuentra la meta.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">TIENE EL OLIVO<\/span> (12\/06\/2013)<br>Tiene el olivo en su entra\u00f1a<br>aromas verdes de luna,<br>de humedades so\u00f1olientas<br>y soledades oscuras.<br><br>Y en sus sue\u00f1os de \u00e1rbol,<br>sue\u00f1a mar y sue\u00f1a espuma,<br>sue\u00f1a lluvias imposibles<br>desde su alma desnuda.<br><br>Tiene tantas cicatrices<br>su hermosa piel de aceituna,<br>que su pecho es un crisol<br>de soledades profundas.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">POSIBLE<\/span> (13\/06\/2013)<br>\u00bfEs posible que lloren los que hoy r\u00eden,<br>que r\u00edan hasta llorar los desahuciados?<br>\u00bfQu\u00e9 vuelvan los forzados emigrantes?<br>\u00bfQu\u00e9 se vayan los bancos al carajo?<br><br>Aunque pudiera ser, tal vez, qui\u00e9n sabe,<br>es m\u00e1s posible esto, sin embargo:<br>que acaben con el pueblo los ministros<br>que el presente camine hacia el pasado.<br><br>que los cobardes sigan en sus puestos,<br>los valientes terminen en el paro,<br>que los ricos aumenten sus riquezas<br>que el pueblo lo consienta, resigndo.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">EL INFIERNO<\/span> (10\/06\/2013)<br>Ha ca\u00eddo el infierno<br>sobre el monte encinado<br>y una blanca penumbra<br>se adue\u00f1a del espacio.<br>El verde de la sierra<br>se perdi\u00f3 por encanto<br>y un cielo de nostalgia<br>se mete entre los labios.<br>El infierno devora<br>el alma de los p\u00e1jaros<br>y una sed de justicia<br>se divisa en su canto.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">ADI\u00d3S<\/span> (11\/06\/2013)<br>Se march\u00f3 levemente,<br>sin llamar la atenci\u00f3n, sin estridencias,<br>sin nada que perder,<br>sin nostalgia dej\u00f3 detr\u00e1s la puerta,<br>con todo lo que tuvo ya perdido,<br>sin despedirse de ella.<br>\u00bfDe ella? Para qu\u00e9<br>si ya ten\u00eda muy lejos la cabeza.<br>Se march\u00f3 sin llorar,<br>porque no soport\u00f3 la indiferencia<br>y no quedaban l\u00e1grimas,<br>ni una sola perdida entre la niebla.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">TIENE EL OLIVO<\/span> (08\/06\/2013)<br>Tiene el olivo en su entra\u00f1a<br>aromas verdes de luna,<br>de humedades so\u00f1olientas<br>y soledades oscuras.<br><br>Y en sus sue\u00f1os de \u00e1rbol,<br>sue\u00f1a mar y sue\u00f1a espuma,<br>sue\u00f1a lluvias imposibles<br>desde su alma desnuda.<br><br>Tiene tantas cicatrices<br>su hermosa piel de aceituna,<br>que su pecho es un crisol<br>de soledades profundas.<span style=\"font-weight: bold;\"><br><\/span>\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">EL PIRATA<\/span> (09\/06\/2013)<br>Esa pierna de metal<br>es la flor de sus despojos<br>y tras su parche en el ojo<br>hay un alma de cristal<br><br>y en sus sue\u00f1os de pirata<br>hay una hermosa doncella<br>con ojos verdes de gata<br>y una perpetua querella<br><br>con los hijos de Simbad,<br>esos sicarios de oro,<br>cazadores del tesoro<br>que ofrece la libertad.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">VENGO<\/span> (06\/06\/2013)<br>Vengo del cielo abierto<br>y de la brisa que ama,<br>vengo del sol sin sombra,<br>de la lluvia que empapa.<br>Acepto las verdades<br>sin miedo ni esperanza.<br><br>Sigo en aquel camino,<br>mi sangre me reclama.<br>Tengo hambre de sue\u00f1os,<br>el fuego me acompa\u00f1a,<br>el hambre me estimula,<br>la sed conmigo avanza.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">OLAS<\/span> (07\/06\/2013)<br>Tejen tenues las olas<br>con sus lenguas de espuma<br>infinitos bosquejos<br>en la arena desnuda.<br><br>Labran versos sutiles<br>a la luz de la luna<br>con salados acordes<br>manchados de amargura.<br><br>En la orilla desierta<br>la mirada profunda<br>se hace eco brillante<br>de la luz absoluta.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">UN HOMBRE DE PROVECHO<\/span> (04\/06\/2013)<br><br>Ayer so\u00f1aba versos imposibles,<br>pero hoy firma expedientes de despido,<br>la vida suele ser imprevisible<br>y nada queda a salvo del olvido.<br><br>Ayer cortaba flores olorosas,<br>con pasi\u00f3n de doncel enamorado<br>y hoy usa las espinas de las rosas<br>para matar bien muerto su pasado.<br><br>Ayer brotaban besos de su boca<br>y canciones fogosas de su pecho;<br>hoy torna en oro todo lo que toca,<br>convertido en un hombre de provecho.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">DECADENCIA<\/span> (05\/06\/2013)<br>El Sol baila su danza<br>de pavoroso fuego,<br>delicado y soberbio<br>patr\u00f3n del universo.<br><br>Y al son de su cadencia<br>el Sol lanza sus besos<br>a las almas que esperan<br>dentro de su esqueleto.<br><br>El Sol se est\u00e1 apagando,<br>desalentado, incierto,<br>borrado por las nubes,<br>camino del invierno.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">SUE\u00d1OS<\/span> (02\/06\/2013)<br>\u00bfQu\u00e9 tal una sorpresa?<br>\u00bfTal vez otras miradas?<br>\u00bfQuiz\u00e1s otros caminos?<br>\u00bfMejor nuevas palabras?<br>Algo que rompa el hielo<br>que seca las entra\u00f1as.<br><br>Un poquito, tal vez,<br>de cari\u00f1o sin trampa,<br>un algo de locura,<br>que oscurezca las canas.<br>Una ramita verde<br>en el \u00e1rbol del alma.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">P\u00c9RDIDAS<\/span> (03\/06\/2013)<br>Ese gui\u00f1o del sol entre las nubes,<br>deslumbra e hipnotiza la mirada,<br>igual que la verdad que se vislumbra<br>entre la escoria gris de la ignorancia.<br><br>Aquella llamarada que abre el cielo<br>es una bocanada de nostalgia<br>de un tiempo claro y limpio, arrinconado<br>en un fr\u00edo rinc\u00f3n de la esperanza.<br><br>Una imagen fugaz de lo que fue,<br>de lo que se escap\u00f3 por la ventana,<br>de aquello que dejamos escapar,<br>de aquello que se pierde en lontananza.\n        <br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">SILENCIO<\/span> (31\/05\/2013)<br>Tengo que alzar la voz,<br>callar no puedo;<br>no es posible callar<br>si late el pecho<br>cuando los alacranes<br>piden silencio.<br><br>Tengo que alzar la voz,<br>lanzarla al viento.<br>El d\u00eda que mi voz<br>se quede dentro,<br>ser\u00e1 que ya no estoy,<br>estar\u00e9 muerto.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">\n         SIN PIEDAD<\/span> (01\/06\/2013)<br>Con los buitres, los sapos y los cerdos,<br>los que juegan con la fe de los dem\u00e1s<br>los que roban el pan de nuestros hijos,<br>no hay que tener ni un gramo de piedad.<br><br>Esto no es una rima de combate,<br>es algo m\u00e1s rabioso, mucho m\u00e1s:<br>es la sed del que est\u00e1 hasta los cojones<br>de tanta desverg\u00fcenza sideral.<br><br>Es el grito que clama en el desierto,<br>es la furia que brota de la mar.<br>Con los buitres, los sapos y los cerdos<br>no hay que tener ni un gramo de piedad.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">LA EMBARAZADA<\/span> (28\/05\/2013)<br>El tierno bamboleo<br>de su cuerpo deshoja<br>mil nombres imposibles,<br>infinitas historias,<br>tejidas en los sue\u00f1os,<br>de noches silenciosas.<br><br>La vida se hace imagen<br>en su cara de rosa<br>y en su pecho se erige<br>la savia milagrosa<br>de otro mundo mejor<br>que su vientre atesora.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">NO TODO EST\u00c1 PERDIDO<\/span> (30\/05\/2013)<br>Nadando en una f\u00e9tida cloaca,<br>sumergido en el lodo de la historia,<br>sin nada que ganar en la partida,<br>confinado en el mundo de las cosas,<br>como una cosa m\u00e1s, lejana, tibia,<br>impotente, cansada, triste y sola.<br><br>Desolado paisaje lo comprime,<br>lo atosiga, lo abruma, lo devora<br>y en medio del silencio de su noche<br>descubre la verdad de su derrota.<br>Tan s\u00f3lo una llamita de locura<br>perdura en el conf\u00edn de su memoria.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">VERDE<\/span> (26\/05\/2013)<br>Verde la luz, verde el pino,<br>verde la pura verdad<br>y verde el alma del vino<br>que invita a la libertad.<br><br>negra la negra paciencia<br>que arrastra la soledad<br>y m\u00e1s negra la conciencia<br>negra de la vanidad.<br><br>Verde la alegre ma\u00f1ana<br>y el camino cuando empieza.<br>Negra la negra campana<br>sepulcral de la tristeza.<br><br>\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">OCASIONES PERDIDAS<\/span> (27\/05\/2013)<br>La ocasi\u00f3n que se pierde<br>tiene alma de lunes,<br>las entra\u00f1as de plomo<br>y horizonte de octubre.<br><br>Las batallas perdidas<br>exhalan un perfume,<br>que lo penetra todo,<br>del suelo hasta las cumbres.<br><br>La suerte derramada<br>se escapa por el t\u00fanel<br>amargo de la noche,<br>que todo lo consume.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        &nbsp; &nbsp; &nbsp;<span style=\"font-weight: bold;\">SECRETO<\/span> (24\/05\/2013)<br><br>En el t\u00fanel sagrado<br>de tu noche me pierdo;<br>renazco en las palabras<br>calladas del silencio<br>y me quemo en la llama<br>que brota de tu cuerpo.<br><br>Nada calienta m\u00e1s<br>que tus brazos de fuego<br>y nada es m\u00e1s sabroso<br>que el fruto de tus pechos.<br>En nada hay m\u00e1s misterio<br>que en tu dulce secreto.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">MISTERIO<\/span> (25\/05\/2013)\n        <br>El silencio sonoro<br>del sonido que calla,<br>los guijarros de oro<br>de una imposible playa.<br><br>La luz oscurecida<br>por la sombra del d\u00eda,<br>la flor de la alegr\u00eda<br>por el dolor partida.<br><br>La vida es un misterio,<br>una absurda aventura,<br>una ambici\u00f3n oscura<br>con sed de cementerio.<br><br>\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">ODIO<\/span> (22\/05\/2013)<br>\u00bfHe de pedir perd\u00f3n porque me encuentre<br>lejos de m\u00ed, presa del desaliento?<br>El odio que me puebla<br>no ha nacido de m\u00ed, no es de mi pecho;<br>lo han instalado ah\u00ed<br>los buitres y los cuervos,<br>los que todo lo pudren y envenenan,<br>los que siembran de hiel el firmamento,<br>los padres del dolor,<br>verdugos de mis sue\u00f1os,<br>los hijos del demonio,<br>los amos del infierno.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">NOVEDAD<\/span> (19\/05\/2013)<br>Ya los \u00e1lamos del r\u00edo<br>lucen terno adolescente,<br>impasibles ante el fr\u00edo<br>que a\u00fan refleja la corriente.<br><br>Aromas de la ribera<br>tejen pasmosa alegr\u00eda<br>con hilos de primavera<br>en las costuras del d\u00eda.<br><br>Y la brisa se recrea<br>en las cornisas del cielo<br>y el campo entero verdea<br>vestido de terciopelo.<br>.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">POR LA CALLE<\/span> (20\/05\/2013)<br>Por la calle andan los sabios,<br>los necios, los ignorantes,<br>los ricos y los ladrones,<br>soldados y generales,<br>los pobres con su pobreza,<br>los zafios con sus maldades.<br><br>Andan todos confundidos<br>y se cruzan por la calle,<br>ignorantes cada uno<br>de lo que cada cual vale.<br>Absortos en sus minucias,<br>sin querer saber de nadie.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">QU\u00c9 TAL<\/span> (21\/05\/2013)<br><br>\u00bfQu\u00e9 tal le van las cosas?<br>\u00bfC\u00f3mo pas\u00f3 el invierno<br>\u00bfHay alguna esperanza?<br>\u00bfC\u00f3mo marcha lo nuestro?<br>\u00bfQu\u00e9 tal el nuevo jefe,?<br>\u00bfLe han cambiado de puesto?<br>\u00bfC\u00f3mo acab\u00f3 el gerente?<br>\u00bfqu\u00e9 tal el Papa nuevo?<br>\u00bfQu\u00e9 tiempo har\u00e1 el domingo?<br>\u00bfEstar\u00e1 el bar abierto?<br>\u00bfLo quiere blanco o tinto?<br>Lleno, por favor, lleno.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">NO LO S\u00c9<\/span> (18\/05\/2013)<br>\u00bfVolver\u00e1n las oscuras golondrinas?<br>No lo s\u00e9.<br>\u00bfDe tu balc\u00f3n sus nidos a colgar?<br>No lo s\u00e9, no lo s\u00e9.<br>\u00bfVolver\u00e1n las tupidas madreselvas?<br>Puede ser.<br>\u00bfDe tu jard\u00edn las tapias a escalar?<br>Puede ser, puede ser.<br>\u00bfRegresar\u00e1n las risas a mi puerta?<br>\u00bfVolver\u00e1n las caricias a crecer?<br>Si saldr\u00e1 el Sol ma\u00f1ana nuevamente,<br>\u00bfqui\u00e9n lo puede saber?\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">\n         NO ME IMPORTA<\/span> (16\/05\/2013)<br>No me importa que ladren,<br>que m\u00e1s da,<br>ni que muerdan;<br>yo puedo defenderme.<br>Me puedo defender sin atacar;<br>Intentar ser yo mismo<br>ya es bastante.<br>Que me dejen vivir<br>y respirar,<br>(parece poca cosa),<br>ya me vale.<br>Vivir y nada m\u00e1s.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">SANGRE<\/span> (23\/05\/2013)<br>El mundo es una org\u00eda,<br>una org\u00eda de sangre,<br>de sangre y de dolor<br>por todas partes.<br>Una org\u00eda de miedo,<br>una org\u00eda a lo grande.<br><br>El mundo se derrama<br>en cada instante.<br>La sangre derramada<br>produce mares<br>de miedo y de dolor,<br>mares de sangre.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">MI CASA<\/span> (17\/05\/2013)<br>Si alguna vez tengo tiempo<br>me quiero hacer una casa<br>con ladrillos invisibles,<br>sin puertas y sin ventanas.<br><br>Que ninguna autoridad<br>pueda reclamarme nada.<br>La luz ser\u00e1 la del Sol;<br>el aire, el de la ma\u00f1ana.<br><br>Pondr\u00e9 sillas infinitas<br>con una mesa muy larga,<br>para que se siente a ella<br>todo el que venga a mi casa.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">OJOS<\/span> (14\/05\/2013)<br><br>Ojos que pierden,<br>ojos que matan,<br>ojos que envuelven,<br>ojos que abrazan.<br><br>Ojos que enferman,<br>ojos que curan,<br>ojos de piedra,<br>ojos de luna.<br><br>Ojos sedientos,<br>ojos de plomo,<br>ojos sin due\u00f1o,<br>ojos sin ojos.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">VIVEN DENTRO DE M\u00cd<\/span> (15\/05\/2013)<br><br>Viven dentro de m\u00ed<br>en dura coexistencia,<br>dragones y palomas,<br>clarines y trompetas.<br><br>Uno,s muerden rabiosos,<br>otras, vuelan y vuelan;<br>aqu\u00e9llos suenan tenues<br>\u00e9stas rompen fronteras.<br><br>Y todos conviviendo<br>en pervertida guerra<br>civil, incandescente,<br>lamentable, rastrera.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <br><span style=\"font-weight: bold;\">PERDIDO<\/span> (12\/05\/2013)<br><br>Hay un cielo sin dios<br>y un infierno sin \u00e1ngel ca\u00eddo,<br>hay un fuego de dos<br>en un tiempo perdido.<br><br>Un pecho sin pecado<br>y una flor sin misterio,<br>agonizan, sedientos, al lado<br>de los asuntos serios.<br><br>Ausente puedes ver,<br>En su pecho, dormido,<br>un cuerpo sin placer,<br>apuntando al olvido.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">HAY QUE SER<\/span> (13\/05\/2013)<br>Hay que ser una estrofa en un poema,<br>un verso en una estrofa enamorada<br>una sonrisa limpia en la tristeza<br>una fuente de agua fresca y clara.<br><br>Hay que ser el oasis del desierto<br>un rayito de sol en la penumbra,<br>el pr\u00edncipe sublime de los cuentos,<br>la luna blanca de la noche oscura.<br><br>Tengo que ser la miel de la colmena,<br>la duda en la certeza reaccionaria,<br>las flores que jalonan la vereda,<br>la claridad que anuncia la ma\u00f1ana.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">MI AMIGO<\/span> (10\/05\/2013)<br>Mi amigo tiene muy claro<br>que entre el honor y el dinero,<br>aunque le salga muy caro,<br>lo segundo es lo primero.<br><br>Y en su peque\u00f1a verdad<br>hay un mundo tan peque\u00f1o<br>que no cabe un solo sue\u00f1o<br>en su pobre vanidad.<br><br>Y la noria gira y gira<br>en su m\u00e1gica ciudad,<br>mas su verdad es mentira<br>y su luz, oscuridad.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <br>EL VERSO DE CRISTAL (11\/05\/2013)<br>El verso de cristal<br>que no se rompe,<br>es fr\u00e1gil como un Sol<br>de medianoche.<br><br>El verso de cristal<br>es transparente,<br>pero al llegar al mundo<br>\u00a1ay!, se oscurece.<br><br>El verso nace libre<br>y se encadena<br>al alma que lo atrapa<br>y que lo sue\u00f1a.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        IMAGEN (08\/05\/2013)<br>Las encinas salpican la ladera<br>y sus manchas oscuras se derraman<br>cual ej\u00e9rcito inm\u00f3vil con sus fuerzas,<br>desplegado al albur de la mirada.<br><br>La serpentina fiel del horizonte<br>dibuja el resplandor de la distancia<br>y el astro cenital ba\u00f1a con bronce<br>la tierra que lo acoge enamorada.<br><br>Una casa se atisba brevemente,<br>-tal vez una ilusi\u00f3n- entre las ramas<br>y aventuro a un pastor en sus deberes:<br>su familia, sus sue\u00f1os y sus cabras.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">LA MUJER DE HIEL<\/span>O( 09\/05\/2013)<br>La mujer de hielo<br>me mira y me atrapa,<br>me pierde, me pierdo,<br>me deja sin armas.<br><br>La mujer de hielo<br>me tiende una trampa:<br>me mira y sin verme<br>con todos me enga\u00f1a.<br><br>La mujer de hielo<br>no atiende a mis l\u00e1grimas<br>y como una diosa<br>me vuelve la espalda.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <br><span style=\"font-weight: bold;\">EL ESPEJO<\/span> (06705\/2013)<br>El espejo refleja<br>la verdad que se oculta,<br>la verdad que m\u00e1s duele,<br>descarnada, desnuda.<br><br>El espejo es un pozo<br>y en su fondo la luna<br>hace gui\u00f1os traviesos<br>desde su noche oscura.<br><br>El espejo transforma<br>la mirada en pregunta<br>y su respuesta esconde<br>la verdad m\u00e1s profunda.<br><br>\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">\n         GANAR Y PERDER<\/span> (07\/05\/2013)<br>Ya no me bastan los sue\u00f1os,<br>necesito realidades;<br>las ilusiones se acaban<br>si solo se palpa el aire.<br><br>Hay que jugar y vencer<br>de vez en cuando, es la clave;<br>no acostumbrarse a ganar:<br>esa es la segunda parte.<br><br>Y perder, si hay que perder<br>no debiera hundir a nadie.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">\n         MALOS TIEMPOS<\/span> (04\/05\/2013)<br>En este tiempo ajeno a la cordura<br>pasan cosas, pero no pasa nada,<br>te tiran de los huevos y t\u00fa aplaudes,<br>te roban lo que es tuyo y t\u00fa te callas.<br><br>En esta c\u00e1rcel l\u00fagubre y sombr\u00eda,<br>apenas se distingue la ma\u00f1ana,<br>los buitres van vestidos de palomas,<br>los cisnes, sin su lago, ya no danzan.<br><br>En esta pena negra ya no hay sitio<br>para cantos de vida y esperanza<br>y en su mierda tan solo ya respiran<br>los ricos, los banqueros: los que mandan.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">\n         DUDAS<\/span> (05\/05\/2013)<br>Cuando media el recelo,<br>las palabras son torpes,<br>las razones no bastan,<br>la conexi\u00f3n se rompe.<br><br>Se interrumpe la historia<br>y se apagan los soles;<br>se corona el silencio,<br>se hace sitio el reproche.<br><br>Las palabras se vuelven<br>agudos aguijones<br>y el mundo se transforma<br>en un lugar sin nombre.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">\n         SORPRESA<\/span> (02\/05\/2013)<br>Como acab\u00f3 muy pronto<br>decidi\u00f3 darle a ella una sorpresa<br>y regres\u00f3 a su casa,<br>con prisas y ansiedades verbeneras,<br>demasiado temprano,<br>un par de horas antes de la cena.<br><br>Contento como un ni\u00f1o,<br>con juvenil anhelo abri\u00f3 la puerta,<br>presagiando pasiones,<br>feliz por sorprenderla;<br>ignorando que iba a recibir<br>la m\u00e1s cruel y corn\u00fapeta sorpresa.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">INDIFERENCIA<\/span> (03\/05\/2013)<br><br>Se cruzan, nos cruzamos por la calle,<br>m\u00f3nadas invisibles,<br>oscuros, olvidados.<br>En herm\u00e9tica isla<br>y dentro de una piel de rudo m\u00e1rmol<br>se esconde una conciencia pervertida<br>una existencia inocua,<br>una pasi\u00f3n de pl\u00e1stico.<br>Las miradas no miran,<br>las palabras no dicen,<br>los besos son mentiras sin destino<br>robadas a los labios.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <br><span style=\"font-weight: bold;\">VERSO<\/span> (30\/04\/2013)<br>Hay un verso que nunca aparece,<br>es esquivo, liviano, imposible<br>de atrapar cuando est\u00e1 tan a mano<br>que cogerlo parece muy simple.<br>\u00a1Es tan fr\u00e1gil, sutil y elevado!<br>Pero es orgulloso y resiste.<br>En su esencia contiene su encanto:<br>no lo puedes coger porque es libre.<br>Y presume de ser soberano<br>y ante nada ni nadie se rinde.<br>Ese verso que nunca aparece<br>es el verso sagrado, sublime.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">LA NIEVE DE MAYO<\/span> (01\/05\/2013)<br>La nieve de mayo<br>sorprende a la sierra<br>y asombra a los p\u00e1jaros.<br>La nieve de mayo<br>deja en la ladera<br>n\u00edveos bordados.<br>Con su manto blanco,<br>visita la sierra<br>la nieve de mayo.<br>La nieve de mayo<br>provoca temblores<br>en la piel del campo.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">IMPOSIBLE<\/span> (28\/04\/2013)<br>Que caiga la tostada boca arriba,<br>que coja el m\u00f3vil cuando yo la llamo,<br>que aparezcan las llaves cuando hay prisa<br>que d\u00e9 el reloj las tres si son las cuatro.<br><br>Que no hagan falta firmas ni papeles,<br>que Dios responda cuando es convocado,<br>que el ministro resuelva los problemas,<br>que los tontos mejoren con los a\u00f1os.<br><br>Imposible es tambi\u00e9n que la raz\u00f3n<br>disuelva sortilegios y milagros,<br>que los necios no sean jilipoyas,<br>que los sabios no sean despistados.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">EF\u00cdMERO<\/span> (29\/04\/2013)<br>La vida es una breve<br>interrupci\u00f3n del sue\u00f1o,<br>perpetuo de los \u00e1tomos,<br>infinito del tiempo.<br><br>La vida es un fugaz<br>desorden de lo eterno,<br>un chispazo que dura<br>apenas un momento.<br><br>Un rel\u00e1mpago azul<br>en un cielo sin cielo;<br>un ma\u00f1ana imposible<br>en un presente muerto.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">AZULES<\/span> (26\/04\/2013)<br>Las ni\u00f1as se divierten<br>con sus risas azules,<br>y sus manos dibujan<br>temblando un coraz\u00f3n.<br><br>Los ni\u00f1os se entretienen<br>con princesas azules,<br>que trenzan con sus torpes<br>dibujos de ilusi\u00f3n.<br><br>Y mujeres y hombres<br>trazan mundos azules<br>en desiertos de asfalto<br>y luces de ne\u00f3n.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">LLANTO 3<\/span> (27\/04\/2013)<br>Llora la piedra<br>su condici\u00f3n amarga<br>de cuerpo sin destino ni horizonte<br>de objeto sin mirada.<br><br>Llora el Sol su opresi\u00f3n<br>de \u00f3rbita sin pausa,<br>de coraz\u00f3n in\u00fatil,<br>de soberbia potencia encadenada.<br><br>Llora el alma su tr\u00e1gico destino<br>de perdida esperanza,<br>de tr\u00e9mula conciencia<br>sin ayer, sin ma\u00f1ana.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <br><span style=\"font-weight: bold;\">LA CULPA<\/span> (24\/04\/2013)<br>Una cruz que se arrastra,<br>un pu\u00f1al que te mata despacio,<br>una flor con aroma de hierro,<br>un amor olvidado.<br><br>Una espina de fuego<br>que se prende en los labios,<br>una brutal cornada que enciende<br>las bengalas del p\u00e1nico.<br><br>Con crudeza de sa\u00f1a infinita<br>se encadena a tus brazos,<br>te cerca y te mantiene<br>eternamente crucificado.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">DESNUDO<\/span> (25\/04\/2013)<br>Desierto ante los hombres,<br>desnudo ante las cosas,<br>peque\u00f1o ante el paisaje,<br>perdido ante la historia.<br><br>Vencido por el miedo,<br>herido por las horas,<br>rendido por los dioses,<br>comido por las sombras.<br><br>Deshecho por el peso<br>brutal de la memoria,<br>en su centro tocado,<br>hundido en la derrota.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">HUELLAS<\/span> (22\/04\/2013)<br>Vamos dejando huellas<br>y trozos de metralla,<br>que usamos en la guerra<br>febril de nuestra causa.<br>Pedazos en la acera<br>de la vida que pasa.<br>Sombras que van quedando<br>perdidas, olvidadas.<br>Pedazos amputados<br>y jirones del alma.<br>El mundo que era ayer<br>no lo ser\u00e9 ma\u00f1ana.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <br><span style=\"font-weight: bold;\">ESE DIOS MUNDANO<\/span> (23\/04\/2013)<br>Sufre la Tierra la furia del cielo,<br>de ese cielo mundano,<br>de ese Dios vengativo,<br>a su pueblo enfrentado.<br><br>La Biblia responde<br>con fren\u00e9ticos salmos,<br>plenos de fieros dicterios rabiosos,<br>de los ultrajes airados,<br>que la furia divina<br>desenfunda a su paso.<br>El Dios de los cielos,<br>ese Dios mundano.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">VINO<\/span> (20\/04\/2013)<br>No hay nada que repare<br>como un trago de vino,<br>ni nada que te asocie<br>mejor a los amigos.<br>Un fino de Jerez<br>embriaga los sentidos.<br><br>La alegr\u00eda aparece<br>con un blanco o un tinto;<br>un manzanilla es fuego;<br>un dulce, n\u00e9ctar vivo;<br>un oloroso es sangre<br>del estanque divino.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">CLASES DE ORACIONES<\/span> (21\/04\/2013)<br>Oraci\u00f3n simple:<br>la que va directamente al Hacedor.<br>Compuesta:<br>la que usa intermediarios<br>entre los hombres y Dios.<br>Oraci\u00f3n activa:<br>brota del coraz\u00f3n.<br>Pasiva: rutinaria y sin amor.<br>Oraci\u00f3n Personal:<br>transida flor de pasi\u00f3n.<br>Impersonal:<br>lo que diga el monse\u00f1or.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <br><span style=\"font-weight: bold;\">OLVIDO 3<\/span> (18\/04\/2013)<br>No se puede olvidar, es indecente,<br>olvidar es rendirse al desaliento;<br>tanto dolor exige una memoria<br>que se inflame rabiosa en el recuerdo.<br><br>La negra y pavorosa maquinaria,<br>que devora a sus hijos sin remedio<br>reclama una presencia inquebrantable<br>en el alma invencible de los tiempos.<br><br>El pasado que duele y que lastima,<br>el mal sin desagravio del pret\u00e9rito,<br>hay que tenerlo siempre muy presente:<br>olvidar es burlarse de los muertos.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">EL RELOJ<\/span> (19\/04\/2013)<br>Las saetas del reloj<br>son aguijones que el tiempo<br>utiliza para herir<br>los respetables traseros.<br><br>Flechas que apuntan al alma,<br>deshaciendo su esqueleto;<br>espinas endemoniadas,<br>demonios en movimiento.<br><br>Agujas que van marcando<br>el comp\u00e1s de los momentos,<br>la vida breve que pasa<br>como un fantasma en el viento.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\"><br>OLVIDO<\/span> (16\/04\/2013)<br>He decidido olvidar<br>los agravios, las ofensas<br>y todo lo que uno piensa<br>que es dif\u00edcil perdonar.<br><br>Pero lo quiero intentar<br>aunque sepa que en la vida<br>el que perdona y olvida<br>tiene poco que ganar.<br><br>Pero ya algo he ganado,<br>mucho m\u00e1s que lo perdido:<br>por olvidar he olvidado<br>hasta el mism\u00edsimo olvido.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\"><br>OLVIDO 2<\/span> (17\/04\/2013)<br>Nuevamente olvid\u00e9, sin darme cuenta,<br>se me olvid\u00f3 otra vez sentir desprecio<br>por tanta desverg\u00fcenza consentida,<br>por tanto miserable que anda suelto.<br><br>Y no es justo, ni humano, ni decente,<br>condenar estas cosas al silencio,<br>demasiado dolor para no estar<br>en guerra abierta en medio del desierto.<br><br>Otra vez me olvid\u00e9, sin darme cuenta,<br>se me olvid\u00f3 otra vez sentir desprecio,<br>pero quiero jurar que nunca m\u00e1s<br>me volver\u00e1 a ocurrir, os lo prometo.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\"><br>EL TIEMPO<\/span> (14\/04\/2013)<br>Ma\u00f1ana ya fue ayer,<br>ayer so\u00f1\u00f3 un ma\u00f1ana,<br>hoy ya no puede ser<br>m\u00e1s que una fruta vana.<br><br>Perpetuo amanecer,<br>el tiempo se devana<br>como un atardecer<br>detr\u00e1s de la ventana.<br><br>Eterno renacer<br>del reloj que se afana<br>en mudar el ayer<br>en incierto ma\u00f1ana.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">LLANTO 2<\/span> (15\/04\/2013)<br>Llora el olivo amor,<br>amor y olvido;<br>hay nostalgia de sol<br>en sus ra\u00edces<br>y en su derrota<br>tiembla el destino.<br><br>Llora l\u00e1grimas dulces,<br>la dulce higuera<br>desde el fuego quebrado<br>de sus caderas:<br>dulzura que recoge<br>la amarga tierra.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <br><span style=\"font-weight: bold;\">LA PELOTA<\/span> (12\/04\/2013)<br>La peloto no entiende,<br>tan solo bota.<br>No grita ning\u00fan gol,<br>ni pide la hora.<br>Tan solo vuela y vuela<br>como una sombra.<br><br>La pelota no sabe<br>de trofeos ni copas,<br>de ca\u00f1os y paredes,<br>de entradas peligrosas.<br>La pelota est\u00e1 ausente<br>de triunfos y derrotas.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">LUZ DEL ALBA<\/span> (13\/04\/2013)<br>Ya vuela la luz del alba,<br>alba que alumbra los montes,<br>montes que apuntan al cielo,<br>cielo que cierra la noche.<br>Noche que ciega la tarde,<br>tarde que se fue por donde<br>ya se escap\u00f3 la ma\u00f1ana,<br>ma\u00f1ana del sol m\u00e1s joven.<br>Joven luz que resplandece,<br>resplandece como un cofre,<br>cofre que oculta un tesoro,<br>tesoro de mil colores.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">EL CIELO DE LOS CRISTIANOS<\/span> (10\/4\/20139)<br>No encuentra a sus hermanos<br>quien solo mira al cielo,<br>quien espera un regalo<br>sin regalar primero,<br>quien solo ofrece a Dios<br>palabras y no ejemplos.<br><br>Se equivoca quien busca<br>la gloria sin esfuerzo,<br>confiado en la fe<br>ganada como un premio.<br>El cielo no est\u00e1 arriba,<br>el cielo est\u00e1 en el suelo.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <br><span style=\"font-weight: bold;\">SOLO T\u00da<\/span> (11\/0472013)<br>El cielo es gris<br>si tus ojos no pueden verlo azul<br>y tu mirada<br>dibuja las estrellas<br>all\u00e1 en el firmamento.<br>Sin tus ojos no hay cielo,<br>ni hay estrellas, ni azul, ni firmamento.<br>Sin ti no hay mundo<br>ni nadie que no erija tu mirada,<br>porque el mundo eres t\u00fa<br>y solo t\u00fa<br>puedes crear el mundo.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">\n         IMPARABL<\/span>E (08\/04\/2013)<br>En el vientre apacible<br>de la tarde que muere<br>se ocultan los secretos<br>de la noche que viene.<br><br>La vida se derrama<br>con l\u00f3gica de sierpe<br>y responde a verdades<br>que el azar tambi\u00e9n tiene.<br><br>Y no hay nada que venza<br>su tr\u00e1gica corriente;<br>nada puede pararla,<br>ni siquiera la muerte.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br>&nbsp;<span style=\"font-weight: bold;\">LOCOS<\/span> (09\/04\/20139<br>Viven, dejan vivir,<br>corren, brincan, se r\u00eden de las reglas,<br>se saltan las se\u00f1ales<br>que les piden prudencia.<br>Si les falta la luz,<br>con el sol se consuelan.<br><br>Mientras unos negocian, ellos viven,<br>mientras otros calculan, ellos sue\u00f1an,<br>Gr\u00e1ciles como plumas,<br>transitan las tabernas,<br>mientras otros se aburren<br>entre sus cosas serias.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">LO QUE HAY QUE HACER<\/span> (06\/04\/2013)<br>Hay que poner la historia boca abajo,<br>hay que poner el mundo boca arriba,<br>hacer una lectura diferente<br>de lo que se nos dijo y se nos diga.<br><br>Hay que quitarle el cetro a los que mandan,<br>poner el barco rumbo hacia la vida,<br>hay que enfrentarse al reino de la muerte,<br>poner en evidencia las mentiras.<br><br>Hay que ser y sentir de otra manera,<br>no seguir suplicando de rodillas<br>y mandar a la mierda sin demora<br>tanta trampa, tanta verdad vac\u00eda.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\"><br>VIVIR<\/span> (07\/04\/2013)<br>Nacer, brotar y surgir,<br>germinar y aparecer,<br>progresar, trepar, crecer,<br>desarrollarse y subir.<br><br>Batallar y combatir,<br>luchar, re\u00f1ir, pelear,<br>a veces perder, ganar,<br>casi siempre sucumbir.<br><br>Penar, llorar y sufrir<br>querer, desear, amar,<br>regocijarse y gozar,<br>Deteriorarse y morir.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">VIDA COTIDIANA<\/span> (04\/04\/2913)<br>Salir, entrar, volver,<br>regresar, asomarse a la ventana,<br>correr, volar, sentir<br>el beso seductor de una mirada.<br>Hablar, hablar y hablar<br>sin detenerse a o\u00edr ni una palabra.<br><br>Correr, correr, correr para olvidar<br>el reloj que te atrapa.<br>Refugio del dolor<br>de la angustia del alma.<br>Emplear la rutina para huir<br>del peso de la nada.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">MIENTRAS<\/span> (05\/04\/2013)<br>Mientras pasen las m\u00e1s grandes mentiras<br>por supremas y espl\u00e9ndidas verdades<br>mientras sigan triunfando los mediocres<br>y aplaudidos sean los criminales.<br>Mientras pasen por damas las obscenas<br>y sigan los podridos en la calle<br>y los chorizos pasen por se\u00f1ores<br>y por gente de bien las cospedales,<br>no habr\u00e1 forma de hallar otras veredas<br>ni manera de huir de estos fangales.<br>Las peores mentiras son, sin duda,<br>las que van disfrazadas de verdades.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">METR\u00d3POLIS<\/span> (02\/04\/2013)<br>Esos troncos sin ramas,<br>esas ramas sin flores,<br>\u00a1ay flores sin abejas,<br>y abejas sin colores!<br><br>Ese sol que no alumbra,<br>cegado por la bruma<br>y ese mar que se muere<br>sobre su propia espuma<br><br>Esa masa que grita<br>y, a veces, se impacienta,<br>aparece marchita<br>perdida en la tormenta.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">IMPUTADA<\/span> (03\/04\/2013)<br>La princesa est\u00e1 triste,<br>\u00bfqu\u00e9 tendr\u00e1 la princesa?<br>Ha metido la mano,<br>ha metido la pierna.<br>La princesa no sabe<br>con su cara de piedra,<br>que las cosas de todos<br>no se miran siquiera.<br>La princesa est\u00e1 triste.<br>\u00bfqu\u00e9 tendr\u00e1 la princesa?<br>S\u00e9 bien lo que no tiene:<br>ni un gramo de verg\u00fcenza.<br><span style=\"font-size: 9px;\">Ya s\u00e9 que Cristina no es princesa, pero es que quer\u00eda parafrasear a Rub\u00e9n Dar\u00edo. Adem\u00e1s, qu\u00e9 m\u00e1s da, estos miembros de la nobleza parecen todos iguales<\/span>.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">LA POES\u00cdA<\/span> (31\/03\/2013)<br>En esta guirnalda hermosa<br>el principio es el final<br>y las l\u00e1grimas son sal.<br>Y en su veleidad curiosa<br>cada cosa es otra cosa.<br>\u00a1Oh met\u00e1fora infernal!<br><br>Por sus antojos de diosa,<br>un estanque es un cristal<br>y unos labios son metal.<br>Y en su alma caprichosa,<br>una herida es una rosa<br>y una rosa es un pu\u00f1al.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">LA ELECCI\u00d3N<\/span> (01\/04\/2013)<br>Quien elige renuncia,<br>renuncia a todo menos a una cosa.<br>El que escoge ha perdido<br>en la propia elecci\u00f3n su sed de gloria.<br>Y a lo que renunci\u00f3<br>por aquella elecci\u00f3n liviana y loca<br>ser\u00e1 un recuerdo amargo,<br>siempre lo seguir\u00e1 como una sombra.<br>Nunca m\u00e1s volver\u00e1.<br>Siempre ser\u00e1 un fracaso su victoria.<br>Quien elige renuncia,<br>renuncia a todo, menos a una cosa.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">VIERNES SANTO<\/span> (29\/03\/2013)<br>Viernes Santo, huele a agua,<br>terror de las cofrad\u00edas,<br>el Santo Entierro de Cristo<br>espera ya en la salida.<br>Otra vez la decisi\u00f3n<br>que deja el alma vac\u00eda.<br><br>De nuevo los nazarenos,<br>de vuelta a casa suspiran<br>con resignaci\u00f3n cristiana:<br>\u00a1Otra vez la puta lluvia!<br>Ni siquiera el mismo Dios<br>puede trasformar la vida.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">EL PAPA<\/span> (30\/03\/2013)<br>El Papa se ha cansado<br>del peso de la tiara,<br>de su triple poder,<br>de la curia romana.<br><br>El Papa Benedicto<br>sali\u00f3 por la ventana,<br>siguiendo a la paloma,<br>compa\u00f1era del alma<br><br>El Papa se cans\u00f3,<br>arroj\u00f3 la toalla,<br>en San Pedro resuenan<br>solemnes las campanas.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">GOL<\/span> (27\/03\/2013)<br>La crisis nos asfixia,<br>gol de Messi,<br>los desahucios nos cercan,<br>otro fallo de Ramos,<br>las conquistas sociales al carajo,<br>parad\u00f3n de Casillas,<br>m\u00e1s horas de trabajo, menos sueldo,<br>impresionante tiro de Ronaldo,<br>adi\u00f3s a las pensiones,<br>fuera de juego claro,<br>recortes, m\u00e1s recortes,<br>golazo\u2026 \u00a1qu\u00e9 golazoooooooooo!\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">JUEVES SANTO<\/span> (28\/03\/2013)<br>Jueves Santo por la tarde:<br>huele a incienso en mi balc\u00f3n,<br>suena el himno nacional<br>cuando est\u00e1 saliendo Dios.<br>Las se\u00f1oras se estremecen<br>al o\u00edr a la legi\u00f3n<br>y una saeta alza el vuelo<br>desde un poblado rinc\u00f3n.<br>La lluvia se ha retirado,<br>comienza la procesi\u00f3n.<br>Jueves Santo por la tarde:<br>huele a incienso en mi balc\u00f3n.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <br><span style=\"font-weight: bold;\">EL TORERO<\/span> (25\/03\/2013)<br>El torero se pierde<br>en la tarde de plata<br>y una nube se lleva<br>la ovaci\u00f3n que reclama.<br><br>El torero se marcha,<br>perdida la mirada<br>en el futuro incierto<br>de un tiempo que se acaba.<br><br>El torero se ha ido<br>perdiendo en la distancia;<br>ya no recoge flores,<br>solo abriga nostalgias.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">L\u00cdBIDO<\/span> (26\/03\/2013)<br>Saltan dentro mol\u00e9culas extra\u00f1as,<br>que no entienden de paz,<br>ni de pactos y treguas<br>cuando entran en liza,<br>cuando entran en guerra.<br><br>Es el grito sagrado y vehemente<br>de la vida que llama<br>con fruici\u00f3n a tu puerta.<br><br>De la vida que quiere seguir siendo,<br>eternidad sin tregua,<br>voluntad infinita<br>y camino sin meta.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">SAETA<\/span> (23\/03\/2013)<br>La saeta, ese cantar<br>de romero y primavera,<br>que brota de las aceras<br>como la flor de azahar.<br><br>Saeta, rayo de luz<br>de esta helada Serran\u00eda<br>al Jes\u00fas de la agon\u00eda<br>encadenado a su cruz.<br><br>Suspiro grave y doliente<br>fervorosa tradici\u00f3n,<br>l\u00e1grima del coraz\u00f3n<br>del afligido creyente.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <br><span style=\"font-weight: bold;\">EL POETA<\/span> (24\/03\/2013)<br>El poeta se ha encerrado<br>en su torre de marfil<br>y en su mundo edulcorado<br>teje sus rosas de abril.<br><br>Apartado de las cosas<br>que duelen a los mortales,<br>en los reinos celestiales<br>embaraza mariposas.<br><br>El poeta se ha dormido<br>junto a la orilla del mar,<br>so\u00f1ando reinos perdidos<br>ya no puede despertar.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">FUERA DE JUEGO<\/span> (21\/03\/2013)<br><br>Al borde de un camino,<br>que va a ninguna parte,<br>con el paso cambiado,<br>al cabo de la calle.<br>De espaldas a esa trupe,<br>que sonr\u00ede al que mande<br>y enfrente de los necios,<br>que envenenan el aire.<br>Andando a contrapi\u00e9<br>igual que un kamikaze,<br>marchando hacia el olvido,<br>hacia ninguna parte.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">LLUVIA 2<\/span>(22\/03\/2013)<br>Llueve,<br>llueve con rabia,<br>llueve con voluntad de inundaci\u00f3n,<br>llueve y llueve sin pausa.<br><br>El cielo encapotado<br>se ha puesto un traje de agua<br>y con larga fruici\u00f3n<br>sobre la tierra f\u00e9rtil se derrama.<br><br>Llueve,<br>llueve sin pausa,<br>llueve sobre mi coraz\u00f3n,<br>llueve y llueve sin pausa.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <br><span style=\"font-weight: bold;\">ENGA\u00d1ADOS<\/span> (19\/03\/2013)<br>No es verdad que seamos los culpables,<br>no es verdad, \u00a1no es verdad!<br>No es verdad que no haya otras veredas,<br>no es verdad.<br><br>No es verdad que seamos responsables<br>de lo que est\u00e1 pasando, \u00a1no es verdad!<br>que digan que no hay otros caminos,<br>\u00a1no es verdad!<br><br>No es verdad, \u00a1os lo juro!<br>Por mucho que lo digan, no es verdad.<br>Que dispare el conejo a la escopeta,<br>no es verdad, \u00a1qu\u00e9 cabrones! No es verdad.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">PRIMAVERA<\/span> (20\/03\/2013)<br><br>Hoy empieza a brotar todo de nuevo,<br>nuevos reto\u00f1os, nuevas ilusiones:<br>son el fruto fugaz del mundo viejo,<br>que renace con nuevos resplandores.<br><br>Ya est\u00e1n aqu\u00ed, livianos, tenues, tiernos<br>como el alma inocente de los hombres,<br>con la avidez de un animal hambriento<br>buscando la verdad de sus razones.<br><br>Son del pasado virginal recuerdo,<br>son del futuro v\u00edctimas precoces<br>puro presente son, vital y cierto.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">HOMBRE<\/span> (17\/03\/2013)<br>Firme ante los desastres<br>del tiempo que nos lleva<br>se levanta su efigie,<br>su dignidad maltrecha,<br>vencida por el plomo<br>brutal de tanta mierda.<br><br>Pero \u00e9l sigue ah\u00ed,<br>v\u00edctima de otra guerra,<br>llevando como puede<br>su esperanza desierta,<br>su soledad de \u00e1rbol<br>y su verdad de piedra.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\"><br>MUJER<\/span> (18\/03\/2013)<br>Aguantando en la espalda<br>de la historia perversa<br>el pasado la esconde,<br>el presente la niega,<br>y el futuro no escoge<br>su vocaci\u00f3n de hembra.<br><br>Humillada sin causa,<br>confinada sin pruebas,<br>sigue viva en su lucha<br>memorable, resuelta.<br>Porque ah\u00ed seguir\u00e1<br>sigo creyendo en ella.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">LAS FLORES OLVIDADAS<\/span> (15\/03\/2013)<br>Un p\u00e1lido reflejo<br>en los labios, la piel y la mirada<br>de lo que pudo ser pero no ha sido<br>se esconde, se acorrala<br>detr\u00e1s, en los rincones<br>del campo de batalla.<br><br>Y marca nuestros pasos,<br>aviva la nostalgia<br>y va dejando un pozo<br>de frutos y de flores olvidadas.<br>Tras lo que pudo ser pero no ha sido<br>la vida se desangra.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">EL PUNTO FINAL<\/span> (16\/03\/3013)<br>Al final de todo,<br>el punto final,<br>el cero absoluto,<br>un salto mortal;<br>silencio, silencio,<br>reino de la paz.<br><br>detr\u00e1s del silencio:<br>\u00bfHay algo detr\u00e1s?<br>\u00bfHay algo? La nada,<br>nada, nada m\u00e1s;<br>el cero absoluto,<br>el punto final.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <br><span style=\"font-weight: bold;\">AYER<\/span> (13\/03\/2013)<br><br>Con ardor juvenilayer ganaba causas,<br>imposibles batallas de la vida.<br>Hoy no puedo ganarlas<br>como ayer las gan\u00e9,<br>pero s\u00ed recordarlas,<br>ganarlas de otra forma,<br>de una forma m\u00e1s sutil y m\u00e1s sabia.<br><br>Ayer tambi\u00e9n perd\u00ed<br>lo que ya no se gana.<br>Lo que ayerse perdi\u00f3<br>se qued\u00f3 para siempre en la distancia.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">LA VERDAD<\/span> (14\/03\/2013)<br><br>Me duele esa verdad que no se dice,<br>que no puede decirse porque explota<br>que no soportar\u00eda ning\u00fan o\u00eddo,<br>que no cabe en el pecho ni en la boca.<br><br>Esa verdad que todos transportamos,<br>aunque muchos no sepan que la portan,<br>conformes con las pl\u00e1cidas verdades,<br>que contentan, que halagan, que conforman.<br><br>Me duele esa verdad que nos callamos,<br>me da\u00f1a esa verdad que nos desborda,<br>me duele esa verdad que queda dentro,<br>que podr\u00eda explicar todas las cosas.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\">JUEGO<\/span> (11)03\/2013)<br><br>Juegan los ni\u00f1os, juegan los mayores.<br>Es un juego la vida, un juego raro,<br>un juego de tramposos y de trampas,<br>un juego embarazoso y delicado.<br><br>Un juego demasiado peligroso,<br>que juegan a la fuerza los humanos,<br>como una maldici\u00f3n, como una noria,<br>que gira sin control y a contramano.<br><br>Juegan los ignorantes y los sabios<br>Y en ese juego todos fracasamos;<br>hasta juegan a Dios los cardenales<br>en el patio sin luz del Vaticano.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">\n         LAS PEQUE\u00d1AS COSAS<\/span> (12\/03\/2013)<br><br>No quiero ni principios ni conceptos<br>grandiosos, de ret\u00f3rica barata,<br>ni son las grandes cosas, sino otras<br>las que mi pl\u00e1cida atenci\u00f3n reclaman:<br>las ondas de una fuente cristalina,<br>el calor contagioso de la barra<br>de una pl\u00e1cida y c\u00e1lida taberna;<br>una tarde lluviosa, una ventana:<br>el c\u00f3mplice cari\u00f1o de mi gente,<br>el abrigo oportuno de mi casa,<br>una palabra, un gesto, una canci\u00f3n,<br>el tacto celestial de una guitarra.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br>&nbsp; &nbsp; &nbsp; <span style=\"font-weight: bold;\">&nbsp;LLANTO<\/span> (9\/3\/2013)<br><br>Lloro por ti y lloro por mi gente,<br>la que sale a vivir cada ma\u00f1ana<br>de sus manos, su pecho, sol de nieve,<br>la que muere blandiendo su esperanza.<br><br>Lloro por los que quieren y no pueden,<br>lloro por la verdad acribillada,<br>lloro por tanta dignidad vencida, inerte,<br>lloro por m\u00ed con l\u00e1grimas amargas.<br><br>Lloran sangre mis venas lentamente,<br>sufre mi coraz\u00f3n la noche larga;<br>peno por ese Dios que no aparece,<br>lloro por este reino de la nada.\n    <\/div>\n    <\/div>\n<\/div>\n<div class=\"art-content-layout\">\n    <div class=\"art-content-layout-row\">\n    <div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <br><span style=\"font-weight: bold;\">LLUVIA<\/span> (10\/03\/2013)<br><br>Llueve sal en los ojos,<br>llueve sangre en la historia desolada.<br>La tierra prometida<br>se ahega entre las l\u00e1grimas<br>del cielo que se hunde<br>en su misma sustancia,<br><br>Sale un olor a azufre<br>por todas las ventanas<br>y una niebla infinita se apodera<br>de las calles del alma.<br><br>El sol se est\u00e1 poniendo para siempre<br>y, lentamente, la tristeza avanza.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 34%\" >\n        <span style=\"font-weight: bold;\">A LO QUE DIGA EL AIRE<\/span> (7\/3\/2013)<br><br>Asido al sol, al fuego de las almas,<br>desnudo, sin apenas equipaje,<br>desoyendo el clamor de las espadas,<br>atento a las piruetas que da el aire.<br><br>Sin ganas de luchar, rotas las armas,<br>olvidado de todos y de nadie.<br>Con otra condici\u00f3n y otra mirada,<br>otorgando valor a lo que vale.<br><br>A Dios no hay que mirarlo cara a cara,<br>porque corres el riesgo de quemarte;<br>el que juega con dioses no descansa<br>ni sabe ciertamente lo que hace.\n    <\/div><div class=\"art-layout-cell\" style=\"width: 33%\" >\n        <span style=\"font-weight: bold;\"><br>LIBERTAD INFINITA<\/span> (8\/3\/2013)<br>Dentro,<br>me siento en plenitud emancipada<br>Fuera,<br>el plomo me acomoda a las aceras.<br>me pesan los recuerdos y las alas.<br>Dentro,<br>me encuentro a salvo, fuerte y a mis anchas.<br>Fuera,<br>me cercan los demonios de la noche;<br>la sed del que abandona la esperanza.<br>Dentro:<br>a salvo en lo infinito.<br>Fuera:<br>perdido entre mis l\u00e1grimas.<br>\n    <\/div>\n    <\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>AL FILO DE LA VIDA Bajar en pdf Comprar en papel Al filo de la vida A partir de hoy, 7 de marzo de 2013, colocar\u00e9 a diario un poema, hecho ex profeso para este espacio y compuesto al comp\u00e1s de cada d\u00eda, sobre la marcha, sin correcciones ni acicalamiento posterior, tal como vayan saliendo. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":14,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_aioseop_title":"","_aioseop_description":"","ngg_post_thumbnail":0,"footnotes":""},"_links":{"self":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/pages\/5365"}],"collection":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/comments?post=5365"}],"version-history":[{"count":0,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/pages\/5365\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/media?parent=5365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}