{"id":5368,"date":"2016-11-21T22:23:52","date_gmt":"2016-11-21T21:23:52","guid":{"rendered":"http:\/\/www.josemariatornay.com\/index.php\/mis-libros\/crisis-que-crisis\/"},"modified":"2018-10-07T15:16:37","modified_gmt":"2018-10-07T14:16:37","slug":"crisis-que-crisis","status":"publish","type":"page","link":"http:\/\/www.josemariatornay.com\/index.php\/crisis-que-crisis\/","title":{"rendered":"\u00bfCrisis? \u00bfQu\u00e9 crisis?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5368\" class=\"elementor elementor-5368 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a038fde elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a038fde\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e6214c7\" data-id=\"e6214c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05724b5 elementor-widget elementor-widget-heading\" data-id=\"05724b5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-large\">\u00bfCRISIS? \u00bfQU\u00c9 CRISIS?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a58a2bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a58a2bd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f2dab89\" data-id=\"f2dab89\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d3ff6e elementor-widget elementor-widget-heading\" data-id=\"7d3ff6e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2018\/10\/\uffc2\uffbfCrisis\uffc2\uffbf-\uffc2\uffbfQu\uffc3\uffa9-crisis_.pdf\">Bajar en pdf<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7d33e5f\" data-id=\"7d33e5f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a749920 elementor-widget elementor-widget-heading\" data-id=\"a749920\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.lulu.com\/shop\/jos%C3%A9-mar%C3%ADa-tornay-ruiz\/crisis-qu%C3%A9-crisis\/paperback\/product-23824339.html\">Comprar en papel<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b59\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-310e\" data-id=\"310e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42af elementor-widget elementor-widget-text-editor\" data-id=\"42af\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 25%;\"><p style=\"text-align: center;\"><img decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/presentacion.jpg\" alt=\"\" width=\"111\" height=\"130\" \/><br \/>PRESENTACI\u00d3N<\/p><\/div><div class=\"art-layout-cell\" style=\"width: 50%;\"><p style=\"text-align: center;\"><img decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/titulotexto.jpg\" alt=\"\" width=\"174\" height=\"130\" \/><br \/><span style=\"font-weight: bold;\">Obra teatral en 12 cuadros, original de Jos\u00e9 Mar\u00eda Tornay<\/span><\/p><\/div><div class=\"art-layout-cell\" style=\"width: 25%;\"><p style=\"text-align: center;\"><img decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/prologo.jpg\" alt=\"\" width=\"140\" height=\"129\" \/><\/p><\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 25%;\"><p><em style=\"color: #990000; font-family: 'Times New Roman'; font-size: medium; letter-spacing: normal; text-indent: 0px;\">Crisis. \u00bfQu\u00e9 crisis? es el t\u00edtulo de un \u00e1lbum legendario del no menos legendario grupo SUPERTRAMP. Siempre me result\u00f3 atractivo dicho t\u00edtulo y, ahora, me parece que viene a cuento de manera especial, para definir el sentido profundo de la obra de teatro que ando construyendo sobre estos tiempos convulsos y lamentables que estamos atravesando.\u00a0<br \/>El ciudadano, hecho a las mentiras recurrentes del poder, tienen la fundada sospecha de que esta crisis no es m\u00e1s que otro ardid de los que mandan, para conseguir objetivos pol\u00edticos y sociales de m\u00e1s largo alcance. \u00bfNo es \u00e9sta una crisis extra\u00f1a? \u00bfQu\u00e9 est\u00e1 pasando? \u00bfQui\u00e9n anda detr\u00e1s de todo esto? \u00bfCu\u00e1l es el papel de los pol\u00edticos?<br \/>Son preguntas que ya se pueden responder. Yo trato de hacerlo en esta obra mordaz y evidente, aunque, a veces, un poco absurda; porque absurdo es el mundo que nos han construido.<br \/>Sin \u00e1nimo de destripar el contenido de la mismo y sus variadas intenciones, s\u00ed puedo adelantar las dos tesis b\u00e1sicas que me animan a sostener lo que sostengo:<br \/>1. El poder financiero se ha desbocado y ha invadido de tal forma al poder pol\u00edtico, que \u00e9ste ha quedado relegado a un papel secundario de mamporrero de aqu\u00e9l. Quien manda de verdad no da la cara, porque para eso y para que se la partan tiene a los imb\u00e9ciles de turno, que est\u00e1n dispuestos a poner su rostro en un papel a cambio de gozar de sustanciosas prebendas, como podemos ver que ocurre en nuestro pa\u00eds con la corrupci\u00f3n generalizada.<\/em><\/p><p><em style=\"color: #990000; font-family: 'Times New Roman'; font-size: medium; letter-spacing: normal; text-indent: 0px;\">2. La corrupci\u00f3n, al menos en nuestro pa\u00eds, se desarrolla y se mantiene, porque hay un pueblo detr\u00e1s que la comprende y que la acepta, de tal forma, que lo que a cualquier persona decente le producir\u00eda verdadera verg\u00fcenza, a nosotros nos suele resbalar de manera escandalosa. Los espa\u00f1oles somos descendientes de la picaresca, del chanchullo y de la trampa y, porque tales desahogos son pr\u00e1cticas generalizadas en la ciudadan\u00eda, es por lo que se asume que al pol\u00edtico, como buen conciudadano, se le consiente que meta la mano y todo lo que tenga que meter. El pol\u00edtico es hijo de un pueblo, que es potencialmente corrupto y, por tanto, \u00a1qu\u00e9 podemos esperar de \u00e9l cuando se encuentra con la posibilidad de trincar? Cualquiera lo har\u00eda.\u00a0<br \/>S\u00e9 que \u00e9sta es una visi\u00f3n brutal de mi pa\u00eds, pero es la que tengo. Decir otra cosa ser\u00eda mentir. De esta forma, aunque exagere, s\u00e9, al menos, que estoy diciendo mi verdad.<\/em><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/Pol%c3%adtico.jpg\" alt=\"\" width=\"160\" height=\"160\" \/><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/Pol%c3%adtico%202.jpg\" alt=\"\" width=\"155\" height=\"160\" \/><\/p><\/div><div class=\"art-layout-cell layout-item-0\" style=\"width: 50%;\">Una reflexi\u00f3n esperp\u00e9ntica sobre el poder. Una caricatura del PODER y la CORRUPCI\u00d3N. Una cr\u00edtica del poder desprovisto de autoridad y de la perversi\u00f3n de la finalidad de la pol\u00edtica. Se trata de una farsa, en la que tipos voluntariamente excesivos y exagerados (\u00bfexagerados?) intentan llamar la atenci\u00f3n sobre conductas y actitudes incomprensiblemente aceptadas en nuestra sociedad que, como mucho, obtienen un rechazo indolente y generoso desde la barra del bar. El realismo m\u00e1s crudo mezclado al absurdo m\u00e1s ins\u00f3lito, tal cual aparecen en la vida diaria, que comparece ante nosotros a la hora de comer, en los telediarios.<br \/><br \/>La obra est\u00e1 estructurada en doce cuadros independientes, unidos por el hilo conductor de la crisis, la corrupci\u00f3n, inevitable y asociada a todo poder y la nimiedad de la pol\u00edtica. Teatro actual para entender el mundo de hoy. Como estoy casi seguro de la dificultad de que alguien cargue con su representaci\u00f3n, aqu\u00ed la coloco para que pueda ser, al menos, le\u00edda por los osados internautas decepcionados, como yo, con este mundo absurdo y esta organizaci\u00f3n brutal del mismo, que han articulado los que mandan. Este es el<table class=\"art-article\" style=\"width: 100%;\"><tbody><tr><td style=\"width: 50%; text-align: center;\"><span style=\"text-decoration: underline;\">\u00cdNDICE<\/span><br \/>EL SISTEMA<br \/>AGRADECIDOS Y TRAIDORES<br \/>EL TALENTO<br \/>ESCR\u00daPULOS<br \/>TRADUCCI\u00d3N SIMULT\u00c1NEA<br \/>ECONOM\u00cdA Y JUSTICIA<br \/>EL MERCADO<br \/>LOS RECORTES<br \/>EL PROGRAMA<br \/>LA CRISIS<br \/>GOBIERNO &#8211; OPOSICI\u00d3N<br \/>FRENTE A FRENTE<\/td><td style=\"width: 50%; text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/titulocrisisquecrisis.jpg\" alt=\"\" width=\"205\" height=\"149\" \/><\/td><\/tr><\/tbody><\/table><p><span style=\"font-size: 20px;\">\u00a0<\/span><\/p><table class=\"art-article\" style=\"width: 100%;\"><tbody><tr><td style=\"width: 100%; text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/cuadro01.jpg\" alt=\"\" width=\"137\" height=\"100\" \/><span style=\"font-size: 20px;\">CUADRO I: EL SISTEMA<\/span><\/td><\/tr><\/tbody><\/table><p><span style=\"font-weight: bold;\">PERSONAJES: Pol\u00edtico, Ciudadano, Secretario, Secretaria<\/span><br \/>VOZ EN OFF: La crisis. \u00bfQu\u00e9 crisis? No hay crisis. Esto es lo que hay y lo que nos espera. No habr\u00e1 vuelta atr\u00e1s. A esto hemos venido a parar por la desverg\u00fcenza de unos, la codicia desaforada de otros, el ego\u00edsmo de la mayor\u00eda y la indolencia c\u00f3mplice de todos nosotros. \u00a1Ah! Una buena noticia: seguramente, ya nunca m\u00e1s volveremos a ser sorprendidos por una crisis. A partir de ahora \u00e9ste ser\u00e1 nuestro estado natural. Es lo que ocurre cuando se llega al \u00faltimo grado de la perversi\u00f3n de todos los valores, de todas las l\u00f3gicas, de todos los principios morales, sociales y pol\u00edticos. Salir de este t\u00fanel no es cosa de programas econ\u00f3micos, ni de reformas laborales, ni de proyectos de actuaci\u00f3n preferente. Hay que quitarles la iniciativa a los pol\u00edticos y a los poderes financieros. La regeneraci\u00f3n ha de venir de otro lado, del pueblo. Sin olvidar que de ese pueblo salen los pol\u00edticos y los banqueros y los especuladores y los inmorales. La sociedad es la que tiene que provocar dentro de s\u00ed misma, de sus conductas y actitudes, una regeneraci\u00f3n, una catarsis lo suficientemente traum\u00e1tica como para que no vuelva m\u00e1s a parir gentes de esa cala\u00f1a. Es en una sociedad sin miedo y cohesionada alrededor del valor de la decencia, donde \u00fanicamente puede radicar la esperanza.<br \/>(<span style=\"font-style: italic;\">Vuelve a sonar la Sinton\u00eda, mientras el Pol\u00edtico se va colocando en el proscenio).<br \/>(Una mesa y dos sillas ser\u00e1n la referencia para el movimiento de los dos personajes centrales del di\u00e1logo, el Pol\u00edtico y el Ciudadano. Los otros dos, Secretario y Secretaria, se limitar\u00e1n a asomarse, cada uno por un lateral).<\/span><br \/>POL\u00cdTICO (<span style=\"font-style: italic;\">Dirigi\u00e9ndose al proscenio<\/span>): \u00bfQu\u00e9 pasa con la pol\u00edtica? \u00bfQu\u00e9 pasa con los pol\u00edticos? \u00bfPor qu\u00e9 todos nos culpan de todo? Porque, no me lo negu\u00e9is, es as\u00ed, somos el chivo expiatorio. La gente nos usa para escupir sobre nosotros sus frustraciones, sus fracasos, sus cabreos, sus decepciones (Con arrogancia) \u00bfY qu\u00e9 hemos hecho mal? \u00bfEh? (Reflexionando y con humildad) Mejor ser\u00eda decir, \u00bfhemos hecho algo bien? (<span style=\"font-style: italic;\">Se dirige a su silla y se sienta<\/span>). No es posible que me equivoque en todo.<br \/>CIUDADANO: No es eso, no es eso. Comet\u00e9is errores; todos lo hacemos. Pero el problema no es ese. El problema es que hab\u00e9is construido un sistema que os fagocita. Os hab\u00e9is quedado sin iniciativa dentro de \u00e9l. Hab\u00e9is construido un r\u00e9gimen que os devora y os obliga a conductas, actitudes y comportamientos, que no pueden conduciros m\u00e1s que al fracaso y al rechazo popular.<br \/>SECRETARIO (Asomando levemente por la parte izquierda del foro y en tono de discreci\u00f3n c\u00f3mica, sin advertir la presencia del Ciudadano): Se\u00f1or Delegado: que dice el presidente del Partido que se ocupe usted del tema de la pensi\u00f3n de su primo\u2026<br \/>CIUDADANO (<span style=\"font-style: italic;\">Haciendo un gesto de que esa intervenci\u00f3n del Secretario viene a confirmar sus palabras<\/span>): Hab\u00e9is abandonado la alta pol\u00edtica. Aquella gran pol\u00edtica, fundada en nobles ideales y en compromisos firmes, ha sido sustituida por la peque\u00f1a pol\u00edtica de la triqui\u00f1uela, de la componenda, del enjuague, del enchufe (haciendo un gesto hacia el lugar que ha abandonado el Secretario).<br \/>POL\u00cdTICO: Esto es una jungla y hay que sobrevivir, por encima de cualquier otra cosa.<br \/>CIUDADANO: Nosotros, los ciudadanos, no podemos sufrir las consecuencias de vuestras batallitas. Os cre\u00e9is m\u00e1s importantes que los temas que ten\u00e9is que gestionar. Y cada uno en vuestra parcela os cre\u00e9is semidioses, con su corte de sacerdotes, monaguillos y dem\u00e1s ralea. Cada cargo es una r\u00e9plica del cargo superior y as\u00ed se multiplican innecesariamente gastos y personal.<br \/>SECRETARIA (E<span style=\"font-style: italic;\">ntrando por el lado derecho del foro y en el mismo tono entre p\u00edcaro y confidencial del Secretario)<\/span>: El Secretario del Secretario del Comit\u00e9 Rector me pide que le pregunte que qu\u00e9 hay de lo suyo\u2026<br \/>CIUDADANO (Gesto de que se confirman sus sospechas): Est\u00e1is atrapados en una red infernal en la que o deb\u00e9is u os deben o las dos cosas a la vez. Eso genera una situaci\u00f3n tan an\u00f3mala, que perd\u00e9is m\u00e1s tiempo en vuestras tramas que en intentar resolver los problemas reales de la gente.<br \/>POL\u00cdTICO: No es f\u00e1cil gobernar un partido y menos contentar a todos.<br \/>CIUDADANO: No se trata de contentar, sino de trabajar sin rodearse de par\u00e1sitos, que buscan en la pol\u00edtica su modus vivendi. Hoy se acercan los aspirantes a los partidos, no porque sintonicen con sus ideas, sino porque le ven m\u00e1s o menos posibilidades para medrar.<br \/>SECRETARIO (Por el lado izquierdo, siempre en el mismo tono): Que llaman de la Casa Real para ver si tenemos buenas relaciones con las autoridades de Tanzania, en cuyo caso podr\u00edamos interceder para que vayan reuniendo a los elefantes\u2026<br \/>CIUDADANO: \u00bfLo ves? Cada loco con su tema. Y a vivir que son dos d\u00edas. Esto hace que cada vez os distanci\u00e9is m\u00e1s del pueblo. Os hab\u00e9is alejado tanto de la gente que cada vez ser\u00e1 m\u00e1s dif\u00edcil que la gente pueda acercarse nuevamente a vosotros.<br \/>POL\u00cdTICO (Con seguridad): La gente no tiene memoria y cuando cambien las cifras macroecon\u00f3micas, recuperaremos su afecto.<br \/>CIUDADANO: Ya, me temo, hab\u00e9is ido demasiado lejos como para volver de rositas. Hab\u00e9is fomentado un sistema que permite que a los partidos no acudan los mejores, sino los trepas, los arribistas y los tipos sin escr\u00fapulos.<br \/>SECRETARIA (Por el lado derecho): Que llama el Secretario General del Sindicato Horizontal interes\u00e1ndose por la subvenci\u00f3n del curso de m\u00e1rquetin.<br \/>CIUDADANO: Y los sindicatos, que venden su independencia por un plato de lentejas, tampoco est\u00e1n en condiciones de ejercer su papel. La confrontaci\u00f3n casi siempre es una pantomima, una farsa para que los trabajadores crean que est\u00e1n bien defendidos.<br \/>POL\u00cdTICO: As\u00ed conseguimos votos y defendemos los intereses de todos. En el fondo, y a nuestra manera, defendemos una \u00e9tica\u2026<br \/>CIUDADANO (Interrumpi\u00e9ndolo): Para llevar la \u00e9tica a la pol\u00edtica hay que renunciar a la pol\u00edtica y, entonces, \u00bfde qu\u00e9 nos sirve la \u00e9tica? Si apuestas por la \u00e9tica, olv\u00eddate de la pol\u00edtica.<\/p><\/div><div class=\"art-layout-cell\" style=\"width: 25%;\"><span style=\"font-style: italic;\"><span style=\"color: #990000; font-family: 'Times New Roman'; font-size: medium; letter-spacing: normal; text-indent: 0px;\">Desde hace unos a\u00f1os, la gente, cuando se encuentra por la calle, ha dejado de hablar del tiempo para hacerlo de la crisis. Y en esas situaciones embarazosas de la vida, en las que no sabemos qu\u00e9 decir y nos vemos impelidos a romper el hielo, nos asimos al tema que ya resulta recurrente: la crisis.<\/span><br style=\"color: #990000; font-family: 'Times New Roman'; font-size: medium; letter-spacing: normal; text-indent: 0px;\" \/><span style=\"color: #990000; font-family: 'Times New Roman'; font-size: medium; letter-spacing: normal; text-indent: 0px;\">Y es que la crisis, adem\u00e1s de una putada, es algo bastante \u00fatil, si se est\u00e1 dispuesto a sacarle partido a todas las cosas, incluidas las\u00a0 lamentables y perniciosas. Si a \u00e9sta se une la inanidad de la pol\u00edtica tal y como se entiende en la actualidad, se produce un c\u00f3ctel explosivo, que invita m\u00e1s a la risa que a cualquier otra consideraci\u00f3n grave.<\/span><br style=\"color: #990000; font-family: 'Times New Roman'; font-size: medium; letter-spacing: normal; text-indent: 0px;\" \/><\/span><span style=\"color: #990000; font-family: 'Times New Roman'; font-size: medium; letter-spacing: normal; text-indent: 0px;\"><span style=\"font-style: italic;\">S\u00e9 y me consta que hay pol\u00edticos que atesoran buenas intenciones y honestidad m\u00e1s que manifiesta, pero tambi\u00e9n he podido comprobar que el sistema al que se integran (la pol\u00edtica) es suficientemente abrasivo como para no permitir muchos entusiasmos individuales o empresas quijotescas. Al final, el sistema se impone y prescinde de las .\u00a0<span style=\"font-size: medium; text-align: -webkit-left;\">Tengo amigos que se dedican a la cosa p\u00fablica. Son buenas personas. Seguro que hay muchas de ellas dedicadas al tema. No es mi intenci\u00f3n ofenderlas. A las otras, las que van llenando de podredumbre los despachos, los pasillos y las instituciones por donde mueven su miseria, no tengo ning\u00fan escr\u00fapulo porque se sientan aludidas. Esa es mi intenci\u00f3n y, sobre todo, el objetivo que pretende esta farsa es poner en solfa un sistema, que olvida lo sustancial y se queda en la superficie, que prima lo adjetivo sobre lo sustantivo y que est\u00e1 m\u00e1s pendiente de lo secundario que de lo esencial.<\/span><span class=\"negrita\">Mi admiraci\u00f3n m\u00e1s profunda a los que tienen que nadar contracorriente en ese magma de intereses espurios y de livianas apariencias, en el que reina la obediencia ciega y la adulaci\u00f3n m\u00e1s cochambrosa. Algunos salen a flote en ese mar de las comisiones, los sobres y la prevaricaci\u00f3n. Son los h\u00e9roes de la pol\u00edtica.<br \/>S\u00e9 la dificultad que supone atacar a un sistema sin lesionar a las personas que incorpora, pero tambi\u00e9n estoy convencido de que un cambio radical del modelo har\u00eda que esas personas dieran al servicio de todos lo mejor que llevan dentro y abandonaran cualquier tentaci\u00f3n perniciosa. Si fueran capaces de abrir las ventanas, podr\u00eda entrar el aire vivificador que la sociedad y la dignidad de todos est\u00e1n reclamando.<br \/>Soy m\u00e1s roussoniano que hobbesiano en el juicio que me merecen los seres humanos. Creo sinceramente en su bondad natural. Estoy convencido de que es el contexto el que alimenta las condiciones para que naufrague aqu\u00e9lla. Pese al ego\u00edsmo propio de quien responde, antes que a otra cosa, al instinto de supervivencia, hay por ah\u00ed dentro, en la inmensa mayor\u00eda de nosotros, algo que nos empuja al altruismo y a la generosidad.<br \/>Aunque he elegido distintos registros para hablar de lo mismo, la verdad es que he intentado moverme en un tono general grotesco y sarc\u00e1stico, que entiendo es el m\u00e1s adecuado para zaherir conductas impresentables e idearios corrompidos, salvando la integridad de la mayor\u00eda de las personas. Alguien puede echar de menos que no se traten los comportamientos positivos y nobles, pero es que esta obra no iba de eso.<br \/>Una reflexi\u00f3n final debe apartarnos a los del pueblo llano de la pretensi\u00f3n de honestidad absoluta y pureza moral, que podr\u00eda deducirse de nuestra condici\u00f3n de sufridores de todo lo que aqu\u00ed se lamenta. No debemos olvidar que los pol\u00edticos son tambi\u00e9n hijos de la misma sociedad a la que todos pertenecemos y que es \u00e9sta la que sostiene y avala un sistema lleno de lacras e imperfecciones y que es, sin duda, manifiestamente mejorable.<\/span><\/span><br \/><\/span><\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\">POL\u00cdTICO: Somos los representantes de los ciudadanos. Al fin y al cabo hemos sido elegidos por ellos.<br \/>CIUDADANO: Os hab\u00e9is convertido en un producto, como cualquier refresco. Un producto que ya nadie quiere consumir, porque es un suced\u00e1neo, una mentira.<br \/>POL\u00cdTICO: Las mentiras no son malas si sirven a un inter\u00e9s superior.<br \/>CIUDADANO: Si Maquiavelo levantara la cabeza se avergonzar\u00eda de su descendencia.<br \/>SECRETARIO (Asomando de nuevo por su lugar habitual): Que llama el portavoz para saber qu\u00e9 versi\u00f3n de los hechos hay que venderle a la ciudadan\u00eda.<br \/>CIUDADANO (Aparte): Cualquier cosa menos la verdad. Esa tiene mal asiento en la boca de un pol\u00edtico.<br \/>POL\u00cdTICO: La que m\u00e1s convenga a los intereses del Partido. La lealtad ante todo.<br \/>CIUDADANO: Hab\u00e9is creado un cuerpo de funcionarios de la pol\u00edtica. Todo queda en casa. Pero tienes que saber que la endogamia no engendra m\u00e1s que deformidad y estulticia. En ella se est\u00e1 cuando se est\u00e1 tan lejos de la realidad\u2026Cambi\u00e1is de puesto, pero nunca abandon\u00e1is la generosa matriz. Pas\u00e1is de ac\u00e1 para all\u00e1, pero siempre sois los mismos. Y si no sois los mismos, muy pronto consegu\u00eds que sean exactamente los mismos.<br \/>SECRETARIA (Entrando por su lado acostumbrada): Que llaman del Partido de la Oposici\u00f3n para ver c\u00f3mo planteamos la discrepancia sobre el tema del f\u00fatbol y la televisi\u00f3n y a ver qu\u00e9 postura nos interesa adoptar a cada uno de cara a la opini\u00f3n p\u00fablica.<br \/>CIUDADANO: En el fondo, ten\u00e9is mejores relaciones con los dem\u00e1s partidos que con los ciudadanos. Es el inevitable esp\u00edritu de gremio, que tanto ha intervenido en la historia de este pa\u00eds. Primero lo m\u00edo, despu\u00e9s los m\u00edos y luego nuestros intereses. Si queda algo\u2026<br \/>POL\u00cdTICO: Tienes una visi\u00f3n muy negativa de las cosas. La pol\u00edtica es una actividad vocacional y s\u00ed, hay errores y alg\u00fan que otro sinverg\u00fcenza pero, en general, los pol\u00edticos se mueven por intereses nobles.<br \/>CIUDADANO: Al principio s\u00ed; luego, ya sabes, el sistema pone a cada uno en su sitio. El poder, en cuando se constituye, abandona la idea inicial de servicio y acoge la idea de ser servido. Ah\u00ed empiezan los problemas.<br \/>SECRETARIO (Desde el lado izquierdo): El director de La Ma\u00f1ana solicita una entrevista para mejorar la imagen del Secretario General.<br \/>CIUDADANO: \u00bfLo ves? No hay soluci\u00f3n. La prensa, los periodistas, comentaristas, tertulianos. Hermosos sustantivos. Quienes debieran servir \u00fanicamente a la verdad, la usan como si fuera un despojo. Es m\u00e1s rentable servir al Partido que corresponda, a \u201clos nuestros\u201d, a los que se ocupan o se ocupar\u00e1n de sus intereses, de sus negocios.<br \/>POL\u00cdTICO: La verdad. \u00bfQu\u00e9 es la verdad? Cada partido tiene o aspira a una parte de la verdad. Por eso se llama as\u00ed: partido. En la uni\u00f3n de lo que defiende cada uno de los partidos est\u00e1 la verdad.<br \/>CIUDADANO: Magn\u00edfica ret\u00f3rica, pero vac\u00eda y \u00bfsabes por qu\u00e9 es una ret\u00f3rica vac\u00eda? Porque a la hora de la verdad, lo que cuenta es que hay que enriquecerse de forma r\u00e1pida, que no sabemos hasta cu\u00e1ndo vamos a estar aqu\u00ed, que hay que\u2026Lo dem\u00e1s son palabras, vocablos sin significado, sonidos que no llevan nada dentro.<br \/>POL\u00cdTICO: La corrupci\u00f3n no es exclusiva de la clase pol\u00edtica. Est\u00e1 en todos los niveles de la sociedad, de la vida.<br \/>CIUDADANO: Pero es mucho m\u00e1s lamentable en los servidores p\u00fablicos, porque viene, adem\u00e1s, propiciada por el sistema. La corrupci\u00f3n es hija de la seguridad. La seguridad procede de las mayor\u00edas absolutas o de la falta de alternativa.<br \/>POL\u00cdTICO: La honradez no es algo natural. Hay que cultivarla y formarla. La tendencia natural es\u2026la desverg\u00fcenza, que es a lo que propende el ego\u00edsmo, sustancia esencial de los seres vivos.<br \/>CIUDADANO: No hay tal. El ser humano es bueno por naturaleza. Viene a corromperse por su relaci\u00f3n con un contexto podrido y por unos escenarios que lo desv\u00edan del camino recto.<br \/>POL\u00cdTICO: Intentamos rodearnos de los mejores\u2026Al menos de los listos, que no es lo mismo que inteligentes. Todos los listos son inteligentes, pero no todos los inteligentes son listos.<br \/>CIUDADANO (Interrumpiendo): Por muchos curr\u00edculums brillantes que presenten los candidatos, la realidad es que a la pol\u00edtica no se dedican los mejores. Los mejores se dedican a otras cosas. A la pol\u00edtica se dedican los que no sirven para esas otras cosas.<br \/>SECRETARIA (Interrumpiendo aceleradamente el discurso del Ciudadano, desde el lado derecho): En la puerta est\u00e1 y me ruega que lo haga pasar el se\u00f1or Duque de Palma.<br \/>(Ese t\u00edtulo funciona como un aut\u00e9ntico resorte que hace que todos se movilicen por la alarma. El siguiente di\u00e1logo transcurre mientras huyen hacia el foro contrario al que ha usado la Secretaria para entrar)<br \/>POL\u00cdTICO: R\u00e1pido, esconded todas las cosas de valor. \u00a1El yerno, el yerno!<br \/>SECRETARIO: \u00a1Las carteras, las carteras!<br \/>SECRETARIA: Los bol\u00edgrafos, los l\u00e1pices, los papeles\u2026\u00a1vamos, vamos!<br \/>CIUDADANO: (Sin moverse de su sitio) Yo no pienso moverme de aqu\u00ed. (Con indiferencia). No s\u00e9 qu\u00e9 pueden ya quitarme.<br \/>(Se hace el oscuro mientras suena con potencia la melod\u00eda de la obra. El mobiliario es \u00fatil para el segundo cuadro).<\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/cuadro02.jpg\" alt=\"\" width=\"108\" height=\"100\" \/><span style=\"font-size: 20px;\">CUADRO II: AGRADECIDOS Y PAGADOS<\/span><\/p><\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><span style=\"font-weight: bold;\">PERSONAJES: Presidente, Ministro, Tesorero del Partido, Secretario<\/span><br \/>(El Presidente comienza a hablar cuando cesa la sinton\u00eda)<br \/>PRESIDENTE (en el proscenio y al p\u00fablico): La pol\u00edtica teje ambiciones y siembra vanidades en el coraz\u00f3n de los hombres. Y los puestos son escasos y los aspirantes siempre son demasiados.<br \/>Gobernar consiste en repartir prebendas que, m\u00e1s tarde, operen en tu propio beneficio. Generar gratitudes asegura el mantenimiento en el poder de quien reparte. Y quien reparte\u2026ya se sabe\u2026se lleva la mejor parte (se sienta en la silla detr\u00e1s de la mesa, adoptando el papel del Presidente del Gobierno).<br \/>MINISTRO: Se\u00f1or Presidente, necesitar\u00edamos una vicesecretar\u00eda de asuntos insignificantes; tengo un cu\u00f1ado, que no para de darme la lata, que ser\u00eda el candidato ideal. Nadie entiende m\u00e1s que \u00e9l de banalidades y de cosas intrascendentes (est\u00e1 casado con mi hermana). Podr\u00edamos canalizar a trav\u00e9s de \u00e9l todos los asuntos internos del partido.<br \/>PRESIDENTE: Ministro, enc\u00e1rguese de la creaci\u00f3n de ese departamento y que empiece a funcionar de inmediato. Por cierto, \u00e9chele un ojo a mi hermano, que est\u00e1 intentado hacer colar su posici\u00f3n de influencia en ambientes poco recomendables.<br \/>MINISTRO: No te preocupes, Presidente, para ese papel tengo a la persona ideal: mi suegra. Nadie como ella sabr\u00eda controlar y fiscalizar de mejor manera la vida de un semejante. Y si le adjuntamos a mi cu\u00f1ada, no se les escapa ni una sola maldad.<br \/>PRESIDENTE: Que incorporen inmediatamente a tu suegra y a tu cu\u00f1ada a la oficina de control de personas, ideas y tr\u00e1fico de emociones. Es un papel que le ir\u00eda como anillo al dedo a la m\u00eda, pero no quiero que la oposici\u00f3n me acuse de nepotismo y tr\u00e1fico de influencias. (El ministro hace mutis por el foro).<br \/>TESORERO (Entrando por la derecha y cruz\u00e1ndose con el Ministro, que sale): Se\u00f1or Presidente (pas\u00e1ndole con discreci\u00f3n un sobre), aqu\u00ed tiene su cuota del mes de plus por responsabilidad espec\u00edfica. Son 15.000 euros, como siempre. Es que como no caben en la n\u00f3mina tengo que colocarlos aparte para que no se entere el compa\u00f1ero de Hacienda.<br \/>PRESIDENTE: No s\u00e9 qu\u00e9 har\u00eda este Partido sin un Tesorero como t\u00fa, tan diligente, tan resuelto (haciendo el gesto que trincar dinero), tan discreto y tan prudente. No s\u00e9 qu\u00e9 har\u00eda yo\u2026<br \/>TESORERO (Interrumpi\u00e9ndole): Yo le digo lo que puede hacer. Llame al director de Informaciones para que le d\u00e9 ca\u00f1a al Juez Mufl\u00f3n a ver si se tranquiliza y deja en paz mi caso de corruptelas variadas.<br \/>PRESIDENTE: No te preocupes; todo est\u00e1 bajo control. Ese peri\u00f3dico nos debe todo lo que tiene. Su director tiene subvencionados hasta los calzoncillos. Har\u00e1 lo que yo le sugiera\u2026<br \/>PRESIDENTE (Se dirige hacia el proscenio y cambia la luz): Ay, pero las cosas de la vida son como son. En la f\u00edsica todo tiende a la entrop\u00eda, es decir, al desorden, mientras que en la pol\u00edtica, en las perversidades de la pol\u00edtica, se tiende al equilibrio. O sea, el pol\u00edtico, en la medida en que reparte y va construyendo una legi\u00f3n de agradecidos, se va convirtiendo a la vez en un reh\u00e9n de ellos. Le deben mucho, pero tambi\u00e9n conocen todos sus secretos, sus puntos flacos y, adem\u00e1s, lo que se recibe como regalo se termina considerando una obligaci\u00f3n. Y si tambi\u00e9n cambian los vientos (en la pol\u00edtica ocurre con frecuencia) m\u00e1s de uno intentar\u00e1 cobrarle sus favores. No hay peor enemigo que un pariente agradecido o un miembro de tu propio Partido (vuelve a su puesto de Presidente del Gobierno).<br \/>TESORERO: Presidente, que dice el antiguo tesorero que o soluciona usted el tema del contencioso de Los Hampones o tira de la manta.<br \/>MINISTRO: Que llama el Obispo exigiendo la renovaci\u00f3n del convenio de subvenci\u00f3n sobre el ciclo \u201cLa influencia del voto de castidad sobre el cambio clim\u00e1tico\u201d o tendr\u00e1 que dar instrucciones a sus p\u00e1rrocos para que nos aticen desde el p\u00falpito.<br \/>SECRETARIO: Se\u00f1or Presidente, el Secretario General del sindicato Transversal espera que usted decida de una vez sobre el aumento solicitado en la ayuda para los J\u00f3venes Agitadores del Porvenir o le echar\u00e1 a los trabajadores a la calle.<br \/>TESORERO: Las amas de casa le exigen en manifestaci\u00f3n la consolidaci\u00f3n de la ayuda puntual que usted les concedi\u00f3 para compensar el desajuste intelectual y emocional que les ocasiona el exceso de horas sentadas delante de la televisi\u00f3n. Su se\u00f1ora es una de las que encabeza la manifestaci\u00f3n.<br \/>SECRETARIO: Se\u00f1or Presidente, que si no renueva el concierto con la Academia de Cine \u201cEl ojo virtual\u201d, est\u00e1n dispuestos a costear una pel\u00edcula que airee sus escarceos er\u00f3tico-sinvergonzones.<br \/>PRESIDENTE (Cada vez m\u00e1s agobiado): Me rindo, me rindo. No puedo m\u00e1s. (Tranquiliz\u00e1ndose y reflexionando en voz alta). Es triste reconocer que antes de que el pueblo te acabe arrojando a la calle, los que te reprueban, los que te amargan la existencia, los que te terminan echando y olvid\u00e1ndose de ti. son los que todo te lo deben. En este mundo nuestro el peor enemigo no es el m\u00e1s fuerte, sino el que te tiene m\u00e1s a mano.<br \/>MINISTRO: \u00bfQu\u00e9 pensabas? \u00bfQu\u00e9 te quer\u00edan por tu talento?<br \/>(Se hace el oscuro y suena la sinton\u00eda de la obra. No hay cambio de mobiliario).<\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/cuadro3.jpg\" alt=\"\" width=\"142\" height=\"99\" \/><span style=\"font-size: 20px;\">CUADRO III: EL TALENTO<\/span><\/p><\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><span style=\"font-weight: bold;\">PERSONAJES:Secretario del Subsecretario, Presidente, Ministro, Subsecretario<\/span><br \/>(Sigue el mismo mobiliario, adapt\u00e1ndolo a la nueva situaci\u00f3n)<br \/>SECRETARIO DEL SUBSECRETARIO: El talento. \u00a1Qu\u00e9 concepto m\u00e1s et\u00e9reo y m\u00e1s vers\u00e1til! Unos lo confunden con el dinero, otros, con la suerte, otros, con la capacidad camale\u00f3nica para adaptarse a todo. Otros, incluso, con la facilidad para ganar voluntades\u2026 Y lo cierto es que algo de talento hace falta para todo: para atesorar riquezas, para buscar la suerte, para acomodarse a las circunstancias, para seducir a los incautos\u2026<br \/>(Muy despacio y marcando bien los tiempos y los silencios) Todo lo que he logrado en esta vida se lo debo a mi esfuerzo (le limpia los zapatos al Presidente); se lo debo a mi capacidad (le sirve el caf\u00e9 al ministro); se lo debo a mi compromiso con este partido y con estas ideas (le enciende el puro al Subsecretario).<br \/>Yo soy un pol\u00edtico com\u00fan, t\u00edpico. Este es para m\u00ed el contenido del talento. Jam\u00e1s he tenido una sola idea propia. Me ha ido de lujo repitiendo las que escuchaba a los que estaban por delante de m\u00ed en el escalaf\u00f3n. He hecho un aut\u00e9ntico arte del ejercicio de no pensar. Para eso ya est\u00e1 otros. Repitiendo lo que ellos dicen est\u00e1n tan contentos conmigo que me dan todo lo que les pido, escuchan mis maldades contra otros compa\u00f1eros y me tienen en cuenta siempre para los ascensos.<br \/>SUBSECRETARIO: Secretario, enc\u00e1rguese del Jefe de Gabinete, que anda un poco d\u00edscolo y va un poco por libre.<br \/>SECRETARIO: Montar\u00e9 una campa\u00f1a de prensa para que sea difamado convenientemente. As\u00ed acabaremos con su carrera pol\u00edtica en poco tiempo. No se come el turr\u00f3n en su puesto. (Aparte). Ya se sabe: los peores enemigos son siempre los de tu propia casa.<br \/>MINISTRO: Secretario, lleve el sobre con la dimisi\u00f3n al Director General de Asuntos Menores. El muy z\u00e1ngano se est\u00e1 metiendo en asuntos mayores.<br \/>SECRETARIO: A qui\u00e9n se le ocurre. Con lo f\u00e1cil que es obedecer. (Aparte) Y los buenos resultados que reporta.<br \/>PRESIDENTE: Necesitamos un voluntario para que se encargue del dossier que demuestre que el Jefe de la Oposici\u00f3n es un alcoh\u00f3lico empedernido, un jugador camorrista, un mujeriego irredento, un lud\u00f3pata irrecuperable y un cabecilla de la mafia. Que aparezca tambi\u00e9n como un esp\u00eda doble y como un posible terrorista de Al Qaeda.<br \/>SECRETARIO: D\u00e9jelo de mi cuenta. Cuando termine el informe no lo va a conocer ni la madre que lo pari\u00f3. La oposici\u00f3n quedar\u00e1 destruida para seis legislaturas (Aparte). Alguien tiene que hacer el trabajo sucio. Es la actividad que m\u00e1s beneficios procura al que se dedica a la escalada pol\u00edtica.<br \/>SUBSECRETARIO: Secretario, oc\u00fapese de hacer un c\u00e1sting para seleccionar a los miembros m\u00e1s embusteros y falsarios del Partido. Ser\u00e1n los encargados de redactar el Programa Electoral para las pr\u00f3ximas elecciones Generales.<br \/>SECRETARIO: Me pongo a la tarea. Reconozco a esos personajes a distancia. Son de los m\u00edos.<br \/>MINISTRO: Secretario, ponga en marcha un plan para convencer a los ciudadanos de la necesidad de los pol\u00edticos, especialmente de los nuestros. No escatime medios. Use la televisi\u00f3n, Internet, las vallas publicitarias, todo. No se preocupe por la financiaci\u00f3n. Los funcionarios dan mucho juego y sus sueldos, m\u00e1s.<br \/>SECRETARIO: Marchando una de lavado de cerebros.<br \/>PRESIDENTE: Secretario, enc\u00e1rguese de seleccionar a los responsables de redactar el proyecto de los nuevos Estatutos del Partido. Procure que no sepan leer ni escribir.<br \/>SECRETARIO (dirigi\u00e9ndose al proscenio. Cambio de luz): Ellos piensan que son poderosos y que me tienen a su servicio. La realidad es que yo los uso como m\u00e1s me conviene y como mejor pueden servir a mis intereses. (Con complicidad). Estar\u00e9is de acuerdo conmigo en que hay que reconocer que soy un hombre con talento.<br \/>(Oscuro y melod\u00eda. Tres de los personajes retirar\u00e1n sendas sillas al hacer mutis por el foro).<\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/cuadro04.jpg\" alt=\"\" width=\"133\" height=\"100\" \/><span style=\"font-size: 20px;\">CUADRO IV:ESCR\u00daPULOS<\/span><\/p><\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><span style=\"font-weight: bold;\">PERSONAJES: Director General, Compa\u00f1ero 1, Compa\u00f1ero 2, Compa\u00f1ero 3<\/span><br \/>(En escena no habr\u00e1 m\u00e1s que la mesa y una silla, para dar m\u00e1s impresi\u00f3n de soledad en el Director General. Los dem\u00e1s deambular\u00e1n a su alrededor como los personajes de un sue\u00f1o).<br \/>DIRECTOR GENERAL (Con aire compungido): Yo era un hombre honrado. A serlo me empujaba mi natural decente y el trabajo minucioso y concienzudo de unos padres entregados a dotarme de unas virtudes, que me sirvieran de bagaje para la vida. \u00a1Qu\u00e9 cosas ten\u00edan los padres de antes! \u00a1Qu\u00e9 antiguos eran! \u00a1Qu\u00e9 honrados? Creo que sigo sinti\u00e9ndome un hombre honesto, que en realidad soy un hombre prostituido, pero honrado, porque siento y sufro porque no puedo serlo, porque para serlo tendr\u00eda que renunciar a mis actividades.<br \/>No, no soy un personaje sin escr\u00fapulos, que no siente las molestias que causa y el da\u00f1o que originan sus decisiones y sus comportamientos. Yo lo siento y lo sufro, pero no puedo hacer otra cosa o\u2026o pierdo mi trabajo y el presente y el futuro de mis hijos y\u2026\u00bfy ad\u00f3nde podr\u00eda ir yo ahora, con 50 a\u00f1os y sin saber hacer otra cosa que no sea medrar, intrigar y buscar la manera de eludir zancadillas y\u2026ponerlas.<br \/>Pero yo quiero ser honrado, porque tengo escr\u00fapulos y lamento los estragos que causo. Yo quiero ser honrado, pero\u2026no me dejan. Suena a excusa, ya lo s\u00e9, pero es la verdad. Cuando empec\u00e9 en esto de la pol\u00edtica, una simple concejal\u00eda de mi pueblo, entr\u00e9 en mi nuevo puesto con la mejor intenci\u00f3n. Quer\u00eda cambiar el mundo y como un Quijote me lanc\u00e9, sin yelmo y sin celada, a desfacer entuertos y a socorrer desvalidos. Con la lanza de mi integridad y con el escudo de mi bonhom\u00eda, empec\u00e9 mi noble labor y comenzaron mis problemas. La primera vez que rechac\u00e9 un regalo recib\u00ed los primeros avisos\u2026<br \/>COMPA\u00d1ERO 1 (asomando la cabeza por un lateral): No puedes hacer eso; nos pones a todos en evidencia.<br \/>COMPA\u00d1ERO 2 (asomando la cabeza por el otro lateral): No puedes desairar de esa forma a Don Cosme.<br \/>COMPA\u00d1ERO 3 (asomando la cabeza por el primer lateral): Es uno de los nuestros.<br \/>COMPA\u00d1ERO 1 (Vuelve a asomarse): Y nos apoya.<br \/>COMPA\u00d1ERO 2 (vuelve a asomarse): Y nos financia.<br \/>COMPA\u00d1ERO 3 (vuelve a asomarse): Y nos compra.<br \/>DIRECTOR GENERAL: La primera vez que renunci\u00e9 a una comisi\u00f3n\u2026<br \/>COMPA\u00d1ERO 1 (asomando la cabeza por un lateral): \u00bfQui\u00e9n te crees que eres?<br \/>COMPA\u00d1ERO 2 (asomando la cabeza por el otro lateral): Nos dejas a los pies de los caballos.<br \/>COMPA\u00d1ERO 3 (asomando la cabeza por el primer lateral): As\u00ed no se hacen las cosas aqu\u00ed.<br \/>COMPA\u00d1ERO 1 (Vuelve a asomarse): Tienes que cobrar.<br \/>COMPA\u00d1ERO 2 (vuelve a asomarse): Tienes que cobrar.<br \/>COMPA\u00d1ERO 3 (vuelve a asomarse): Tienes que cobrar.<br \/>DIRECTOR GENERAL (sin salir del agobio que siente ante las imprecaciones de sus compa\u00f1eros): Pero cuando m\u00e1s se enfurecieron fue la primera vez que no quise coger el sobre\u2026 Llegaron al insulto.<br \/>COMPA\u00d1ERO 1 (asomando la cabeza por un lateral): Pero, c\u00f3mo. \u00bfQu\u00e9 vas, de puro?<br \/>COMPA\u00d1ERO 2 (asomando la cabeza por el otro lateral): \u00bfC\u00f3mo puedes hacernos esto?<br \/>COMPA\u00d1ERO 3 (asomando la cabeza por el primer lateral): Vas a hundir al partido.<br \/>COMPA\u00d1ERO 1 (Vuelve a asomarse): Este t\u00edo es imb\u00e9cil.<br \/>COMPA\u00d1ERO 2 (vuelve a asomarse): Este hombre no vive en la realidad.<br \/>COMPA\u00d1ERO 3 (vuelve a asomarse): \u00a1Qu\u00e9 t\u00edo m\u00e1s jilipollas!<br \/>Y as\u00ed, siempre que quise jugar limpio. Lo del cargo es indiferente. Suced\u00eda cuando era concejal y ocurre ahora que soy director general. El sistema est\u00e1 pervertido y en el nivel que te muevas te encuentras con las mismas condiciones, con el mismo contexto asfixiante, que te obliga y te marca los comportamientos y los l\u00edmites y los caminos. No tienes nada que hacer. O entras en el redil o te echan. No hay m\u00e1s.<br \/>(Cambiando de tono y haci\u00e9ndolo m\u00e1s confidencial) y menos pesaroso) Me lo dijo al poco tiempo de empezar. El chico no era de mi partido, pero congeniamos y nos cogimos mutua simpat\u00eda. O te vuelves uno de los nuestros o te buscas otro negocio. Se ve que ya hab\u00eda vencido los escr\u00fapulos suficientes como para poder dar consejos. Y \u00bfqu\u00e9 hice yo entonces? Protestar, reafirmarme en mis valores \u00e9ticos y, a la vez, empezar a ir metiendo la cabeza en aquella cofrad\u00eda. \u00a1Madre m\u00eda! Y con qu\u00e9 rapidez se aprenden estas cosas. Cada vez peleaba menos por mis principios, por una gesti\u00f3n limpia, por un trabajo transparente y eficaz. Y cada vez me iba hundiendo m\u00e1s y m\u00e1s en la corriente general de ignominia y degradaci\u00f3n.<br \/>Y empec\u00e9 a aceptar algunos regalos y a trincar comisiones y a coger los sobres. Y termin\u00e9 cogiendo todos los regales y exigiendo cada vez m\u00e1s comisiones y preguntando cada final de mes cu\u00e1ndo me daban el negro. Y he aprendido a motivar (hace el gesto de comprar) a periodistas, a regalar subvenciones innecesarias y caprichosas, a trabajar en mi provecho y a olvidar el \u00fanico objetivo que deb\u00eda tener mi tarea, mi trabajo: el bien com\u00fan.<br \/>Y como a\u00fan me queda dentro algo de lo que fui, ahora tengo que asistir con malestar (os puedo asegurar que esto nos pasa a muy pocos) cada vez mayor al espect\u00e1culo lamentable de la gente que se deja el sueldo y las ilusiones, enterrados en la mierda que hemos construido o tolerado (cada vez m\u00e1s indignado), de la gente que se queda sin sustento, del empobrecimiento general, de la p\u00e9rdida de derechos ganados con sangre y con l\u00e1grimas; de tantas ilusiones frustradas, de asistencias imprescindibles eliminadas, de tantos recortes injustos, de la apat\u00eda y el abandono que generan la p\u00e9rdida de horizontes\u2026de\u2026Y todo por culpa de un\u2026<br \/>Estoy pensando que en un arrebato de estos de dignidad no tendr\u00e9 m\u00e1s remedio que hablar y denunciar\u2026<br \/>TODOS LOS COMPA\u00d1EROS (al un\u00edsono y avanzando dos pasos hacia \u00e9l): \u00a1Fuera del partido!<br \/>(Se hace el oscuro y suena la sinton\u00eda. Dos actores colocar\u00e1n la mesa a la izquierda de la escena con la silla. A la derecha se colocar\u00e1 un atril).<br \/>DIRECTOR GENERAL: \u00a1Fuera del Partido!<\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/cuadro05.jpg\" alt=\"\" width=\"139\" height=\"99\" \/><span style=\"font-size: 20px;\">CUADRO V: TRADUCCI\u00d3N SIMULT\u00c1NEA<\/span><\/p><\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><span style=\"font-weight: bold;\">PERSONAJES: Diputado, Traductor<\/span><br \/>El personaje del DIPUTADO se adelanta al proscenio, despu\u00e9s de haber colocado con el personaje del TRADUCTOR, un atril y una mesa con su silla, ambos orientados hacia la sala, durante los breves instantes que durar\u00e1 el oscuro y la sinton\u00eda musical de la obra, uno de los hilos conductores de la misma).<br \/>No es verdad que los pol\u00edticos manejen un lenguaje vac\u00edo y desprovisto de significado. No es verdad. \u00bfLo sabr\u00e9 yo que me dedico a traducirlos? No hay ni un solo pol\u00edtico que d\u00e9 puntada sin hilo. Hasta los m\u00e1s incompetentes saben que detr\u00e1s de sus palabras hay un c\u00f3digo que transmite unos significados, unos valores, unos sentimientos. Su lenguaje no es el com\u00fan que usan los mortales, los acad\u00e9micos, los cient\u00edficos y los comerciantes. Es sencillamente, el lenguaje de los pol\u00edticos, profundamente insignificante hacia afuera, pero extremadamente significativo hacia adentro.<br \/>DIPUTADO (siempre con tono mitinero y exaltaci\u00f3n controlada): Queridos amigos y compa\u00f1eros.<br \/>TRADUCTOR (siempre en tono sosegado de traducci\u00f3n simult\u00e1nea, sin expresar matices y en inflexi\u00f3n monocorde): Queridos ingenuos y d\u00f3ciles borregos.<br \/>DIPUTADO: Hoy vengo a ofreceros mi absoluto compromiso con esta hermosa y encantadora ciudad.<br \/>TRADUCTOR: Tengo que empezar halagando vuestro ego para predisponeros positivamente hacia mi objetivo.<br \/>DIPUTADO: Mi partido velar\u00e1 siempre por vuestro bienestar y por que ni una sola de vuestras necesidades quede sin satisfacer.<br \/>TRADUCTOR: Mi partido no se ocupar\u00e1 nunca m\u00e1s de vosotros hasta la pr\u00f3xima vez que se convoquen elecciones.<br \/>DIPUTADO: Somos consciente de los momentos de dificultades que estamos pasando.<br \/>TRADUCTOR: Sabemos que est\u00e1is viviendo por encima de vuestras posibilidades.<br \/>DIPUTADO: Que la crisis es el resultado de las pol\u00edticas equivocadas del partido que ocup\u00f3 el gobierno antes de nosotros.<br \/>TRADUCTOR: Que la crisis responde al af\u00e1n especulativo de los agentes financieros, pero me interesa m\u00e1s cargarla en la responsabilidad de la oposici\u00f3n y en vuestro despilfarro.<br \/>DIPUTADO: Su falta de sensibilidad hacia los m\u00e1s desfavorecidos. Su deprecio hacia las pol\u00edticas sociales\u2026<br \/>TRADUCTOR: Esta es justamente nuestra ideolog\u00eda, pero conviene ponerla en el debe de los otros\u2026<br \/>DIPUTADO: Han provocado esta situaci\u00f3n actual de empobrecimiento y desamparo de las clases m\u00e1s desfavorecidas.<br \/>TRADUCTOR: \u00bfQu\u00e9 co\u00f1o hacen los pobres pretendiendo ser como los ricos?<br \/>DIPUTADO: Yo vengo a proponer una regeneraci\u00f3n de la pol\u00edtica, una regeneraci\u00f3n de la sociedad.<br \/>TRADUCTOR: Yo vengo a convenceros para que me sig\u00e1is votando a pesar de lo que digan de m\u00ed.<br \/>DIPUTADO: La p\u00e9rdida de valores est\u00e1 en la base de nuestra precaria situaci\u00f3n actual.<br \/>TRADUCTOR: Ten\u00e9is lo que merec\u00e9is por confiar en gente como nosotros.<br \/>DIPUTADO: El dinero debe subordinarse a los elevados principios que han de regir nuestro comportamiento.<br \/>TRADUCTOR: El dinero es la clave de todo y es el dios al que siempre rendiremos nuestra pleites\u00eda.<br \/>DIPUTADO: Los grandes principios que orientan nuestro programa\u2026<br \/>TRADUCTOR: Nuestro programa solo contiene vaguedades y promesas imposibles de consumar.<br \/>DIPUTADO: Son la solidaridad y el bienestar para todos los ciudadanos, al margen de su orientaci\u00f3n ideol\u00f3gica, por encima de a qui\u00e9n voten o dejen de votar.<br \/>TRADUCTOR: Vamos a intentar instalarnos en el poder y a beneficiarnos de los privilegios que \u00e9ste otorga, por encima de cualquier veleidad igualitaria.<br \/>DIPUTADO: Pod\u00e9is tener la seguridad de que ninguna de vuestras reivindicaciones quedar\u00e1 sin atender, porque son justas y necesarias.<br \/>TRADUCTOR: Pod\u00e9is tener la seguridad de que pasaremos ampliamente de todas vuestras demandas, porque est\u00e1n injustificadas y son innecesarias<br \/>DIPUTADO: Merec\u00e9is un pueblo m\u00e1s moderno, una presencia m\u00e1s constante en nuestras preocupaciones de gobierno.<br \/>TRADUCTOR: \u00bfQu\u00e9 m\u00e1s quer\u00e9is, si viv\u00eds en un lugar privilegiado? \u00a1Como si no tuvi\u00e9ramos otras cosas de qu\u00e9 ocuparnos.<br \/>DIPUTADO: Os voy a poner un ejemplo de entrega y de sacrificio por los dem\u00e1s. Hoy tenemos la enorme suerte de tener entre nosotros al vicepresidente primero del Gobierno, que ha querido acompa\u00f1arnos en esta jornada radiante de esperanza para nuestro pueblo y nuestra comunidad.<br \/>TRADUCTOR: Os voy a poner un ejemplo de personaje sin escr\u00fapulos y arribista sin consideraci\u00f3n. Se trata del vicepresidente del Gobierno. \u00c9l ha venido hoy aqu\u00ed a robarme el protagonismo y a soltaros unas cuantas mentiras envueltas en buenas palabras.<br \/>DIPUTADO: Su trayectoria es una singladura limpia e irreprochable, repleta de grandes servicios al Estado y al Partido, que nunca le podremos agradecer de forma suficiente.<br \/>TRADUCTOR: Su trayectoria pol\u00edtica est\u00e1 jalonada por una ristra indecente de servilismo y peloteo indecentes, de sumisi\u00f3n y sometimiento a todo aquel que pudiera beneficiar sus intereses y sus ambiciones.<br \/>DIPUTADO: Pero antes de cederle la palabra, quiero terminar mi intervenci\u00f3n dici\u00e9ndoos que no pens\u00e9is que estoy hoy aqu\u00ed para pediros el voto y despu\u00e9s desaparecer como alma que lleva el diablo. Eso es lo que hacen los otros\u2026<br \/>TRADUCTOR: Sabed que solo he venido a robaros vuestro apoyo para poderme quedar despu\u00e9s con vuestra hacienda\u2026<br \/>DIPUTADO: que cogen el voto, como un bot\u00edn de guerra y corren con \u00e9l para apoltronarse y servir a sus propios intereses.<br \/>TRADUCTOR: que hacen lo mismo que yo voy a hacer, pero con m\u00e1s desverg\u00fcenza y m\u00e1s arte que ellos.<br \/>DIPUTADO: Yo voy a pelear por vuestras carreteras<br \/>TRADUCTOR: Yo voy a luchar por mis coches.<br \/>DIPUTADO: Por vuestros puestos de trabajo.<br \/>TRADUCTOR: Por el trabajo de mi familia y de mis amigos.<br \/>DIPUTADO: Por vuestra seguridad.<br \/>TRADUCTOR: Por mi seguridad.<br \/>DIPUTADO: Por vuestra libertad<br \/>TRADUCTOR: Por mis intereses.<br \/>DIPUTADO: Por vuestra cultura<br \/>TRADUCTOR: Por vuestra ignorancia.<br \/>DIPUTADO: Por vuestro futuro.<br \/>TRADUCTOR: Por mi porvenir.<br \/>(Se hace el OSCURO y la M\u00daSICA de la SINTON\u00cdA vuelve a marcar el ritmo del cambio de ambientaci\u00f3n para la pr\u00f3xima escena. La mesa permanece a la izquierdo incorporando una silla m\u00e1s. A la derecha, se sustituye el atril por otra mesa con dos sillas).<\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/cuadro06.jpeg\" alt=\"\" width=\"139\" height=\"99\" \/><span style=\"font-size: 20px;\">CUADRO VI:ECONOM\u00cdA Y JUSTICIA<\/span><\/p><\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><span style=\"font-weight: bold;\">PERSONAJES: Ministro de Econom\u00eda y Hacienda, Director General de Econom\u00eda, Ministro de Justicia, Director General de Instituciones Penitenciarias.<\/span><br \/><br \/>A un lado y otro del escenario, los actores, durante el oscuro, colocar\u00e1n sendas mesas, donde despachar\u00e1n los dos ministros con sus respectivos directores generales. La acci\u00f3n ir\u00e1 alternando con agilidad uno y otro di\u00e1logo, que en algunos momentos se volver\u00e1 trepidante. Se hace la luz sobre la parte izquierda donde est\u00e1n colocados el Ministro de Econom\u00eda y su Director General. La otra parte de la escena permanece en oscuro.<br \/>DIRECTOR GENERAL DE ECONOM\u00cdA (En el proscenio): La Econom\u00eda. \u00bfQui\u00e9n entiende de Econom\u00eda? Ni los grandes sabios de esta ciencia se ponen de acuerdo. Que si control del d\u00e9ficit, que si est\u00edmulos al crecimiento; que si subir los impuestos, que si bajarlos; que si mercado libre, que si econom\u00eda planificada. M\u00e1s que una ciencia, esto es un arte. (Con piller\u00eda) El arte de conseguir que siempre paguen los mismos y que siempre ganen los de siempre (Se dirige hacia la mesa donde lo espera el Ministro).<br \/>MINISTRO DE ECONOM\u00cdA: Buenos d\u00edas, Rodr\u00edguez. \u00bfQu\u00e9 buenas me trae hoy?<br \/>D.G. de ECONOM\u00cdA: Buenas, ninguna; alguna regular y la mayor\u00eda, malas, tirando a peores.<br \/>MINISTRO DE ECONOM\u00cdA: Bien. Usted siempre tan positivo y optimista.<br \/>D.G. de ECONOM\u00cdA: Es que, se\u00f1or, la situaci\u00f3n econ\u00f3mica del pa\u00eds no invita a alegr\u00edas.<br \/>MINISTRO DE ECONOM\u00cdA: Habr\u00e1 que seguir tomando medidas sin que nos tiemble el pulso.<br \/>D.G. de ECONOM\u00cdA: La situaci\u00f3n en la calle cada vez est\u00e1 m\u00e1s alterada. La gente se empieza a rebelar y surgen protestas por todas partes.<br \/>MINISTRO DE ECONOM\u00cdA: Tener la piel dura ante las protestas y el coraz\u00f3n de piedra ante las decisiones dif\u00edciles y dolorosas que hemos de tomar, forma parte de nuestro trabajo y est\u00e1 recogido en nuestro salario. Tome nota luego de las propuestas que llevaremos al pr\u00f3ximo Consejo de Ministros. Ahora veamos esos asuntos.<br \/>(En este momento, la luz se traslada a la parte derecha para iluminar la escena que comienzan el Ministro de Justicia y su Director General. La parte izquierda queda en oscuro).<br \/>MINISTRO DE JUSTICIA (se levanta y va hacia el proscenio): La Justicia con may\u00fasculas es representada por una diosa ciega. Ciegos somos nosotros, los seres humanos que recogemos ingenuamente el deber de representarla. La Justicia es una aspiraci\u00f3n, un ideal, pero nunca ser\u00e1 una realidad, una posibilidad efectiva. La Justicia es un camino largo, largo\u2026 Largo y plagado de trampas y recovecos que nos impiden llegar a la meta. (Se dirige a la mesa, donde lo espera su Director General, y se sienta). Usted dir\u00e1, Mart\u00ednez.<br \/><br \/>DIRECTOR GENERAL DEL RAMO: Pues, Se\u00f1or, aqu\u00ed traigo la carpeta cargada de asuntos pendientes. Cada vez hay m\u00e1s ciudadanos que reclaman y utilizan los juzgados para presentar quejas, querellas y zarandajas.<br \/>MINISTRO DE JUSTICIA: \u00a1Ay, estamos consiguiendo que se judicialice la vida!. Ya nadie llega a acuerdos particulares; todo el mundo necesita de un \u00e1rbitro para dirimir sus cuitas. Eso es una gran desgracia social. Tendremos que tomar medidas.<br \/>DIRECTOR GENERAL: Antiguamente solo reclamaban los pudientes. Hoy, cualquier mequetrefe se siente con derecho a requerir y a demandar. \u00a1Qu\u00e9 atrevimiento!<br \/>MINISTRO DE JUSTICIA: Bien, habr\u00e1 que adoptar algunas decisiones. Las llevaremos al pr\u00f3ximo Consejo de Ministros.<br \/>(En este momento se hace la luz para iluminar a la vez las dos escenas y el di\u00e1logo ir\u00e1 pasando de lado a otro con creciente intensidad).<br \/>D.G. DE ECONOM\u00cdA: Como bien sabe, Se\u00f1or Ministro, la Banca est\u00e1 descapitalizada, ha perdido todos los ahorros de los espa\u00f1oles exponi\u00e9ndolos a operaciones especulativas de enorme riesgo. Los banqueros exigen al Gobierno que solvente semejante desaguisado o no podr\u00e1n seguir manteniendo el sistema.<br \/>MINISTRO DE ECONOM\u00cdA: Del sistema, amigo m\u00edo, formamos parte nosotros tambi\u00e9n. Esto no puede irse al infierno. Hay que inyectar todo el dinero que necesiten.<br \/>D.G. DE ECONOM\u00cdA: El dinero es limitado, se\u00f1or Ministro, habr\u00e1 que tomar medidas impopulares contra la poblaci\u00f3n.<br \/>MINISTRO DE ECONOM\u00cdA: La poblaci\u00f3n tambi\u00e9n forma parte del sistema. Que arrime el hombro.<br \/>D.G DE I. PENITENCIARIAS: Se\u00f1or Ministro, el yerno de su Majestad acaba de ser condenado por su implicaci\u00f3n en todos los delitos econ\u00f3micos tipificados en el C\u00f3digo Penal. Solicita le sea conmutada la sentencia de seis meses de trabajos sociales, por unas vacaciones subvencionadas en Santo Domingo.<br \/>MINISTRO DE JUSTICIA: Concedido. No hay que ponerse a mal con la nobleza.<br \/>D.G DE I. PENITENCIARIAS: Otro asunto: un colectivo de madres de ni\u00f1os desaparecidos solicitan ser recibidas por usted para informarle sobre la problem\u00e1tica\u2026<br \/>MINISTRO DE JUSTICIA: Ya tengo yo bastante problem\u00e1tica. Rec\u00edbalas usted y h\u00e1gales una faena de ali\u00f1o para que se marchen en paz.<br \/>D. G. DE ECONOM\u00cdA: La Duquesa del Amanecer solicita una subvenci\u00f3n para vallar las 35 fincas, que ocupan una extensi\u00f3n de\u2026<br \/>MINISTRO DE ECONOM\u00cdA: Concedida. M\u00e1s asuntos.<br \/>D.G. DE ECONOM\u00cdA: El barrendero de los patios y jardines del Ministerio solicita una nueva escoba para optimizar su tiempo y as\u00ed\u2026<br \/>MINISTRO: Denegado. Que barra como ha barrido siempre. \u00bfQu\u00e9 delicadezas son esas?<br \/>D. G. DE I. PENIENCIARIAS: Se\u00f1or Ministro, el compa\u00f1ero Mangante ha escamoteado dos mil millones de la Fundaci\u00f3n de Asuntos Asombrosos. Espera conocer nuestra disposici\u00f3n.<br \/>MINISTRO DE ECONOM\u00cdA: Ponga al Equipo Jur\u00eddico del Departamento a estudiar el tema y que le den carpetazo cuanto antes. Estas cosas no deben trascender a la Opini\u00f3n P\u00fablica.<br \/>D.G DE I. PENITENCIARIAS: Ahora (Buscando en los papeles o en el ordenador) tengo por aqu\u00ed el asunto que despachamos todas las semanas. El chico aquel que fue condenado injustamente y sin pruebas y que est\u00e1 en prisi\u00f3n a la espera de\u2026<br \/>MINISTRO DE JUSTICIA: Que espere un poco, porque tenemos muchos temas pendientes que tratar. \u00bfEs que todav\u00eda no se ha acostumbrado a la c\u00e1rcel? Le regalamos el mantenimiento y no se le ocurre otra cosa que exigir.<br \/>D. G. DE ECONOM\u00cdA: Otro asunto: La Iglesia reclama su derecho a seguir manteniendo sus privilegios fiscales\u2026<br \/>MINISTRO DE ECONOM\u00cdA: \u00a1Con la Iglesia hemos topado! Concedido. Ya le pediremos al pueblo un peque\u00f1o esfuerzo m\u00e1s para compensar la p\u00e9rdida de esos ingresos.<br \/>D. G. DE ECONOM\u00cdA: Aqu\u00ed tenemos varias asociaciones sin \u00e1nimo de lucro que solicitan tambi\u00e9n una especial consideraci\u00f3n fiscal dado el car\u00e1cter altruista de su labor.<br \/>MINISTRO: Nosotros no estamos aqu\u00ed para aplaudir la generosidad, sino para administrar los recursos p\u00fablicos de forma justa y equilibrada. Que paguen como todo el mundo\u2026 (gesto c\u00f3mico)\u2026 Como todo el mundo que paga.<br \/>D. G. DE I. PENITENCIARIAS: La familia del conductor suicida que atropell\u00f3 mortalmente a un peque\u00f1o en la Autov\u00eda solicita el indulto bas\u00e1ndose en su amistad con los altos cargos del partido y esperan que usted sea sensible a dicha circunstancia\u2026<br \/>MINISTRO DE JUSTICIA: Concedido. Entre bomberos no nos pisemos la manguera.<br \/>D.G. DE I. PENITENCIARIAS: Tenemos pendiente el asunto de la madre que solicita la conmutaci\u00f3n de la pena que fue impuesta a su hijo por insultar al Se\u00f1or Presidente llam\u00e1ndole \u00a1ingenuo! (llev\u00e1ndose las manos a la cabeza). Madre de Dios, nada menos que ingenuo.<br \/>MINISTRO DE JUSTICIA: Eso es algo intolerable. Ya mismo lo llamar\u00e1n incompetente y otras barbaridades. Que cumpla su castigo y que pague la multa, que estamos sin un c\u00e9ntimo.<br \/>(A partir de ahora el di\u00e1logo se vuelve m\u00e1s vivo y el cambio de una escena a otra, m\u00e1s acelerado).<br \/>D. G. DE ECONOM\u00cdA: El cu\u00f1ado del Presidente no ha hecho la declaraci\u00f3n de la renta\u2026<br \/>MINISTRO DE ECONOM\u00cdA: Se la haces t\u00fa y listo. Y que salga negativa, ya sabes.<br \/>D. G. DE I. PENITENCIARIAS: Un ciudadano reclama una multa de tr\u00e1fico de 100 euros.<br \/>MINISTRO DE JUSTICIA: Que le cobren una tasa de 500.<br \/>D. G DE ECONOM\u00cdA: Un millonario norteamericano quiere abrir un casino en Espa\u00f1a, pero pone como condici\u00f3n que se permita fumar en sus instalaciones.<br \/>MINISTRO DE ECONOM\u00cdA: Que sea obligatorio fumar en el casino. Que no se contrate a nadie que no sea fumador. Estamos como para perder inversiones.<br \/>D. G. DE I. PENITENCIARIAS: El peri\u00f3dico La Tarde insiste en sus cr\u00edticas hacia su reforma de\u2026<br \/>MINISTRO DE JUSTICIA: Que le retiren la subvenci\u00f3n a ese diario.<br \/>D. G. DE ECONOM\u00cdA: El casino de su pueblo solicita una ayuda para\u2026<br \/>MINISTRO DE ECONOM\u00cdA: Concedida.<br \/>D. G. DE I. PENITENCIARIAS: Un pobre ha recurrido\u2026<br \/>MINISTRO DE JUSTICIA: Denegado.<br \/>D. G. DE ECONOM\u00cdA: Su secretaria lo espera en la Cafeter\u00eda de\u2026<br \/>MINISTRO DE ECONOM\u00cdA: Deje el resto de asuntos para la semana que viene.<br \/>D. G. DE I. PENITENCIARIAS: Su se\u00f1ora lo espera en la \u00f3pera\u2026<br \/>MINISTRO DE JUSTICIA: contin\u00fae con los asuntos pendientes, Mart\u00ednez.<br \/>(Oscuro y Sinton\u00eda mientras se coloca una tarima debajo de una de las mesas para que el Mercado quede en un plano superior al de los otros personajes).<\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/cuadrosiete.jpg\" alt=\"\" width=\"134\" height=\"100\" \/><span style=\"font-size: 20px;\">CUADRO VII:EL MERCADO<\/span><\/p><\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><span style=\"font-weight: bold;\">PERSONAJES: Presidente, Ministro de Hacienda, Mercado<\/span><br \/>(En una de las mesas despachar\u00e1n el Presidente y el Ministro de Hacienda, mientras en la otra, y en un plano superior, se colocar\u00e1 el personaje que representa al Mercado).<br \/>PRESIDENTE: Me ha llamado Merkel. Me presiona Obama. \u00bfQu\u00e9 hago? El mercado reclama medidas, ajustes para controlar el d\u00e9ficit. Los inversores nos dar\u00e1n la espalda si no cumplimos con el deber de devolver lo que nos prestan. A partir de ahora la mayor parte de lo que ingresemos tendr\u00e1 que ir al pago de las deudas que hemos contra\u00eddo. El dinero es insensible; el mercado no tiene coraz\u00f3n. Nosotros tenemos que empezar por perderlo para poder ejercer nuestra tarea.<br \/>MERCADO: Los principios, se\u00f1or presidente, los ideales, no son m\u00e1s que utop\u00eda. Utop\u00eda que calienta el cerebro y no permite tomar las decisiones adecuadas. Aprenda de nosotros, del Mercado. No nos guiamos m\u00e1s que por una l\u00f3gica, la del beneficio. Si el mercado gana todos ganan. Si el Mercado pierde es la ruina para todos.<br \/>MINISTRO: Se\u00f1or Presidente, la situaci\u00f3n ha llegado a un l\u00edmite que ya no valen pa\u00f1os calientes. Hay que tomar medidas dr\u00e1sticas y radicales. (Saca unas tijeras enormes que llevaba detr\u00e1s de la espalda). Aqu\u00ed tiene la herramienta imprescindible.<br \/>PRESIDENTE (El Presidente las coge y las coloca sobre la mesa y blandi\u00e9ndolas, dice): Como dijo Groucho Marx: \u201cEstos son mis principios: si no le gusta, tengo otros\u201d. Veamos qu\u00e9 podemos hacer. (Deja las enormes tijeras sobre la mesa).<br \/>MERCADO: Como primer mandamiento: apoyar a la Banca; como primera medida, inyectarle dinero; como primero objetivo, supeditarlo todo a su saneamiento.<br \/>PRESIDENTE: Pero la banca y sus due\u00f1os son los que han generado esta penosa situaci\u00f3n, por dedicarse a especular, a multiplicar el dinero f\u00e1cil y por no apoyar proyectos fruct\u00edferos de la econom\u00eda productiva.<br \/>MERCADO: Pero la gente no puede saber eso. Tenemos que hacer que los ciudadanos asuman que la crisis es la consecuencia de sus excesos, de haber vivido por encima de sus posibilidades. Tenemos que convencerlos de que han ganado mucho, han gastado m\u00e1s y han terminado creando esta org\u00eda de paro y empobrecimiento entre sus filas.<br \/>MINISTRO: Habr\u00e1 que hacerles creer que tienen que renunciar, por su bien, a los derechos adquiridos, a la sanidad y a la educaci\u00f3n gratuitas, a una jubilaci\u00f3n decente\u2026<br \/>MERCADO: \u00a1Ay, el Estado de Bienestar! \u00a1Qu\u00e9 invento m\u00e1s nefasto! No nos ha tra\u00eddo m\u00e1s que problemas. Igualdad, derechos, participaci\u00f3n, solidaridad, pensiones, dignidad\u2026Pamplinas, inventos de los pol\u00edticos, que no ten\u00e9is los pies en la realidad.<br \/>PRESIDENTE: Muy al contrario. Somos tan realistas, que estamos siempre dispuestos a adaptarnos a cualquier realidad. Aqu\u00ed estamos, al servicio del Mercado, a tus \u00f3rdenes, a las \u00f3rdenes del capital, aunque nos cueste el puesto. Cuando haya que rendir pleites\u00eda a los ideales, lo haremos de la misma manera. Ser pol\u00edtico es tener una absoluta capacidad de adaptaci\u00f3n.<br \/>MERCADO: El puesto se conserva haciendo lo que se debe hacer en cada caso. Y ahora lo que hay que hacer es usar esas tijeras que le ha regalado el ministro. Podar, cortar, recortar, eliminar, suspender, diferir, prescindir\u2026<br \/>MINISTRO: \u00bfNo estar\u00e9is (duda), no estaremos yendo demasiado lejos al forzar la situaci\u00f3n de una manera tan dr\u00e1stica?<br \/>MERCADO: La contundencia, amigos m\u00edos, es la clave para resolver estos asuntos. Hay que golpear antes de que tengan tiempo de organizarse; dar los palos precisos cuando el enemigo est\u00e1 descuidado.<br \/>PRESIDENTE: (Con un resto de dignidad): Pero es que no debi\u00e9ramos considerar al pueblo como nuestro enemigo. El pueblo es el que nos asigna esta responsabilidad y debi\u00e9ramos\u2026<br \/>MERCADO: El pueblo desconoce sus intereses; tan solo necesita consignas, orientaci\u00f3n. Los ciudadanos tienen que asumir que lo que le proponemos es lo que m\u00e1s les interesa, lo \u00fanico que les interesa. Hay que desmontar ese maldito Estado del Bienestar, que no ha tra\u00eddo m\u00e1s que trabajadores holgazanes y sindicatos tocacojones.<br \/>PRESIDENTE: Si al menos hubiera una tercera v\u00eda, una posibilidad de compromiso. Pongamos que ni Estado de Derecho, pero tampoco Liberalismo Salvaje. Digamos que un compromiso entre el Liberalismo y el control estatal, que dome\u00f1ara un tanto sus desaforadas ambiciones y paliara su nefasta tendencia a dejar en la estacada a tantos y tantos marginados que no caben en el sistema.<br \/>MERCADO: Palabras. Nada m\u00e1s que palabras. Lo que hay que hacer es tomar medidas urgentes para que los poderosos cada vez lo sean m\u00e1s. Ellos son los que han de crear riqueza para todos y solo lo har\u00e1n si no ven limitadas sus posibilidades de enriquecimiento. Para eso hay que tomar las medidas, que, sin duda, continuar\u00e9is adoptando de aqu\u00ed en adelante, Esta es la \u00faltima palabra.<br \/>MINISTRO: Creo, Se\u00f1or Presidente, que tendremos que usar las tijeras y por mucho tiempo.<br \/>MERCADO: Estaremos pendientes de todos vuestros movimientos. Si os port\u00e1is bien y sois aplicados, tendr\u00e9is todo nuestro apoyo, seguir\u00e9is en el mundo civilizado y recibir\u00e9is pr\u00e9stamos en condiciones ventajosas (aparte) para nosotros. En caso contrario, os mandaremos directamente a los infiernos.<br \/>(Oscuro y Sinton\u00eda. Se retira todo el mobiliario, menos una mesa sin silla, que servir\u00e1 para colocar unas enormes tijeras).<\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/cuadro08.jpg\" alt=\"\" width=\"209\" height=\"130\" \/><span style=\"font-size: 20px;\">CUADRO VIII:LOS RECORTES<\/span><\/p><\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><span style=\"font-weight: bold;\">PERSONAJES: Presidente, Ministro de la Presidencia, Secretario, Ujier<\/span><br \/>Unas tijeras enormes reposar\u00e1n sobre una mesa, mientras los distintos personajes se mover\u00e1n alrededor de ellas).<br \/>MINISTRO (vuelve a entregarle las tijeras): Bien, Presidente, creo que es lo que m\u00e1s nos conviene. Al fin y al cabo, nosotros estamos en el lado de los privilegiados. No vayamos a tirar piedras contra nuestro propio tejado. Ya sabe aquello de que quien escupe al cielo\u2026<br \/>PRESIDENTE: Lo s\u00e9, lo s\u00e9, Ministro y habr\u00e1 que hacer frente a nuestras responsabilidades. La gente nos ha puesto aqu\u00ed para que tomemos decisiones, no para que le digamos lo mal que est\u00e1 el pa\u00eds. Para eso ya est\u00e1 la oposici\u00f3n, con su catastrofismo y sus predicciones apocal\u00edpticas.<br \/>PRESIDENTE (Coge las tijeras y simula cortar a diestro y siniestro a medida que va enumerando los conceptos que habr\u00e1 que sacrificar): Adi\u00f3s ideales; adi\u00f3s principios; adi\u00f3s programa\u2026<br \/>MINISTRO (en tono solemne y, al final, demag\u00f3gico y exaltado): No nos temblar\u00e1 el pulso. Nos pondremos al pa\u00eds en contra, pero tendremos el consuelo de que nos asiste la raz\u00f3n del partido, el porvenir de la patria y el triunfo del mercado. \u00a1Viva la democracia!<br \/>PRESIDENTE: D\u00e9jese de soflamas y alegatos, que no hay nadie aqu\u00ed que pueda aprovecharlos. Reserve sus entusiasmos para cuando le pongan un micr\u00f3fono delante. Y Traiga, Ministro, los asuntos m\u00e1s urgentes.<br \/>MINISTRO: Tome nota, Secretario, de las resoluciones y vaya recogiendo (hace adem\u00e1n de cortar con las tijeras) los despojos. (Le entrega las tijeras al Presidente). Europa sugiere (gesto de ordena) que se retrase la edad de jubilaci\u00f3n y se limiten las prejubilaciones.<br \/>PRESIDENTE (a partir de ahora cada medida de ajuste ir\u00e1 acompa\u00f1ada de un adem\u00e1n de corte con las famosas tijeras): Sin m\u00e1s dilaci\u00f3n. Sit\u00fae la jubilaci\u00f3n a los 85 a\u00f1os. La de experiencia que pueden aportar estas criaturas. Es imprescindible la experiencia para que los j\u00f3venes tengan fuentes de aprendizaje.<br \/>MINISTRO (dirigi\u00e9ndose al Secretario): d\u00e9 la orden de que se pasen por televisi\u00f3n, de forma constante, reportajes, avalados por cient\u00edficos, sobre la conveniencia para la salud f\u00edsica y mental de mantenerse activos en el puesto de trabajo hasta edades avanzadas. Pronto estar\u00e1 todo el mundo convencido. La televisi\u00f3n tiene una enorme fuerza de penetraci\u00f3n en los cerebros.<br \/>SECRETARIO: Con todos los respetos, acaba su se\u00f1or\u00eda de prolongar mi estancia en esta casa 25 a\u00f1os m\u00e1s; acabo de cumplir los 60 y estaba gestionando la prejubilaci\u00f3n.<br \/>PRESIDENTE: Olv\u00eddese, Fern\u00e1ndez, Le vendr\u00e1 bien. El estudio que ha citado el Ministro revela que el trabajo empieza a proporcionar verdadera satisfacci\u00f3n en la d\u00e9cada entre los 70 y los 80 a\u00f1os. Lo anterior es masoquismo y sacrificio. No querr\u00e1 perder semejante colof\u00f3n a su vida laboral.<br \/>MINISTRO: Se\u00f1or Presidente, el tema que ahora nos ocupa exigir\u00eda, m\u00e1s que tijeras, bistur\u00ed. La sanidad representa un gasto imposible de mantener\u2026<br \/>PRESIDENTE (blandiendo las tijeras): Que se privaticen la mitad de los hospitales y que se cobre a cada paciente una tasa por utilizar los servicios de urgencia y ambulatorio.<br \/>SECRETARIO: Le recuerdo, Se\u00f1or, que ya costeamos los servicios sanitarios con nuestros impuestos.<br \/>PRESIDENTE: Pero la Sanidad es un asunto suficientemente importante como pagarlo dos veces y m\u00e1s si hace falta. Que paguen tambi\u00e9n la mitad del coste de los medicamentos, As\u00ed ir\u00e1n menos y no se envenenar\u00e1n con tanta qu\u00edmica.<br \/>MINISTRO: Hay que conseguir que nadie se ponga enfermo. Vamos a solucionar de un plumazo el problema del dolor en el mundo.<br \/>UJIER (Entrando por un lateral): Se\u00f1or Presidente, el diputado Riesgo insiste en que quiere hablarle de su prima.<br \/>PRESIDENTE: Haga el favor de mandar al carajo a Riesgo y a su prima. \u00a1Qu\u00e9 pesadilla!<br \/>MINISTRO: El siguiente asunto viene determinado por un informe de los expertos que asegura que a mayor velocidad, los veh\u00edculos gastan m\u00e1s combustible<br \/>PRESIDENTE (Cogi\u00e9ndole gusto ya al uso de la tijeras):! Recorte! Limitada la velocidad en autov\u00edas y autopistas a 30 kil\u00f3metros por hora y en las dem\u00e1s carreteras a 20.<br \/>MINISTRO: Pero, se\u00f1or, a esa velocidad nos pasar\u00e1 los tractores y los ciclistas.<br \/>PRESIDENTE: Pero apenas se gastar\u00e1n combustible y asfalto. Adem\u00e1s, no habr\u00e1 accidentes. Si ordenamos, adem\u00e1s, una subida lineal de 15 euros sobre el litro de carburante, miel sobre ojuelas.<br \/>SECRETARIO: \u00a1Fuera contaminaci\u00f3n! y \u00a1fuera v\u00edctimas!<br \/>MINISTRO: Seguimos mejorando la salud de la poblaci\u00f3n. Otro sector que reclama nuestra poda es la Educaci\u00f3n. Tenga en cuenta, no obstante, que prometimos en nuestro programa que no solo no recortar\u00edamos, sino que aumentar\u00edamos la inversi\u00f3n.<br \/>PRESIDENTE: (con \u00e9nfasis) La educaci\u00f3n es el futuro. (Cambiando el registro). Pero estamos en el presente (gui\u00f1ando con un gesto p\u00edcaro y empu\u00f1ando las tijeras), luego \u00a1recorte! Que le bajen el sueldo a los maestros y, si protestan, que les quiten las vacaciones. Que reduzcan la mitad de los pupitres. Que usen uno cada dos alumnos, as\u00ed se ir\u00e1n acostumbrando a las estrecheces que estamos fraguando para el d\u00eda de ma\u00f1ana. La educaci\u00f3n solo sirve para crear d\u00edscolos y opositores.<br \/>MINISTRO: Los directores de Colegios de Barcelona se quejan de que hay una gran mayor\u00eda de alumnos que no usa el comedor porque llevan las fiambreras de su casa.<br \/>PRESIDENTE: A cu\u00e1nto asciende el uso del comedor?<br \/>MINISTRO; A cinco euros la comida, Presidente.<br \/>PRESIDENTE: Autorice una tasa de diez euros por cada tartera que entre en el Colegio. Es que no tienen ideas estos pedagogos.<br \/>UJIER: Se\u00f1or Presidente, que llama el Ministro del Interior para que le comunique que ya hay grupos de manifestantes ante la sola sospecha de los recortes que est\u00e1 usted tramando.<br \/>PRESIDENTE (dirigi\u00e9ndose al Ministro): Que se ponga a funcionar la maquinaria de la prensa adicta para que culpe a la oposici\u00f3n y a los sindicatos de dicha sospecha.<br \/>MINISTRO: Otra cuesti\u00f3n: los diputados europeos, los de Las Cortes y Comunidades Aut\u00f3nomas solicitan un aumento de sus dietas. Aducen que unos representantes del pueblo deben viajar en clase preferente y comer en restaurantes dignos de su categor\u00eda. \u00bfQu\u00e9 es eso de comer en la cafeter\u00eda del Congreso por 3 euros?<br \/>SECRETARIO (Con mucha discreci\u00f3n, rozando el miedo): La mayor\u00eda tienen vivienda propia en las sedes de los Parlamentos. \u00bfPara qu\u00e9 necesitan las dietas?<br \/>PRESIDENTE: No sea ingenuo, Fern\u00e1ndez, para que las usemos nosotros tambi\u00e9n, ahora y cuando nos manden a la oposici\u00f3n.<br \/>MINISTRO: Presidente, la prima de riesgo est\u00e1 descontrolada y sigue subiendo.<br \/>PRESIDENTE: Menos mal que nosotros estamos en el \u00faltimo piso. Podremos resistir.<br \/>UJIER: Con permiso, Se\u00f1or Presidente, tengo que informarle que Riesgo\u2026<br \/>MINISTRO (Sali\u00e9ndose materialmente de sus casillas): D\u00edgale a Riesgo que no me toque m\u00e1s los cojones o tendr\u00e9 que (acci\u00f3n de cortar con las tijeras) los suyos.<br \/>SECRETARIO: \u00bfQuiere que esto conste en acta, Se\u00f1or Presidente?<br \/>PRESIDENTE (Mirando con furia al Secretario): \u00a1Fern\u00e1ndez, por Dios! (Seren\u00e1ndose). Bien, pasemos a otros asuntos.<br \/>UJIER; Se\u00f1or Presidente, tengo que comunicarle que el Rey ha vuelto a caerse.<br \/>PRESIDENTE: \u00a1Madre m\u00eda, qu\u00e9 cruz! D\u00edgale al Vicepresidente que se ocupe del tema. Prosigamos.<br \/>MINISTRO: El ministro del Ej\u00e9rcito\u2026<br \/>SECRETARIO (Muy decidido): \u00a1Viva Honduras!<br \/>PRESIDENTE: D\u00e9jese de ocurrencias, Fern\u00e1ndez. Prosiga Ministro.<br \/>MINISTRO: Dec\u00eda que el Ministro del Ej\u00e9rcito teme que los recortes puedan llegar a su Departamento, porque ya sabe usted que los militares en este pa\u00eds son un poder\u2026<br \/>PRESIDENTE: Que el Ministro tranquilice al Ej\u00e9rcito. Las tijeras no van con ellos. (Con \u00e9nfasis) Pues no hay cosas importantes que recortar para que nos pongamos a recortar lo superfluo.<br \/>MINISTRO: El d\u00e9ficit p\u00fablico se vuelve intolerable y los ingresos del Estado est\u00e1n decreciendo como consecuencia del descenso de la actividad econ\u00f3mica. Habr\u00e1 que cortar por lo sano en una serie de servicios y sectores y subir los impuestos. Por ejemplo, Funcionarios.<br \/>PRESIDENTE (Gesto de cortar con las tijeras): Que se les reduzca un veinte por ciento el salario. \u00a1Para lo que hacen!<br \/>MINISTRO: Presidente, los funcionarios llevan ya varios recortes. Se van a levantase en armas.<br \/>MINISTRO: PRESIDENTE (Otro tijeretazo): Que les corten la paga de Navidad.<br \/>MINISTRO: Pol\u00edticos.<br \/>PRESIDENTE: Que nos suban un cincuenta por ciento.<br \/>MINISTRO: El IVA.<br \/>PRESIDENTE: Que lo suban un cien por cien.<br \/>MINISTRO: Las manifestaciones\u2026<br \/>PRESIDENTE: Que las corten.<br \/>MINISTRO: Las huelgas.<br \/>PRESIDENTE: Cortadas de ra\u00edz.<br \/>UJIER: Presidente, el se\u00f1or Riesgo\u2026<br \/>SECRETARIO: \u00a1Manda g\u00fcevos!<br \/>PRESIDENTE: Que se los corten.<br \/>(Se hace el oscuro y empieza a sonar la sinton\u00eda de la obra. Los actores vuelven a colocar las dos mesas a los lados, flanqueando al atril y la tarima que vuelven a escena).<\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/cuadro09.jpg\" alt=\"\" width=\"146\" height=\"99\" \/><span style=\"font-size: 20px;\">CUADRO IX:EL PROGRAMA<\/span><\/p><\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><span style=\"font-weight: bold;\">PERSONAJES: Secretario General del Partido, Responsable de la Campa\u00f1a Electoral, Asesor de imagen, Ide\u00f3logo, Secretario.<\/span><br \/>(Los personajes estar\u00e1n distribuidos en las dos mesas a juicio del director. La idea es que el atril quede centrado para la escena final del Cuadro).<br \/>SECRETARIO GENERAL (En el proscenio): Las elecciones son el escenario perfecto para comprobar la aut\u00e9ntica madera de los pol\u00edticos. Ofrecen las ocasiones inmejorables para que demostremos nuestra dureza de car\u00e1cter. (Aparte) Y de cara. El contacto con el pueblo nos robustece y podemos ensayar el papel que nos tocar\u00e1 representar. Esto es teatro, puro teatro. (Con entusiasmo) \u00a1Vivan las elecciones! Pero antes del mitin, \u00a1qu\u00e9 escuela de actores! tenemos que hacer el programa, \u00a1qu\u00e9 escuela de supercher\u00eda! Pero esto es un arte, \u00bfeh? No pens\u00e9is que es f\u00e1cil. (Se re\u00fane con los compa\u00f1eros, que lo esperan alrededor de una mesa). Bien, vamos a centrar nuestro trabajo sobre cuatro ejes fundamentales: Educaci\u00f3n, Infraestructuras, Sanidad y Econom\u00eda.<br \/>RESPONSABLE DE CAMPA\u00d1A: Bueno, como sab\u00e9is, m\u00e1s que un conjunto de compromisos ante nuestros potenciales votantes, esto no es m\u00e1s que un c\u00famulo de buenas intenciones destinadas a convencer al electorado de que vote a nuestro Partido. Esto es una obviedad, pero lo digo por si alguien lo hab\u00eda olvidado.<br \/>IDE\u00d3LOGO: Te\u00f3ricamente, un programa electoral es un contrato entre el Partido y sus votantes y, como tal contrato, debe ser cumplido. Pero \u00e9sta es la teor\u00eda y no vamos a ser tan ingenuos pensando que los otros van a respetarla. De manera que se trata de prometer m\u00e1s que los dem\u00e1s y mejor que ellos. Es decir, el programa, m\u00e1s que un contrato ser\u00e1 un cebo, un se\u00f1uelo para ganar adhesiones.<br \/>SECRETARIO GENERAL: Lo malo ser\u00e1 que, si ganamos, el Presidente del Gobierno tendr\u00e1 que incumplir estos compromisos.<br \/>RESPONSABLE DE CAMPA\u00d1A: Esa ser\u00e1 otra historia y es problema del Presidente. Nosotros, a lo nuestro, que es lo que nos interesa. En cualquier caso, intentaremos que el Presidente no conozca el programa, para evitarle as\u00ed la mala conciencia de incumplirlo. Y si se lo lee dar\u00e1 lo mismo, porque ya se encargar\u00e1 \u00e9l de hacer exactamente lo contrario.<br \/>SECRETARIO GENERAL: Tal vez si incorpor\u00e1ramos a alg\u00fan ciudadano a esta mesa podr\u00edamos tener la voz del pueblo\u2026<br \/>RESPONSABLE DE CAMPA\u00d1A (Interrumpiendo): El pueblo no sabe lo que le interesa y nosotros tampoco, pero tenemos (Con sorna y malicia) otros intereses, as\u00ed que\u2026procedamos.<br \/>RESPONSABLE DE CAMPA\u00d1A: Tome nota, Secretario. Educaci\u00f3n.<br \/>IDE\u00d3LOGO: Tema fundamental, porque los ciudadanos son muy sensibles a este asunto. Entiendo que hay que prometer un incremento en la inversi\u00f3n y que, en ning\u00fan caso, esta parcela deber\u00e1 sufrir la tijera de los recortes.<br \/>SECRETARIO GENERAL: Apunte que cada alumno dispondr\u00e1 de un equipo inform\u00e1tico sofisticado, compuesto de ordenador con conexi\u00f3n a Internet, impresora, tablet y tel\u00e9fono m\u00f3vil. (Con picard\u00eda) Esto har\u00e1 que los alumnos empujen con vehemencia a sus padres para que nos voten. Los chicos ahora tienen mucha capacidad de persuasi\u00f3n. No como en nuestros tiempos, que ped\u00edas un scalextric y te daban una piruleta.<br \/>IDE\u00d3LOGO: Y no olvide, Secretario, acentuar el tema del biling\u00fcismo y alg\u00fan que otro plan con siglas irresistibles para los votanres, del tipo PIC (Plan para Incrementar la Inteligencia) o PICE (Plan de Ilusiones que se Cargar\u00e1 la Escuela). Estas cosas son muy distinguidas para la gente, aunque es evidente que no sirven absolutamente para nada; pero visten mucho.<br \/>RESPONSABLE DE LA CAMPA\u00d1A: Pasemos al segundo eje de la campa\u00f1a: la Sanidad.<br \/>SECRETARIO GENERAL: Aumento de la inversi\u00f3n y promesa de construir Hospitales y Centros de Salud en todas las poblaciones.<br \/>SECRETARIO: Es mi deber recordar que \u00faltimamente estamos cerrando Centros de noche y privatizando hospitales.<br \/>IDE\u00d3LOGO: No importa. Una cosa es predicar y otra dar trigo. Nosotros, al programa, que ya vendr\u00e1 el Gobierno con los recortes. Hospitales por un tubo\u2026y m\u00e9dicos y enfermeras\u2026y ambulancias y\u2026lo que haga falta.<br \/>RESPONSABLE DE CAMPA\u00d1A: Y si el Gobierno tiene problemas para aplicar esta parte del programa, que saque un Decreto Ley que obligue a la gente a estar sanos, que nos hemos vuelto todos muy delicados, joder.<br \/>IDE\u00d3LOGO: Entiendo que debi\u00e9ramos prometer inversiones en investigaci\u00f3n en enfermedades raras y contagiosas. Eso da mucha sensaci\u00f3n de responsabilidad y preocupaci\u00f3n por la salud de los ciudadanos. Basta con la promesa; la inversi\u00f3n ya la dedicaremos a asuntos m\u00e1s importantes para nosotros.<br \/>SECRETARIO GENERAL: Se acepta. Bien, pasemos al tercer eje de nuestro programa: Infraestructuras.<br \/>IDE\u00d3LOGO: Este es un tema para lucirse en el programa. Un pa\u00eds moderno necesita cambiar los caminos por carreteras y \u00e9stas por autov\u00edas. Que no quede ni un pueblo sin la suya. Prometamos las que hagan falta. A los electores les encantan los coches y las autopistas.<br \/>RESPONSABLE DE CAMPA\u00d1A: Secretario, incorpore im\u00e1genes, planos y todo tipo de gr\u00e1ficos. La inform\u00e1tica ayuda mucho a confundir y embaucar. Contribuye a construir una realidad virtual, que terminar\u00e1 siendo aceptada como la \u00fanica realidad.<br \/>SECRETARIO: \u00bfY los baches y los atascos?<br \/>SECRETARIO GENERAL: Ya se ocupar\u00e1 el ministro. \u00bfAlgo tendr\u00e1 que hacer, \u00bfno? Lo nuestro es prometer. Especialidad: promesas. No podemos estar en todo. Por ejemplo (se dirige al Secretario), que se entregue un GPS a cada conductor. Pasamos a un tema central: la econom\u00eda.<br \/>IDE\u00d3LOGO: Primero una reflexi\u00f3n general. Entiendo que nuestro quehacer tiene un objetivo fundamental: buscar el voto popular, cueste lo que cueste. Para ello debemos dar buenos titulares a la prensa. No hay ning\u00fan tema que motive m\u00e1s a la gente que el econ\u00f3mico. Tenemos que trasladar la idea de que, pese a la tremenda situaci\u00f3n actual, ning\u00fan partido que no sea el nuestro est\u00e1 en condiciones ni tiene la capacidad de sortear los problemas que nos afligen.<br \/>RESPONSABLE DE CAMPA\u00d1A: Y de hacer posible que todos miremos al futuro con optimismo y esperanza. Secretario, anote esta frase, que me ha salido redonda.<br \/>SECRETARIO GENERAL: Hay que plantear inversiones y bajadas de impuestos y ayudas sociales y proponer que vamos a acabar con el Senado, las Diputaciones, las Fundaciones\u2026<br \/>SECRETARIO: Eso no, por Dios, \u00bf qu\u00e9 haremos con la ristra de in\u00fatiles, incompetentes y pesebreros, que tenemos colocados en esas instituciones, porque no sirven para otra cosa?<br \/>RESPONSABLE DE CAMPA\u00d1A: No te alarmes. Esto es humo y buenos prop\u00f3sitos, hasta que consigamos el voto. Toma nota, todos los mensajes deben ser positivos (Con \u00e9nfasis y comicidad): trabajo para todos y bajada de impuestos. Con esto no hay quien nos pare.<br \/>SECRETARIO GENERAL: Y como punto final, debemos hacer una apolog\u00eda de la transparencia, de la limpieza y la claridad en la gesti\u00f3n. Porque un Partido\u2026<br \/>RESPONSABLE DE LA CAMPA\u00d1A: Un momento, un momento. Ahora ensayamos el mitin. Primero, cerremos el programa.<br \/>IDE\u00d3LOGO: Yo entiendo (sigue con su tono pedante) que podemos darlo por terminado. Una \u00faltima idea: insistir mucho en las propuestas y esconder todo lo posible las verdaderas intenciones. En t\u00e9rminos t\u00e9cnicos, El Plan B debe quedar absolutamente enmascarado por el Plan A.<br \/>RESPONSABLE DE CAMPA\u00d1A: Bien, pasemos entonces al ensayo del mitin. Se\u00f1or Secretario General, col\u00f3quese en la tarima y detr\u00e1s del atril. (\u00c9ste hace lo que le indica el Responsable de la Campa\u00f1a y los dem\u00e1s toman posiciones como espectadores, menos el Asesor de Imagen, que revolotea alrededor del Secretario General).<br \/>ASESOR DE IMAGEN: Paso firme y decidido. Levante la barbilla; muestre seguridad en s\u00ed mismo; transmita siempre la idea de que controla la situaci\u00f3n.<br \/>SECRETARIO GENERAL (Intentando obedecer todas las instrucciones que recibe): Seguridad. Control. Estimados amigos\u2026<br \/>IDE\u00d3LOGO: No olvide la idea estrat\u00e9gica central: culpar siempre al otro partido de todo lo malo. Echarles la culpa de todo. Atribuirnos lo bueno.<br \/>SECRETARIO GENERAL: Estas nubes que acaban de cubrir la cara luminosa del Sol son una muestra m\u00e1s de los trucos taimados y marrulleros de nuestros oponentes\u2026<br \/>IDE\u00d3LOGO: Demasiado po\u00e9tico. M\u00e1s energ\u00eda.<br \/>SECRETARIO GENERAL: Solo nosotros seremos capaces de levantar a Espa\u00f1a de la actual postraci\u00f3n hist\u00f3rica, que viene determinada\u2026<br \/>IDE\u00d3LOGO: Demasiada ret\u00f3rica. Sea concreto, vaya al grano, pero sin decir nada. Olv\u00eddese del fondo. Lo importante son las formas: la fuerza, el car\u00e1cter, la determinaci\u00f3n.<br \/>ASESOR DE IMAGEN: Y sonr\u00eda, hombre, sonr\u00eda. La gente quiere ver actitudes positivas y optimistas.<br \/>SECRETARIO GENERAL (Empezando a mostrar s\u00edntomas de agobio): Somos conscientes de que la presente crisis es la consecuencia de la err\u00e1tica pol\u00edtica que en su d\u00eda llev\u00f3 a cabo en el gobierno el actual partido de la oposici\u00f3n.<br \/>ASESOR DE IMAGEN: Sonr\u00eda con seguridad.<br \/>IDE\u00d3LOGO: D\u00e9le fuerte.<br \/>SECRETARIO GENERAL: M\u00e1s que de la oposici\u00f3n, habr\u00eda que llamarlo el Partido de la Corrupci\u00f3n. (Aplausos y v\u00edtores de todos los presentes).<br \/>IDE\u00d3LOGO: No proponga nada. Va bien as\u00ed, dando ca\u00f1a. Fuerte.<br \/>ASESOR DE IMAGEN: Sonr\u00eda, hombre, sonr\u00eda.<br \/>SECRETARIO DEL PARTIDO (Sonriendo ostensiblemente): Las cifras escandalosas del paro, el sufrimiento\u2026<br \/>ASESOR DE IMAGEN: Ahora no, co\u00f1o. Este tema no es para re\u00edrse. Acomode el semblante a las palabras.<br \/>IDE\u00d3LOGO: D\u00e9jese de trascendencias. Apele a los sentimientos, aunque salga por los Cerros de \u00dabeda.<br \/>SECRETARIO GENERAL (Sinti\u00e9ndose cada vez m\u00e1s agobiado): Vamos a intentar reducir el desempleo\u2026<br \/>IDE\u00d3LOGO: Esa promesa est\u00e1 muy gastada. Prometa cosas imposibles.<br \/>ASESOR DE IMAGEN: Sonr\u00eda. (Con sard\u00f3nica intenci\u00f3n). La risa es muy apropiada para las promesas. Incluso la carcajada.<br \/>SECRETARIO GENERAL: Bajaremos la luz y la gasolina.<br \/>IDE\u00d3LOGO: Algo m\u00e1s impactante. Algo demoledor.<br \/>ASESOR DE IMAGEN: No olvide los vaqueros y la chaqueta de pana para el mitin.<br \/>SECRETARIO GENERAL (Empezando a desbarrar por el agobio): Subiremos la incomprensi\u00f3n y el odio.<br \/>ASESOR DE IMAGEN: Sonr\u00eda, hombre, por Dios.<br \/>IDE\u00d3LOGO: Necesitamos una nueva gram\u00e1tica. \u00a1Invente un nuevo lenguaje!<br \/>SECRETARIO GENERAL (En el \u00faltimo grado del confusi\u00f3n): Puedo prometer y prometo que a partir de hoy el idioma oficial de este pa\u00eds ser\u00e1\u2026el sueco.<br \/>(Sinton\u00eda de la obra, tras la perplejidad de los presentes. Los actores proceder\u00e1n a retirar una de las mesa y el atril con la tarima. Dejar\u00e1n tres sillas).<\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/cuadro10.jpg\" alt=\"\" width=\"131\" height=\"99\" \/><span style=\"font-size: 20px;\">CUADRO X:LA CRISIS<\/span><\/p><\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\">PERSONAJES: Pol\u00edtico, Soci\u00f3logo, Ciudadano consciente, Votante de derechas, Votante de izquierdas<br \/>(Se sentar\u00e1n alrededor de una mesa central o merodear\u00e1n alrededor de ella).<br \/>POL\u00cdTICO (En el proscenio): He estado un a\u00f1o, \u00a1un a\u00f1o! sin enterarme de que estaba asomando las orejas una crisis. Me he pasado dos a\u00f1os, \u00a1dos a\u00f1os! neg\u00e1ndola. El tiempo que he perdido en esas dos tareas ha sido suficiente para que la crisis me lleve por delante. Ahora tendr\u00e1n que venir otros a pelearse con ella. Yo, al final, hice todo lo que pude, es decir, seguir las instrucciones que me llegaron de arriba. Si llega a ser por m\u00ed no habr\u00eda crisis. \u00bfCrisis? \u00bfQu\u00e9 crisis? \u00a1Todav\u00eda estar\u00eda neg\u00e1ndola! (Se traslada hasta la silla central de la mesa).<br \/>SOCI\u00d3LOGO: El tema es bien sencillo, pero lo emborron\u00e1is tanto los pol\u00edticos, lo carg\u00e1is de tanta ret\u00f3rica con vistas a vuestro propio beneficio, que los ciudadanos se confunden, son enredados de manera deliberada, y buscan explicaciones peregrinas para lo que pasa y culpables imaginarios, seg\u00fan el color.<br \/>VOTANTE DE DERECHAS: La culpa es de Zapatero.<br \/>VOTANTE DE IZQUIERDAS: La culpa es de Rajoy.<br \/>Ya quisieran ellos ser tan importantes como para ser culpables de lo que pasa. Aqu\u00ed ha habido un golpe de estado incruento por parte de los poderes financieros, que se han hecho con el poder total. \u00bfHas o\u00eddo hablar de la globalizaci\u00f3n? Ya ten\u00edan el poder, pero antes los pol\u00edticos dispon\u00edan de un espacio para marcar objetivos, orientar planes, dise\u00f1ar proyectos. Ahora se han convertido, os hab\u00e9is convertido, en unos mamporreros de aquellos poderes.<br \/>POL\u00cdTICO: Mamporreros suena fuerte\u2026<br \/>SOCI\u00d3LOGO: Suena a la verdad. La pol\u00edtica es una servidora fiel del capital. Sin ninguna duda. Y no es que quiera serlo, es que no tiene m\u00e1s remedio que serlo. No hay salida. O entras en el juego o te sacan. \u00bfUsted quiere jugar a este juego? Bien, pues estas son las reglas; at\u00e9ngase a ellas. Si no las acepta, no podr\u00e1 jugar. As\u00ed de f\u00e1cil. Haz lo que se te diga y podr\u00e1s seguir dedic\u00e1ndote a la pol\u00edtica; si no\u2026Y a los pa\u00edses se le impone el mismo discurso: \u00a1O entras en el juego o te sacamos!<br \/>CIUDADANO: Pero, por qu\u00e9 esta deriva. \u00bfQu\u00e9 ha pasado?<br \/>SOCI\u00d3LOGO: Lo que ha pasado es que el capital se ha dado cuenta de que, al poder operar con total libertad e impunidad en cualquier parte del mundo (eso es la globalizaci\u00f3n) tiene nuevas posibilidades de sacarle rendimiento a su dinero, que antes no ten\u00eda o que eran m\u00ednimas. Por otra parte, ha comprendido que especulando en sofisticados productos financieros se multiplican las ganancias de una manera desorbitada con respecto a lo que se obtiene invirtiendo en la producci\u00f3n de bienes.<br \/>POL\u00cdTICO: As\u00ed que \u00a1a ganar dinero f\u00e1cil! A guardarlo en para\u00edsos fiscales, mientras, las empresas est\u00e1n asfixiadas porque no hay un banco que les firme un cr\u00e9dito. \u00bfC\u00f3mo no me enter\u00e9 de nada?<br \/>SOCI\u00d3LOGO: Esa es la cuesti\u00f3n. El dinero se ha independizado de la producci\u00f3n. Hoy no hay que producir cosas para ganarlo. Basta con saberlo mover y colocarlo en los lugares m\u00e1s rentables y m\u00e1s seguros.<br \/>CIUDADANO: Como hicieron los bancos espa\u00f1oles.<br \/>SOCI\u00d3LOGO: Exactamente como no hicieron los bancos espa\u00f1oles, que invirtieron nuestros ahorros en productos t\u00f3xicos, que en un santiam\u00e9n, quedaron volatilizados. Como por arte de magia, se descapitalizaron, se arruinaron. Nos arruinaron.<br \/>POL\u00cdTICO: Y para salvar la situaci\u00f3n, tuvimos que inyectarles el dinero de todos. Y el dinero de todos se acab\u00f3 y para conseguir m\u00e1s hay que subir los impuestos, bajar los sueldos, retrasar la edad de jubilaci\u00f3n, mandar a mucha gente al paro\u2026<br \/>CIUDADANO. D\u00edganme ustedes qu\u00e9 culpa hemos tenido los ciudadanos en esta fiesta macabra.<br \/>SOCI\u00d3LOGO: Alguna hay, pero no para merecer tanto castigo como estamos sufriendo. El mercado es ciego y\u2026<br \/>CIUDADANO: Pero, \u00bfqui\u00e9n co\u00f1o es el Mercado?<br \/>SOCI\u00d3LOGO: Esa es la gran cuesti\u00f3n. El Mercado no es nadie y somos todos. Todo aquel que invierte un c\u00e9ntimo forma parte del mercado. \u00bfQui\u00e9n no lo ha hecho alguna vez? Todos hemos puesto alg\u00fan ahorro donde nos pudiera reportar alg\u00fan beneficio. Y el que busca beneficios quiere el m\u00e1ximo beneficio, sin reparar en cuestiones morales o pol\u00edticas. Nos pasa a todos. Todos somos el mercado, que tiene sus reglas; la principal: obtener la m\u00e1xima rentabilidad. El mercado es una l\u00f3gica. Una l\u00f3gica implacable.<br \/>CIUDADANO: Y si alguien queda arrollado por su maquinaria\u2026aunque sea un pa\u00eds entero\u2026<br \/>VOTANTE DE DERECHAS: \u00a1Zapatero es el culpable! \u00a1Los sociatas!<br \/>VOTANTE DE IZQUIERDAS: \u00a1Rajoy! \u00a1La derechona!<br \/>SOCI\u00d3LOGO: Son las reglas del juego. Creadas por el capitalismo y aceptadas mayoritariamente. Lo que ocurre es que si nos salen bien las jugadas, perfecto; si nos salen mal, nos acordamos de la madre del mercado y de todos los progenitores del pol\u00edtico que no tragamos.<br \/>VOTANTE DE DERECHAS: \u00a1Zapatero, chorizo!<br \/>VOTANTE DE IZQUIERDAS: \u00a1Rajoy, ladr\u00f3n!<br \/>SOCI\u00d3LOGO: Y no es eso, no es eso. Los partidos tienen una \u00fanica responsabilidad: haber consentido convertirse en siervos, en asistentes del Mercado. La Pol\u00edtica ha sucumbido a la Econom\u00eda. \u00bfY qui\u00e9n tiene la culpa de esto?<br \/>VOTANTE DE DERECHAS: Zapatero<br \/>VOTANTES DE IZQUIERDAS: Rajoy.<br \/>POL\u00cdTICO (Ignorando las voces, pero dolido por las imprecaciones de los votantes): Los ciudadanos, los votantes tienden a simplificar la realidad. Hacen una lectura muy simple de las cosas.<br \/>SOCI\u00d3LOGO: Hacen la lectura que les corresponde hacer. Ellos tambi\u00e9n forman parte del sistema y han sido condicionados a reaccionar as\u00ed. El sistema lo controla todo y manipula hasta las cr\u00edticas que recibe. Convierte a los ciudadanos en seres programados para entender mensajes simples y dar respuestas irracionales.<br \/>CIUDADANO (Dirigi\u00e9ndose al pol\u00edtico): Y reduce nuestra participaci\u00f3n pol\u00edtica a votar cada cierto tiempo con la \u00fanica finalidad de legitimaros en vuestros puestos, cargos y privilegios. Votamos por costumbre, no por convicci\u00f3n. Sabiendo que nuestro voto es papel\u2026mojado.<br \/>SOCI\u00d3LOGO: \u00bfY para qu\u00e9? \u00bfPor qu\u00e9 esa p\u00e9rdida de sustancia de la pol\u00edtica? \u00bfQui\u00e9n ha propiciado esa degeneraci\u00f3n de vuestra misi\u00f3n original? \u00bfQui\u00e9n ha convertido el poder en ambici\u00f3n si debiera ser servicio? \u00bfQui\u00e9n ha transformado el dinero en un fin, en el \u00fanico fin, si debiera ser un instrumento? \u00bfQui\u00e9n lo ha convertido en un dios al que hay que sacrificar todos los valores?<br \/>VOTANTE DE DERECHAS: Zapatero.<br \/>VOTANTE DE IZQUIERDAS: Rajoy.<br \/>(Se hace el oscuro y suena la sinton\u00eda mientras los actores preparan el mobiliario del siguiente Cuadro, que consistir\u00e1 en dos mesas separadas, una a cada lado y un par de sillas).<\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/cuadro11.jpeg\" alt=\"\" width=\"164\" height=\"100\" \/><span style=\"font-size: 20px;\">CUADRO XI: GOBIERNO &#8211; OPOSICI\u00d3N<\/span><\/p><\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><span style=\"font-weight: bold;\">PERSONAJES: Narrador, Gobierno, Oposici\u00f3n, Periodista 1, periodista 2.<\/span><br \/>(Dos mesas y dos sillas donde se sentar\u00e1n, por un lado el portavoz del Gobierno, que est\u00e1 respondiendo a las preguntas de un periodista y, por otro, el portavoz de la Oposici\u00f3n haciendo lo propio con otro periodista. Dos carteles, uno en cada mesa, indicar\u00e1n GOBIERNO y OPOSICI\u00d3N, seg\u00fan corresponda. El Narrador se mover\u00e1 a lo largo del proscenio).<br \/>Narrador: El pol\u00edtico es un ser poli\u00e9drico, multifac\u00e9tico. (Dirigi\u00e9ndose a alguien del p\u00fablico). \u00bfUsted solo tiene una cara? Usted no puede ser pol\u00edtico. (Dirigi\u00e9ndose a otro espectador). Y usted, \u00bftiene ideolog\u00eda? Usted no puede dedicarse a la pol\u00edtica. El pol\u00edtico puro no tiene ideolog\u00eda. No tiene ideolog\u00eda porque las tiene todas. Tiene todas las ideolog\u00edas. Las va sacando, como saca el mago conejos de la chistera, en funci\u00f3n de las circunstancias, en funci\u00f3n de sus intereses o los de su Partido. O en funci\u00f3n de lo que diga el Gobierno, o la Oposici\u00f3n, dependiendo de d\u00f3nde se encuentre en cada momento. \u00bfEsto est\u00e1 bien o est\u00e1 mal? Depende. \u00bfDe qu\u00e9 depende? De seg\u00fan como se mire, todo depende.<br \/>En este mundo traidor,<br \/>nada es verdad ni es mentira,<br \/>todo es seg\u00fan el color<br \/>del cristal con que se mira.<br \/>(El Narrador se retira hacia un lateral y se hace la luz sobre la mesa donde est\u00e1 el Gobierno).<br \/>GOBIERNO (Dirigi\u00e9ndose al Periodista): La situaci\u00f3n lamentable en que ha dejado las arcas p\u00fablicas el anterior gobierno nos obliga a tomar medidas dr\u00e1sticas sobre temas bastante delicados. Para empezar, no tendremos m\u00e1s remedio que subir tres puntos el IVA.<br \/>PERIODISTA: Quiero recordarle que en el programa de su Partido aseguraban que no tocar\u00edan los impuestos.<br \/>GOBIERNO: La realidad muchas veces se impone a las intenciones. Y dada la situaci\u00f3n con la que nos hemos encontrado, no podemos hacer otra cosa.<br \/>(La luz pasa a la otra mesa donde se encuentra la Oposici\u00f3n)<br \/>PERIODISTA: \u00bfQu\u00e9 opini\u00f3n les merece la subida del IVA que acaba de anunciar el Gobierno?<br \/>OPOSICI\u00d3N: Subir el IVA es una medida que solo pueden adoptar los malos gobernantes. Lo que hay que hacer es todo lo contrario: bajar los impuestos para que los ciudadanos consuman m\u00e1s y aumente la circulaci\u00f3n del capital.<br \/>(Se hace el oscuro sobre las dos mesas y la luz se hace sobre el Narrador).<br \/>NARRADOR: Esto es lo normal: la oposici\u00f3n se opone a lo que plantea el Gobierno. No hay nada que objetar. Pero, he aqu\u00ed que tres meses despu\u00e9s\u2026<br \/>(Vuelve a hacerse la luz sobre las mesas).<br \/>GOBIERNO: La mejora de los indicadores macroecon\u00f3micos nos permite disponer una bajada de cuatro puntos del Impuesto sobre el Valor A\u00f1adido, el famoso IVA. Gracias al esfuerzo de este Gobierno hemos conseguido paliar en buena medida las lamentables condiciones en que dej\u00f3 el gobierno anterior el d\u00e9ficit p\u00fablico.<br \/>OPOSICI\u00d3N (Dirigi\u00e9ndose al Periodista): Bajar el IVA es una absoluta irresponsabilidad. En las actuales circunstancias, esta medida nos conducir\u00e1 inevitablemente, a corto plazo, a un aumento del d\u00e9ficit, y a largo plazo, a una cat\u00e1strofe segura.<br \/>(Vuelven a quedar a oscuras las mesas y luz sobre el Narrador).<br \/>NARRADOR (En tono condescendiente) \u00a1Cosas de la pol\u00edtica! Pero, no abandonemos el juego. (Al estilo del presentador de un circo). Pasen y vean. Hay m\u00e1s sorpresas y maravillas.<br \/>(Luz sobre las mesas)<br \/>GOBIERNO (Dirigi\u00e9ndose al Periodista): La actual coyuntura internacional aconseja que iniciemos hoy mismo la retirada de las tropas destacadas en Afganist\u00e1n. El precio que estamos pagando\u2026<br \/>OPOSICI\u00d3N (Dirigi\u00e9ndose y contestando a una pregunta del Periodista): La retirada de las tropas de Afganist\u00e1n es otra grav\u00edsima irresponsabilidad de este Gobierno irresponsable. Los pa\u00edses occidentales debemos trabajar juntos por un mundo mejor y este Gobierno se empe\u00f1a en quedarse al margen de la modernidad\u2026<br \/>(Se apagan las luces sobre las mesas y vuelve a aparecer el Narrador).<br \/>NARRADOR: \u00bfNos podemos imaginar qu\u00e9 ocurrir\u00e1 dos meses despu\u00e9s cuando el Gobierno anuncie el regreso de las tropas al lugar del conflicto? \u00bfSer\u00e1 lo que todos estamos pensando? Ser\u00e1.<br \/>(Luz a las mesas, mientras el Narrador se hace a un lado).<br \/>GOBIERNO: El cambio que se ha producido en nuestros intereses estrat\u00e9gicos nos impone la dolorosa obligaci\u00f3n de reincorporar a nuestras tropas al lugar del conflicto.<br \/>OPOSICI\u00d3N: Regresar a Afganist\u00e1n es una barbaridad de tal calibre, que este Gobierno, muy pronto, tendr\u00e1 que lamentar su indiferencia ante el riesgo que corren nuestros militares\u2026<br \/>(Se hace el oscuro sobre las mesas y vuelve la luz sobre el Narrador).<br \/>NARRADOR: \u00bfEs bueno subir el IVA o no? \u00bfHay intereses estrat\u00e9gicos? \u00bfCorren riesgos innecesarios nuestros soldados? (Gesto de no ser posible saberlo). Los ciudadanos nunca agradeceremos de forma suficiente la transparencia, la claridad, el rigor con el que se nos informa sobre los asuntos candentes. Sobre todo, agradecemos la firmeza de los ideales, la solidez de las ideas y la coherencia de los comportamientos.<br \/>(Vuelve la luz a las mesas).<br \/>GOBIERNO (En declaraciones exclusivas al Periodista): Nosotros nunca renunciaremos a nuestros principios\u2026<br \/>OPOSICI\u00d3N: Este Gobierno no puede resolver los problemas de Espa\u00f1a, porque le falta cintura, no tiene flexibilidad para adaptarse a los escenarios cambiantes\u2026<br \/>GOBIERNO: Nosotros estamos dispuestos a negociar con todos y a cambiar nuestro ideario si con ello alcanzamos el noble objetivo de la paz\u2026<br \/>OPOSICI\u00d3N: \u00bfQu\u00e9 puede esperarse de un Gobierno que carece de principios, que se arrima al sol que m\u00e1s calienta y que es tan flexible que apenas puede mantenerse en pie?<br \/>(Oscuro en las mesas y luz sobre el Narrador).<br \/>NARRADOR: Esto que acabamos de contemplar es un ejercicio de alta dial\u00e9ctica, de estar y no estar, de ser y no ser, de c\u00f3mo la realidad puede ser interpretada de una forma y de la contraria. Pero, sigamos con el cuento. Vayamos a la traca final. (Vuelve el tono de presentador circense) Prepar\u00e9monos para disfrutar del gran n\u00famero, el triple salto mortal, la cuadratura del c\u00edrculo. (Se dirige decidido a la mesa del Gobierno y coge el cartel. Va hacia la mesa de la Oposici\u00f3n y cambia el cartel de \u00e9sta por el de Gobierno y lleva el cartel de Oposici\u00f3n a la mesa del Gobierno. Seguir\u00e1 con su parlamento mientras realiza el cambio). Los vientos viran y los que mueven los hilos de la pol\u00edtica son especialmente caprichosos. Y he aqu\u00ed que el Gobierno pasa a ser Oposici\u00f3n y la Oposici\u00f3n se convierte en Gobierno. Un soplo m\u00e1gico, \u00a1eh voil\u00e0!<br \/>(El Narrador se hace a un lado y la luz vuelve a las mesas).<br \/>GOBIERNO (Dirigi\u00e9ndose al Periodista): La situaci\u00f3n lamentable en que ha dejado las arcas p\u00fablicas el anterior gobierno nos obliga a tomar medidas dr\u00e1sticas sobre temas bastante delicados. Para empezar, no tendremos m\u00e1s remedio que subir tres puntos el IVA.<br \/>PERIODISTA: Quiero recordarle que en el programa de su Partido aseguraban que no tocar\u00edan los impuestos.<br \/>GOBIERNO: La realidad muchas veces se impone a las intenciones. Y dada la situaci\u00f3n con la que nos hemos encontrado, no podemos hacer otra cosa.<br \/>PERIODISTA: \u00bfQu\u00e9 opini\u00f3n les merece la subida del IVA que acaba de anunciar el Gobierno?<br \/>OPOSICI\u00d3N: Subir el IVA es una medida que solo pueden adoptar los malos gobernantes. Lo que hay que hacer es todo lo contrario: bajar los impuestos para que los ciudadanos consuman m\u00e1s y aumente la circulaci\u00f3n del capital.<br \/>GOBIERNO: La mejora de los indicadores macroecon\u00f3micos nos permite disponer una bajada de cuatro puntos del Impuesto sobre el Valor A\u00f1adido, el famoso IVA. Gracias al esfuerzo de este Gobierno hemos conseguido paliar en buena medida las lamentables condiciones en que dej\u00f3 el gobierno anterior el d\u00e9ficit p\u00fablico.<br \/>OPOSICI\u00d3N (Dirigi\u00e9ndose al Periodista): Bajar el IVA es una absoluta irresponsabilidad. En las actuales circunstancias, esta medida nos conducir\u00e1 inevitablemente, a corto plazo, a un aumento del d\u00e9ficit, y a largo plazo, a una cat\u00e1strofe segura.<br \/>GOBIERNO (Dirigi\u00e9ndose al Periodista): La actual coyuntura internacional aconseja que iniciemos hoy mismo la retirada de las tropas destacadas en Afganist\u00e1n. El precio que estamos pagando\u2026<br \/>OPOSICI\u00d3N (Dirigi\u00e9ndose y contestando a una pregunta del Periodista): La retirada de las tropas de Afganist\u00e1n es otra grav\u00edsima irresponsabilidad de este Gobierno irresponsable. Los pa\u00edses occidentales debemos trabajar juntos por un mundo mejor y este Gobierno se empe\u00f1a en quedarse al margen de la modernidad\u2026<br \/>GOBIERNO: El cambio que se ha producido en nuestros intereses estrat\u00e9gicos nos impone la dolorosa obligaci\u00f3n de reincorporar a nuestras tropas al lugar del conflicto.<br \/>OPOSICI\u00d3N: Regresar a Afganist\u00e1n es una barbaridad de tal calibre, que este Gobierno, muy pronto, tendr\u00e1 que lamentar su indiferencia ante el riesgo que corren nuestros militares\u2026<br \/>GOBIERNO (En declaraciones exclusivas al Periodista): Nosotros nunca renunciaremos a nuestros principios\u2026<br \/>OPOSICI\u00d3N: Este Gobierno no puede resolver los problemas de Espa\u00f1a, porque le falta cintura, no tiene flexibilidad para adaptarse a las escenarios cambiantes\u2026<br \/>GOBIERNO: Nosotros estamos dispuestos a negociar con todos y a cambiar nuestro ideario si con ello alcanzamos el noble objetivo de la paz\u2026<br \/>OPOSICI\u00d3N: \u00bfQu\u00e9 puede esperarse de un Gobierno que carece de principios, que se arrima al sol que m\u00e1s calienta y que es tan flexible que apenas puede mantenerse en pie?<br \/>NARRADOR: La cuadratura del c\u00edrculo, por fin, ante ustedes.<br \/>(Se hace el oscuro y empieza a sonar la sinton\u00eda. Los actores retirar\u00e1n una mesa y centrar\u00e1n la otra a ritmo de la m\u00fasica).<\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"art-lightbox\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/11\/cuadro12.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><span style=\"font-size: 20px;\">CUADRO XII<\/span><\/p><\/div><\/div><\/div><div class=\"art-content-layout\"><div class=\"art-content-layout-row\"><div class=\"art-layout-cell\" style=\"width: 100%;\"><span style=\"font-weight: bold;\">PERSONAJES: Pol\u00edtico, Ciudadano<\/span><br \/>(Los dos personajes partir\u00e1n de la posici\u00f3n de sentados y enfrentados en una mesa CUANDO INICIEN EL DI\u00c1LOGO. Antes har\u00e1 cada uno un breve mon\u00f3logo en el proscenio. A discreci\u00f3n del director quedar\u00e1n los diferentes movimientos que vaya requiriendo la acci\u00f3n).<br \/>POL\u00cdTICO: \u00bfC\u00f3mo es posible que siendo representante del pueblo me haya distanciado tanto de \u00e9l; y que \u00e9l se haya alejado tanto de m\u00ed, que ya no me reconozca en ellos, que ya no se reconozcan en m\u00ed? Como dos l\u00edneas paralelas; sin posibilidad de encuentro. Alejados en intereses y en objetivos. Sin nada que compartir, como no sea el desprecio mutuo que nos profesamos. (Se dirige a la mesa y se sienta en su silla).<br \/>CIUDADANO: Yo soy el pueblo, el famoso pueblo, protagonista en todas las declaraciones de principios que hacen los pol\u00edticos cuando se les llena la boca de democracia; el que est\u00e1 en el frontispicio de todas las constituciones, de todas las revoluciones. Por cierto, \u00a1qu\u00e9 pronto se olvidan del pueblo los revolucionarios!: piden mi ayuda y, una vez instalados, paso al olvido. Yo soy una parte de ese pueblo, que no se siente representado por los que nos dicen representar. Soy un ciudadano, un s\u00fabdito desencantado.<br \/>(Dirigi\u00e9ndose a la mesa y sent\u00e1ndose frente al pol\u00edtico. Ser\u00eda interesante marcar f\u00edsicamente la distancia psicol\u00f3gica que los separa). Est\u00e1s tan lejos de m\u00ed que apenas puedo vislumbrarte. No te reconozco. T\u00fa no eres aquel al que vot\u00e9 cargado de ilusiones, aquel al que eleg\u00ed confiando en su talento y en su probidad.<br \/>POL\u00cdTICO: No alcanzo a comprender lo que ha pasado, pero, en todo caso, no es exclusiva mi responsabilidad. T\u00fa tambi\u00e9n te has distanciado y has desconfiado muchas veces, sin motivo, de m\u00ed.<br \/>CIUDADANO: La ra\u00edz de esta distancia est\u00e1 en que en cuanto los pol\u00edticos acced\u00e9is al m\u00e1s m\u00ednimo poder, lo primero que hac\u00e9is es perder de vista el primer objetivo, el \u00fanico al que debierais encaminar toda vuestra labor: servir a los que os eligen. Por una extra\u00f1a perversi\u00f3n de los objetivos, lo que hac\u00e9is es transformar el verbo servir de activa a pasiva y solicit\u00e1is ser servidos. As\u00ed, el ciudadano se convierte en un s\u00fabdito y no en un sujeto de derecho.<br \/>POL\u00cdTICO: Y de deberes. Que t\u00fa sueles olvidar esta parte del contrato social. Y exiges todo y te implicas lo justo.<br \/>CIUDADANO: \u00bfC\u00f3mo puedes acusar de falta de compromiso a quien tiene un trabajo precario, inestable, mal remunerado; a quien tiene que levantarse cada ma\u00f1ana a las claras del d\u00eda y volver a las tantas de la noche para sostener a una mujer desempleada, a tres hijos en paro, a quinientos y pico diputados, a otros tantos senadores, a miles de concejales, alcaldes\u2026<br \/>POL\u00cdTICo: No sigas por ese camino. Yo tambi\u00e9n tengo que soportarte a ti y a la gente que como t\u00fa no hac\u00e9is m\u00e1s que reprocharnos los errores y silenciar los aciertos. Que alguno debe haber, \u00bfno?<br \/>CIUDADANO: \u00bfVes como tienes la conciencia pervertida de que hay que agradecerte tu trabajo? Porque entiendes que lo que haces se debe a tu generosidad; te consideras un benefactor de la comunidad. Y no te quieres enterar de que no eres m\u00e1s que un trabajador al servicio de la gente; a mi servicio; yo soy tu jefe y tengo que exigirte, como me exige a m\u00ed el m\u00edo y el de cualquier trabajador.<br \/>POL\u00cdTICO: Yo solo tengo que responder ante mi partido, que es el que tiene que pedirme cuentas de mi gesti\u00f3n.<br \/>CIUDADANO: Tu gesti\u00f3n tiene que estar basada en la justicia, en la racionalidad y en el sentido com\u00fan y no en la arbitrariedad, en el sinsentido y el capricho, precisamente porque solo te consideras con la obligaci\u00f3n de responder ante tus socios. Y en cuanto a los beneficios que te reportan tus\u2026<br \/>POL\u00cdTICO: Mi salario es justo. T\u00fa bien sabes lo que tengo que soportar como responsable p\u00fablico. Entre otras cosas, el veneno que destilan tus permanentes frustraciones.<br \/>CIUDADANO: No puedo entender tu salario. Tal vez, tu salario s\u00ed, pero no tu inmensa desverg\u00fcenza para completarlo con todo tipo de regalos, comisiones, dietas, sobres subterr\u00e1neos y dem\u00e1s desahogos.<br \/>POL\u00cdTICO: La vida de un pol\u00edtico es como la de un deportista de \u00e9lite; corta. Por eso hay que aprovechar todas las oportunidades.<br \/>CIUDADANO: Y esa ansiedad es la que os lleva al abandono del inter\u00e9s com\u00fan y os echa en brazos de la irresponsabilidad. Y lo malo es que tu irresponsabilidad se traduce en cosas concretas para m\u00ed. Cuando t\u00fa permites que el poder financiero y los bancos campen por sus respetos, est\u00e1s creando las condiciones para que mi sueldo se reduzca, para que no pueda acceder a una prejubilaci\u00f3n o a una jubilaci\u00f3n digna, para que los derechos conseguidos a golpe de un doloroso esfuerzo se vayan al carajo, para que me vaya al paro, o me echen de mi piso o pierda\u2026<br \/>POL\u00cdTICO: Es imposible que yo pueda ser responsable de tanto desaguisado, de tanto desm\u00e1n. Algo habr\u00e1s puesto t\u00fa, cuando eludes en cuanto puedes tus obligaciones fiscales, cuando escoges la factura sin IVA, cuando\u2026<br \/>CIUDADANO: Alto ah\u00ed. No compares. Mis peque\u00f1as indecencias, de las que soy consciente, son reactivas. No son m\u00e1s que una manera de responder, de protestar, ante la podredumbre que t\u00fa y los que se dedican a lo que t\u00fa te dedicas, vais sembrando por donde pas\u00e1is. \u00a1Menudo ejemplo!<br \/>POL\u00cdTICO: Pero as\u00ed no se solucionan los problemas. \u00bfEsas son tus ejemplares respuestas?<br \/>CIUDADANO: Las que me provocan tu falta de decencia, la deserci\u00f3n de tu verdadera responsabilidad, tu falta de conciencia social, tu indiferencia ante el sufrimiento de la gente.<br \/>POL\u00cdTICO: No olvides que tengo unas ideas, unos principios\u2026<br \/>CIUDADANO: No me hables de principios, por favor. La \u00faltima raz\u00f3n que t\u00fa tuviste para escoger este partido fue la coincidencia ideol\u00f3gica. T\u00fa tienes los principios que necesitas tener en cada momento. T\u00fa cambias de discurso cuando te conviene. Te vendes y te dejas comprar. Tus ideas son de usar y tirar, en funci\u00f3n de las circunstancias. \u00bfC\u00f3mo co\u00f1o me hablas de principios?<br \/>POL\u00cdTICO: Quiero decir que no solo t\u00fa tienes derecho a estar descontento con la realidad. A m\u00ed tambi\u00e9n me afecta y no puedo controlar la mayor\u00eda de la realidad, que es esquiva y tornadiza.<br \/>CIUDADANO: Pero t\u00fa tienes acceso a los instrumentos que manejan la informaci\u00f3n y manipulan las conciencias. T\u00fa puedes, y de hecho lo haces, conseguir que la gente asuma como verdades lo que no son m\u00e1s que mentiras miserables. T\u00fa puedes maniobrar para cargarte una buena reputaci\u00f3n o para ensalzar a un impresentable. Tienes los hilos para manejar todo eso. Yo no.<br \/>POL\u00cdTICO: Te sobra rencor acumulado contra m\u00ed y te falta generosidad para entender mi papel. Te sobra resentimiento y te falta autocr\u00edtica.<br \/>CIUDADANO: Y a ti te sobra soberbia para abusar de la gente y te falta humildad para entender sus problemas; te sobra desveng\u00fcenza para cagarte en los ideales y te falta honestidad para manejar con decencia el dinero de todos.<br \/>POL\u00cdTICO: Yo intento hacer una pol\u00edtica justa\u2026<br \/>CIUDADANO: No puede ser justo quien es fuerte con los d\u00e9biles y d\u00e9bil con los fuertes. Porque t\u00fa no crees en nada\u2026 en nada m\u00e1s que en servirte de tu posici\u00f3n\u2026<br \/>POL\u00cdTICO: Yo tengo que remitirte a nuestro programa\u2026<br \/>CIUDADANO: Mira, no me toques los cojones con el programa. Ya sali\u00f3 la palabra maldita. Vuestro programa no es una relaci\u00f3n de prop\u00f3sitos, sino una sarta de mentiras para embaucar a los votantes. No es un cat\u00e1logo de soluciones para abordar problemas, sino un inventario de recetas para robar votos inocentes.<br \/>POL\u00cdTICO: Lo que ocurre es que hay veces en que la realidad no permite cumplir todas las promesas y hay que hacer pol\u00edticas de recuperaci\u00f3n, hay que abordar dolorosos recortes, que vienen obligados por las circunstancias, por la nefasta pol\u00edtica anterior y por el sentido de la responsabilidad.<br \/>CIUDADANO: T\u00fa est\u00e1s, vosotros est\u00e1is para modificar la realidad, no para usarla de coartada para aplicar el verdadero programa, que no te atreves, el que no os atrev\u00e9is a explicar con claridad. Adem\u00e1s, recortar es de pol\u00edticos malos, incompetentes, incapaces. Si vuestra gesti\u00f3n fuera adecuada, si fuerais capaces de sanear de verdad el sistema, de hacer una terapia apropiada, no tendr\u00edas que acudir a recortar nada. Pero, claro, que t\u00e9 importa a ti el pueblo, qu\u00e9 le importa a los de tu clase la gente. F\u00edjate qu\u00e9 paradoja m\u00e1s cruel: los pol\u00edticos est\u00e1is mucho m\u00e1s cerca de los miembros de la oposici\u00f3n que de los ciudadanos.<br \/>POL\u00cdTICO: Bien, reconozco que toda esta ret\u00f3rica que utilizas contra m\u00ed es suficientemente demoledora como para que d\u00e9 por terminada aqu\u00ed la discusi\u00f3n. Pero tengo algo que decirte. Ni yo ni ning\u00fan otro pol\u00edtico hemos sido engendrados en un tubo de ensayo. Somos todos hijos de la misma sociedad, del mismo pueblo que t\u00fa dices defender y del que t\u00fa tan orgulloso te sientes. Somos tambi\u00e9n hijos de ese pueblo que elude obligaciones fiscales, que hace trampas en las facturas, que practica el absentismo laboral, que exige sin dar, que miente y enga\u00f1a y que se deja comprar. Y es que t\u00fa, t\u00fa tambi\u00e9n eres uno de nosotros. T\u00fa eres como yo. Es verdad que yo, que tendr\u00eda que servirte, te uso para mi servicio. Pero eso es exactamente lo que t\u00fa har\u00edas tambi\u00e9n si estuvieras en mi lugar.<\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfCRISIS? \u00bfQU\u00c9 CRISIS? Bajar en pdf Comprar en papel PRESENTACI\u00d3N Obra teatral en 12 cuadros, original de Jos\u00e9 Mar\u00eda Tornay Crisis. \u00bfQu\u00e9 crisis? es el t\u00edtulo de un \u00e1lbum legendario del no menos legendario grupo SUPERTRAMP. Siempre me result\u00f3 atractivo dicho t\u00edtulo y, ahora, me parece que viene a cuento de manera especial, para definir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":17,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_aioseop_title":"","_aioseop_description":"","ngg_post_thumbnail":0,"footnotes":""},"_links":{"self":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/pages\/5368"}],"collection":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/comments?post=5368"}],"version-history":[{"count":0,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/pages\/5368\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/media?parent=5368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}