{"id":9250,"date":"2016-12-11T14:46:38","date_gmt":"2016-12-11T13:46:38","guid":{"rendered":"http:\/\/www.josemariatornay.com\/?p=9250"},"modified":"2016-12-11T14:51:42","modified_gmt":"2016-12-11T13:51:42","slug":"9250","status":"publish","type":"post","link":"http:\/\/www.josemariatornay.com\/index.php\/2016\/12\/11\/9250\/","title":{"rendered":"El balc\u00f3n y la niebla"},"content":{"rendered":"<p style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-9245 size-full\" src=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/12\/aymironda01.jpg\" alt=\"aymironda01\" width=\"800\" height=\"600\" srcset=\"http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/12\/aymironda01.jpg 800w, http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/12\/aymironda01-300x225.jpg 300w, http:\/\/www.josemariatornay.com\/wp-content\/uploads\/2016\/12\/aymironda01-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><br \/>\nColgada de un barranco<br \/>\nmi Ronda, entre la niebla,<br \/>\nuna diosa parece<br \/>\ndescendida a la Tierra,<br \/>\nEsa Ronda que vuela,<br \/>\nesa Ronda tan quieta,<br \/>\ndetenida en el tiempo,<br \/>\neternamente eterna.<br \/>\nRotundamente roca,<br \/>\nresueltamente piedra.<br \/>\n\u00a1Ay, mi Ronda, tan alta<br \/>\ncomo el Sol que te besa,<br \/>\ntan noble y orgullosa<br \/>\ncomo una luna llena.<br \/>\nRonda dentro de mi alma,<br \/>\ntan joven y tan vieja.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Colgada de un barranco mi Ronda, entre la niebla, una diosa parece descendida a la Tierra, Esa Ronda que vuela, esa Ronda tan quieta, detenida en el tiempo, eternamente eterna. Rotundamente roca, resueltamente piedra. \u00a1Ay, mi Ronda, tan alta como el Sol que te besa, tan noble y orgullosa como una luna llena. Ronda dentro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_aioseop_title":"","_aioseop_description":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/posts\/9250"}],"collection":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/comments?post=9250"}],"version-history":[{"count":0,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/posts\/9250\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/media?parent=9250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/categories?post=9250"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.josemariatornay.com\/index.php\/wp-json\/wp\/v2\/tags?post=9250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}